{"id":12415,"date":"2020-09-17T09:14:31","date_gmt":"2020-09-17T07:14:31","guid":{"rendered":"http:\/\/campusvygon.com\/cl\/?p=12415"},"modified":"2021-09-03T17:34:24","modified_gmt":"2021-09-03T15:34:24","slug":"seguridad-ucin-evitar-error","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/","title":{"rendered":"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error"},"content":{"rendered":"\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"http:\/\/campusvygon.com\/cl\/project\/whitepaper-cultura-de-la-seguridad-en-las-ucin\/\">Descarga en PDF<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque siempre ha existido (y existe) la preocupaci\u00f3n por mejorar la seguridad del paciente en el entorno sanitario, el informe <strong><em>\u201cTo&nbsp;err&nbsp;is&nbsp;Human:&nbsp;Building&nbsp;a&nbsp;safer&nbsp;health&nbsp;system\u201d, <\/em><\/strong>publicado en<em>&nbsp;<\/em>1999 por el&nbsp;Committee&nbsp;on&nbsp;Quality&nbsp;of&nbsp;Health&nbsp;Care&nbsp;in American del&nbsp;Institute&nbsp;of&nbsp;Medicine, pone en evidencia un grave problema de la&nbsp;estructura sanitaria:<strong> la escasa&nbsp;preocupaci\u00f3n por&nbsp;una cultura de la seguridad para el paciente<sup>1,2<\/sup>.&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio recog\u00eda que los errores en la asistencia de los servicios sanitarios americanos habr\u00edan causado la muerte de entre 48 y 98 mil pacientes.&nbsp; Lo que se traduc\u00eda en un aumento de 8,8 millones de d\u00f3lares, en t\u00e9rminos de&nbsp;morbi-mortalidad y aumento de las estancias hospitalarias<sup>2<\/sup>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Hacia la cultura de seguridad<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La necesidad de implantar herramientas y estrategias para mejorar la seguridad del paciente en general, y crear una cultura de seguridad empieza a tomar tal importancia que en 2004 la Organizaci\u00f3n Mundial de la Salud pone en marcha la \u201cAlianza Mundial para la Seguridad del Paciente\u201d anunciando un conjunto de pautas para reducir el n\u00famero de complicaciones que sufren los pacientes durante la actuaci\u00f3n m\u00e9dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, comienzan a surgir, en los pa\u00edses con los mejores y m\u00e1s fuertes sistemas sanitarios., comit\u00e9s de seguridad y sociedades cient\u00edficas dedicadas a la seguridad en los pacientes<sup>1<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Espa\u00f1a, El Ministerio de sanidad desarroll\u00f3 un plan estrat\u00e9gico para la seguridad del paciente que incluye como metas<sup>3<\/sup>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Promover y desarrollar el conocimiento y cultura de seguridad del paciente entre los profesionales sanitarios en cualquier nivel de atenci\u00f3n sanitaria<\/li><li>Dise\u00f1ar y establecer sistemas de comunicaci\u00f3n de incidencias relacionadas con la seguridad en el paciente<\/li><li>Promover la implementaci\u00f3n de pr\u00e1cticas seguras en los centros sanitarios del Sistema Nacional de Salud (SNS)<\/li><li>Facilitar la participaci\u00f3n de pacientes y ciudadanos<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad.png\" rel=\"attachment wp-att-12427\"><img loading=\"lazy\" decoding=\"async\" width=\"4627\" height=\"3147\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad.png\" alt=\"7 estrategias cultura seguridad\" class=\"wp-image-12427\" srcset=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad.png 4627w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad-300x204.png 300w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad-1024x696.png 1024w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad-768x522.png 768w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad-1536x1045.png 1536w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad-2048x1393.png 2048w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad-1080x735.png 1080w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/7-estrategias-cultura-seguridad-335x228.png 335w\" sizes=\"(max-width: 4627px) 100vw, 4627px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, su implementaci\u00f3n a\u00fan <strong>est\u00e1 poco desarrolla de algunos \u00e1mbitos sanitarios como la neonatolog\u00eda<\/strong><sup>2<\/sup>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Seguridad del paciente neonatal<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La cultura de la seguridad se convierte en un tema m\u00e1s delicado y complejo cuando se analiza cuidados altamente especializados como en las unidades de cuidados intensivos neonatales<sup>4<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los reci\u00e9n nacidos son los pacientes m\u00e1s indefensos asistidos en todo hospital, sobre todo los de muy bajo peso al nacer ingresados en las UCIN. Estos pacientes son vulnerables debido a su desarrollo org\u00e1nico, funcional e inmunol\u00f3gico inmaduro. Los neonatos hospitalizados son, generalmente, inestables tiene una dependencia absoluta del personal asistencial y no poseen la capacidad de alertar a sus cuidadores de que algo va mal<sup>3,4<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La UCIN son uno de los servicios m\u00e1s expuestos a la comisi\u00f3n de errores en el tratamiento. <\/strong>Esto se debe al complejo sistema de procesos tecnol\u00f3gicos y a las m\u00faltiples intervenciones humanas, que, si bien tienen acciones positivas en su supervivencia, tambi\u00e9n aumentan los riesgos de cometer practicas inseguras para la ocurrencia de eventos adversos<sup>4,6<\/sup>. <strong>Se calcula que un prematuro puede llegar a ser \u201ctocado\u201d unas 200 veces en 24 horas<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tasa de errores no var\u00eda significativamente entre la asistencia de pacientes adultos y la observado en ni\u00f1os, empero las consecuencias de estos fallos son peores en los reci\u00e9n nacidos. Existen estudios que demuestran que <strong>los neonatos tienen un mayor \u00edndice de mortalidad debido a errores<\/strong><sup>1<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunas investigaciones apuntan a que las tasas de <strong>errores derivados de la asistencia<\/strong> sanitaria en este grupo de pacientes se encuentran <strong>alrededor del 10-15% de los ingresos<\/strong><sup>2<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los incidentes m\u00e1s comunes en la atenci\u00f3n neonatal est\u00e1n provocados por el manejo incorrecto de medicamentos, la aparici\u00f3n de infecciones provocadas por la asistencia sanitaria o, bien, se derivan de intervenciones asistenciales. A continuaci\u00f3n, describimos detalladamente los errores m\u00e1s comunes y c\u00f3mo manejarlos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Incidencias comunes en las UCIN<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Errores en la medicaci\u00f3n <\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Son los errores m\u00e1s frecuentes descritos en las UCIN<\/strong>. Se supone que los errores de medicaci\u00f3n son 8 veces m\u00e1s habituales en este servicio que en las unidades de adultos hospitalizados<sup>6<\/sup>. Los reci\u00e9n nacidos, especialmente los prematuros muy peque\u00f1os, durante sus primeros d\u00edas, recibe una gran cantidad de medicamentos, de forma simult\u00e1nea, en sus primeros d\u00edas de vida<sup>1<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la etapa neonatal los protocolos de administraci\u00f3n de f\u00e1rmacos difieren de otras edades. El reci\u00e9n nacido presenta especialidades farmac\u00e9uticas adecuadas a sus necesidades y a diferencias fisiol\u00f3gicas por ser una un grupo no homog\u00e9neo y cambiante que requiere de pautas variables en funci\u00f3n de su peso, edad gestacional y d\u00edas de vida<sup>5<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El error m\u00e1s habitual se da en la prescripci\u00f3n del f\u00e1rmaco.<\/strong> Supone el 70% de todos los errores de medicaci\u00f3n. Si estos errores no son identificados antes de infundir el medicamento al paciente pueden tener consecuencias graves o incluso provocar su muerte.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-style-default is-layout-flow wp-block-quote-is-layout-flow\"><p>Recuerda: <strong>Es importante prestar atenci\u00f3n en la prescripci\u00f3n de f\u00e1rmacos potencialmente peligrosos y con efectos adversos graves. La insulina, adrenalina, indometacina y heparina por v\u00eda intravenosa son los medicamentos de son frecuente en neonatos m\u00e1s peligrosos. Un error en la dosis puede provocar la muerte del paciente.<\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los problemas m\u00e1s habituales en la prescripci\u00f3n es el c\u00e1lculo de la dosis, sobre todo cuando se indican f\u00e1rmacos en dosis inferiores a 1mg\/kg. <strong>La <\/strong><a href=\"http:\/\/campusvygon.com\/cl\/enfit-incompatible-seguridad-neonatal-2\/\"><strong>precisi\u00f3n de la dosis<\/strong><\/a><strong> a administrar es fundamental ya que puede comprometer gravemente la salud del paciente.<\/strong> La elecci\u00f3n de la v\u00eda, la frecuencia en la administraci\u00f3n e incluso el desconocimiento por parte del profesional sanitario de la droga a infundir aumenta la inseguridad en la asistencia de los pacientes<sup>1<\/sup>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg.png\" rel=\"attachment wp-att-12459\"><img loading=\"lazy\" decoding=\"async\" width=\"4961\" height=\"3508\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg.png\" alt=\"Medida de prescripci\u00f3n.jpg\" class=\"wp-image-12459\" srcset=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg.png 4961w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg-300x212.png 300w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg-1024x724.png 1024w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg-768x543.png 768w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg-1536x1086.png 1536w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg-2048x1448.png 2048w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg-400x284.png 400w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg-1080x764.png 1080w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medida-de-prescripcion.jpg-335x237.png 335w\" sizes=\"(max-width: 4961px) 100vw, 4961px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La <a href=\"http:\/\/campusvygon.com\/cl\/infusion-neonatos\/\">administraci\u00f3n es otro de los momentos claves en la vigilancia de la seguridad del reci\u00e9n nacido<\/a>. Una vez superado los errores de conexi\u00f3n entre sistemas de administraci\u00f3n no relacionados con la aplicaci\u00f3n de la <a href=\"http:\/\/campusvygon.com\/cl\/enfit-no-seguro-neonatos\/\">norma ISO 80369<\/a> queda por resolver el trabajo que, en ocasiones, enfermer\u00eda debe realizar en cuanto a la preparaci\u00f3n y fraccionamiento de los f\u00e1rmacos por &nbsp;la inexistencias de presentaciones farmac\u00e9uticas para neonatos<sup>1,2<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las \u00fanicas medicaciones que se suelen preparar en los servicios de farmacia de los hospitales para las UCINs, son las soluciones de nutrici\u00f3n parenteral, por su complejidad, y ciertas preparaciones orales. Este vac\u00edo farmac\u00e9utico, obliga al uso de medicamentos fuera de indicaci\u00f3n en reci\u00e9n nacidos<sup>2<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es habitual, tambi\u00e9n, observar errores por la confusi\u00f3n de medicamentos que se comercializan con nombres parecidos o presentaciones similares, pero que tienen funciones diferentes o se administran a trav\u00e9s de v\u00edas distintas. Es esencial guardar de forma correcta los viales, para evitar la equivocaci\u00f3n o mezcla de medicamentos potencialmente peligrosos con los de uso com\u00fan<sup>1<\/sup>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion.png\" rel=\"attachment wp-att-12424\"><img loading=\"lazy\" decoding=\"async\" width=\"4961\" height=\"3508\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion.png\" alt=\"Medidas administraci\u00f3n\" class=\"wp-image-12424\" srcset=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion.png 4961w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion-300x212.png 300w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion-1024x724.png 1024w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion-768x543.png 768w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion-1536x1086.png 1536w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion-2048x1448.png 2048w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion-400x284.png 400w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion-1080x764.png 1080w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-administracion-335x237.png 335w\" sizes=\"(max-width: 4961px) 100vw, 4961px\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Errores en los procedimientos<sup>1<\/sup><\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">En la UCIN se llevan a cabo, de forma rutinaria, un gran n\u00famero \u00ad\u00adde procedimientos. Pero, a pesar de su cotidianidad, generan un riesgo evidente en la seguridad del paciente. Uno de los procedimientos m\u00e1s habituales en los que se anotan errores en la pr\u00e1ctica es la intubaci\u00f3n endotraqueal por la mala ubicaci\u00f3n&nbsp; del tubo. Es por ese motivo, por el que, siempre que es posible, las UCIN emplean el uso de <a href=\"http:\/\/campusvygon.com\/cl\/insure-lisa\/\">t\u00e9cnicas menos invasivas<\/a> que eviten sufrimiento y complicaciones en el neonato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, es com\u00fan, que diferentes procedimientos se vean entorpecidos por la falta de formaci\u00f3n. La tasa de errores aumenta cuando se produce cambios en la rotaci\u00f3n de residentes y becarios, increment\u00e1ndose el n\u00famero de infecciones nosocomiales y otras deficiencias en procedimientos invasivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuanto m\u00e1s complejo es el procedimiento, m\u00e1s escasa la formaci\u00f3n, no se cuentan con las gu\u00edas y el material adecuado para llevarlo a cabo o existe escasez de personal de enfermer\u00eda, m\u00e1s dif\u00edcil resulta llevar a cabo el tratamiento con seguridad.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1.png\" rel=\"attachment wp-att-12423\"><img loading=\"lazy\" decoding=\"async\" width=\"4961\" height=\"3508\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1.png\" alt=\"Errores en procedimientos\" class=\"wp-image-12423\" srcset=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1.png 4961w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1-300x212.png 300w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1-1024x724.png 1024w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1-768x543.png 768w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1-1536x1086.png 1536w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1-2048x1448.png 2048w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1-400x284.png 400w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1-1080x764.png 1080w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-1-335x237.png 335w\" sizes=\"(max-width: 4961px) 100vw, 4961px\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Errores relacionados con las infecciones nosocomiales<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Las <strong>infecciones nosocomiales son uno de los problemas m\u00e1s graves adquiridos en los centros hospitalarios<\/strong> que se dan a nivel global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un estudio sobre infecciones nosocomiales en el \u00e1mbito hospitalario realizado en el \u00e1rea neonatal, Guti\u00e9rrez <em>et al<\/em> identificaron que los factores m\u00e1s habituales de la sepsis en reci\u00e9n nacidos eran la ruptura temprana de membrana, el tipo de nacimiento, las infecciones urinarias y vaginales de la madre, la <a href=\"http:\/\/campusvygon.com\/cl\/asepsia-infeccion-brc-neonatos\/\">multi invasi\u00f3n con cat\u00e9teres centrales y arteriales<\/a> y <a href=\"http:\/\/campusvygon.com\/cl\/neonatos-picc-doble-luz\/\">la multipunci\u00f3n<\/a><sup>6<\/sup>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Puede interesarte&#8230;<\/p><cite><a href=\"http:\/\/campusvygon.com\/cl\/iras-neonatos-prevencion\/\"><strong><em>\u201c\u00bfC\u00f3mo manejar las IRAS en neonatos?: Herramientas de prevenci\u00f3n y medidas para reducir su impacto\u201d<\/em> <\/strong><\/a><strong><em>en este art\u00edculo podr\u00e1s encontrar informaci\u00f3n m\u00e1s detallada sobre este tipo de complicaciones.<\/em><\/strong><\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Las infecciones nosocomiales representan una de las principales preocupaciones en los profesionales sanitarios ya que la prevenci\u00f3n y la reducci\u00f3n de estas infecciones podr\u00edan reducirse con estrategias simples como el lavado de manos. Sin embargo, para su completa prevenci\u00f3n y control se requiere del apoyo institucional mediante la promoci\u00f3n programas, gu\u00edas, formaci\u00f3n, estrategias y seguimiento y seguimiento de estas <sup>1<\/sup>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion.png\" rel=\"attachment wp-att-12422\"><img loading=\"lazy\" decoding=\"async\" width=\"4961\" height=\"3508\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion.png\" alt=\"Medidas de preveci\u00f3n de la infecci\u00f3n\" class=\"wp-image-12422\" srcset=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion.png 4961w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion-300x212.png 300w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion-1024x724.png 1024w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion-768x543.png 768w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion-1536x1086.png 1536w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion-2048x1448.png 2048w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion-400x284.png 400w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion-1080x764.png 1080w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Medidas-de-prevecion-de-la-infeccion-335x237.png 335w\" sizes=\"(max-width: 4961px) 100vw, 4961px\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Errores en la identificaci\u00f3n del paciente<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La equivocada identificaci\u00f3n del paciente contin\u00faa siendo un motivo de error y evento adverso en la pr\u00e1ctica asistencias hospitalaria. Esta se asocia con la ocurrencia de m\u00faltiples tipolog\u00edas de errores como los de medicaci\u00f3n transfusi\u00f3n, realizaci\u00f3n de procedimientos invasivos, cirug\u00edas\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las unidades de cuidados intensivos neonatales la incorrecta identificaci\u00f3n del paciente suele producirse con menos frecuencia que en otras \u00e1reas ya que es una pr\u00e1ctica obligatoria que se realiza inmediatamente despu\u00e9s del nacimiento del reci\u00e9n nacido<sup>1<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, algunas investigaciones demuestran que las UCIN no est\u00e1n exentas de este tipo de errores. Garc\u00eda <em>et al<\/em> encontraron factores en los servicios de neonatolog\u00eda que dificultan una buena identificaci\u00f3n del neonato: errores en la letra, falta de congruencia en los datos, o disonancias entre la tarjeta y la pulsera de identificaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos.png\" rel=\"attachment wp-att-12421\"><img loading=\"lazy\" decoding=\"async\" width=\"4961\" height=\"3224\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756.png\" alt=\"Errores de comunicaci\u00f3n\" class=\"wp-image-12421\" srcset=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756.png 4961w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756-300x195.png 300w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756-1024x665.png 1024w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756-768x499.png 768w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756-1536x998.png 1536w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756-2048x1331.png 2048w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756-1080x702.png 1080w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Errores-en-procedimientos-e1600263812756-335x218.png 335w\" sizes=\"(max-width: 4961px) 100vw, 4961px\" \/><\/a><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Errores en la comunicaci\u00f3n del equipo<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Las barreras en la comunicaci\u00f3n en las instituciones m\u00e9dicas suponen un desaf\u00eda para la seguridad de los pacientes en la asistencia ya que est\u00e1 estrechamente ligada a la ocurrencia de errores<sup>1<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una disciplina compleja, como la medicina, la comunicaci\u00f3n es un factor clave para la consecuci\u00f3n de una alta calidad en el trabajo. Esta debe ser completa, oportuna, precisa y comprendida entre aquellos que establecen una relaci\u00f3n dirigida a las prescripciones que se aplicar\u00e1n al neonato<sup>1,6<\/sup>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-scaled.jpg\" rel=\"attachment wp-att-12418\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1828\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-scaled.jpg\" alt=\"20 recomendaciones: seguridad en la UCIN\" class=\"wp-image-12418\" srcset=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-scaled.jpg 2560w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-300x214.jpg 300w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-1024x731.jpg 1024w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-768x548.jpg 768w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-1536x1097.jpg 1536w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-2048x1462.jpg 2048w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-1080x771.jpg 1080w, https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Conclusiones-finales-comprimido-335x239.jpg 335w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Existen, pues, diferentes obst\u00e1culos para implantar la nueva cultura de seguridad para el paciente de forma definitiva en las actividades m\u00e9dicas. Queda un camino largo por recorrer para la creaci\u00f3n de un espacio sanitario en el que los errores sean vistos como una oportunidad de aprendizaje y se establezcan sistemas de evaluaci\u00f3n fiables que permitan una evaluaci\u00f3n continua de los datos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, son cada vez m\u00e1s los profesionales e instituciones dispuestos a establecer cambios en las rutinas profesionales para ofrecer una asistencia sanitaria de calidad y libre de equivocaciones.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Bibliograf\u00eda<\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li>Organizaci\u00f3n Panamericana de la Salud. Centro Latinoamericano de Perinatolog\u00eda, Salud de la Mujer y Reproductiva. <em>Abordaje y la prevenci\u00f3n de errores que ocurren en el cuidado de los reci\u00e9n nacidos<\/em>. Washington, D.C.: OPS; 2018 (Publicaci\u00f3n Cientifica CLAP 1606). Disponible en: <a href=\"https:\/\/iris.paho.org\/bitstream\/handle\/10665.2\/49097\/9789275320068-spa.pdf?sequence=5&amp;isAllowed=y\">https:\/\/iris.paho.org\/bitstream\/handle\/10665.2\/49097\/9789275320068-spa.pdf?sequence=5&amp;isAllowed=y<\/a><\/li><li>Ministerio de Sanidad, Servicios Sociales e Igualdad. (2015). <em>Estado de la Seguridad del Paciente Neonatal<\/em> [PDF] (pp. 15-42). Disponible en: <a href=\"https:\/\/www.seguridaddelpaciente.es\/resources\/documentos\/2015\/neonatologia.pdf\">https:\/\/www.seguridaddelpaciente.es\/resources\/documentos\/2015\/neonatologia.pdf<\/a><\/li><li>Soria, E. (2012). <em>Cultura de la Seguridad del paciente en una Unidad de Cuidados Intensivos Neonatales (UCIN)<\/em> [PDF] (pp. 13-35). C\u00f3rdoba. Disponible en: <a href=\"http:\/\/lildbi.fcm.unc.edu.ar\/lildbi\/tesis\/soria_etelvina_del_milagro.pdf\">http:\/\/lildbi.fcm.unc.edu.ar\/lildbi\/tesis\/soria_etelvina_del_milagro.pdf<\/a><\/li><li>Viecili, L. (2019). Aprendiendo con los errores: an\u00e1lisis de los incidentes en una unidad de cuidados neonatales. Revisado 4 Septiembre 2020, de <a href=\"https:\/\/www.scielo.br\/scielo.php?script=sci_arttext&amp;pid=S0104-11692019000100314&amp;lng=en&amp;nrm=iso&amp;tlng=es\">https:\/\/www.scielo.br\/scielo.php?script=sci_arttext&amp;pid=S0104-11692019000100314&amp;lng=en&amp;nrm=iso&amp;tlng=es<\/a><\/li><li>T. Esqu\u00e9 Ruiz, M.G. Moretones Su\u00f1ol, J.M. Rodr\u00edguez Migu\u00e9lez, E. S\u00e1nchez Ortiz, M. Izco Urroz, M. de Lamo Camino, J. Figueras Aloy. <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S2341287916000235\"><em>Medication errors in a neonatal unit: One of the main adverse events<\/em><\/a><em>. <\/em>Anales de Pediatr\u00eda (English Edition), Volumen 84, Issue 4, Abril 2016, P\u00e1g. 211-217 <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S1695403315003707\">https:\/\/www.sciencedirect.com\/science\/article\/pii\/S1695403315003707<\/a><\/li><li>S\u00e1nchez, L. (2012). <em>Seguridad del neonato hospitalizado. Aproximaciones y propuestas<\/em> (9th ed.). <a href=\"http:\/\/www.scielo.org.mx\/scielo.php?script=sci_arttext&amp;pid=S1665-70632012000200004\">http:\/\/www.scielo.org.mx\/scielo.php?script=sci_arttext&amp;pid=S1665-70632012000200004<\/a><\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Aunque siempre ha existido (y existe) la preocupaci\u00f3n por mejorar la seguridad del paciente en el entorno sanitario, el informe \u201cTo&nbsp;err&nbsp;is&nbsp;Human:&nbsp;Building&nbsp;a&nbsp;safer&nbsp;health&nbsp;system\u201d, publicado en&nbsp;1999 por el&nbsp;Committee&nbsp;on&nbsp;Quality&nbsp;of&nbsp;Health&nbsp;Care&nbsp;in American del&nbsp;Institute&nbsp;of&nbsp;Medicine, pone en evidencia un grave problema de la&nbsp;estructura sanitaria: la escasa&nbsp;preocupaci\u00f3n por&nbsp;una cultura de la seguridad para el paciente1,2.&nbsp;&nbsp; El estudio recog\u00eda que los errores en la asistencia [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":12432,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[286,118],"tags":[431,429,433,432,434,120,430],"class_list":["post-12415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neonatologia","category-neonatologia-y-nutricion-enteral","tag-cultura-de-la-seguridad","tag-errores","tag-errores-de-comunicacion","tag-errores-de-medicacion","tag-errores-por-iras","tag-seguridad","tag-ucin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error<\/title>\n<meta name=\"description\" content=\"Conoce las estrategias para prevenir estos errores y convertir las UCIN en servicios m\u00e1s seguros con el cambio hacia una cultura de seguridad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error\" \/>\n<meta property=\"og:description\" content=\"Conoce las estrategias para prevenir estos errores y convertir las UCIN en servicios m\u00e1s seguros con el cambio hacia una cultura de seguridad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Chile\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-17T07:14:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-03T15:34:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Sin-titulo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Karine Fric\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karine Fric\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/\"},\"author\":{\"name\":\"Karine Fric\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/d0c0d6e48a7c32c1b48c28e70eb783d0\"},\"headline\":\"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error\",\"datePublished\":\"2020-09-17T07:14:31+00:00\",\"dateModified\":\"2021-09-03T15:34:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/\"},\"wordCount\":2154,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Sin-titulo-1.png\",\"keywords\":[\"cultura de la seguridad\",\"errores\",\"errores de comunicaci\u00f3n\",\"errores de medicaci\u00f3n\",\"errores por IRAS\",\"seguridad\",\"UCIN\"],\"articleSection\":[\"Neonatolog\u00eda\",\"Obstetricia, Neonatolog\u00eda y Nutrici\u00f3n Enteral\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/\",\"name\":\"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Sin-titulo-1.png\",\"datePublished\":\"2020-09-17T07:14:31+00:00\",\"dateModified\":\"2021-09-03T15:34:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/d0c0d6e48a7c32c1b48c28e70eb783d0\"},\"description\":\"Conoce las estrategias para prevenir estos errores y convertir las UCIN en servicios m\u00e1s seguros con el cambio hacia una cultura de seguridad\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Sin-titulo-1.png\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Sin-titulo-1.png\",\"width\":1024,\"height\":512,\"caption\":\"Seguridad en UCIN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/seguridad-ucin-evitar-error\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/\",\"name\":\"Campus Vygon Chile\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/d0c0d6e48a7c32c1b48c28e70eb783d0\",\"name\":\"Karine Fric\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09ecbec787eab7d7afeec9f3413d48e4de2ca55710b77c7c5b6a567bc59b28f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09ecbec787eab7d7afeec9f3413d48e4de2ca55710b77c7c5b6a567bc59b28f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09ecbec787eab7d7afeec9f3413d48e4de2ca55710b77c7c5b6a567bc59b28f2?s=96&d=mm&r=g\",\"caption\":\"Karine Fric\"},\"description\":\"Soy Delegada especialista en Anestesia-Emergencias en Catalu\u00f1a \u2022 EXPERIENCIA Mi pasi\u00f3n por la comunicaci\u00f3n, los acuerdos beneficiosos entre personas y el servicio al cliente me han llevado al sector de las ventas desde hace unos 20 a\u00f1os y m\u00e1s concretamente desde hace 11 a\u00f1os en el sector sanitario, donde he podido ampliar mi compromiso social desarrollando una relaci\u00f3n estrecha con el profesional sanitario para ayudarle en la tarea de mejorar la calidad de vida de los pacientes hospitalizados. \u2022 PUEDO AYUDARTE EN... Mi trabajo se basa en el compromiso claro de Vygon en proporcionar material quir\u00fargico de alta calidad a los profesionales de la salud, estar a su escucha para la resoluci\u00f3n de cualquier necesidad y acompa\u00f1arles en su aprendizaje continuo.\",\"sameAs\":[\"https:\\\/\\\/www.vygon.es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/karinefric\\\/\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/author\\\/kfric\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error","description":"Conoce las estrategias para prevenir estos errores y convertir las UCIN en servicios m\u00e1s seguros con el cambio hacia una cultura de seguridad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/","og_locale":"es_ES","og_type":"article","og_title":"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error","og_description":"Conoce las estrategias para prevenir estos errores y convertir las UCIN en servicios m\u00e1s seguros con el cambio hacia una cultura de seguridad","og_url":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/","og_site_name":"Campus Vygon Chile","article_published_time":"2020-09-17T07:14:31+00:00","article_modified_time":"2021-09-03T15:34:24+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Sin-titulo-1.png","type":"image\/png"}],"author":"Karine Fric","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Karine Fric","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/"},"author":{"name":"Karine Fric","@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/d0c0d6e48a7c32c1b48c28e70eb783d0"},"headline":"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error","datePublished":"2020-09-17T07:14:31+00:00","dateModified":"2021-09-03T15:34:24+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/"},"wordCount":2154,"commentCount":5,"image":{"@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Sin-titulo-1.png","keywords":["cultura de la seguridad","errores","errores de comunicaci\u00f3n","errores de medicaci\u00f3n","errores por IRAS","seguridad","UCIN"],"articleSection":["Neonatolog\u00eda","Obstetricia, Neonatolog\u00eda y Nutrici\u00f3n Enteral"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/","url":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/","name":"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error","isPartOf":{"@id":"https:\/\/campusvygon.com\/cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Sin-titulo-1.png","datePublished":"2020-09-17T07:14:31+00:00","dateModified":"2021-09-03T15:34:24+00:00","author":{"@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/d0c0d6e48a7c32c1b48c28e70eb783d0"},"description":"Conoce las estrategias para prevenir estos errores y convertir las UCIN en servicios m\u00e1s seguros con el cambio hacia una cultura de seguridad","breadcrumb":{"@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/#primaryimage","url":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Sin-titulo-1.png","contentUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/09\/Sin-titulo-1.png","width":1024,"height":512,"caption":"Seguridad en UCIN"},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/cl\/seguridad-ucin-evitar-error\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/cl\/"},{"@type":"ListItem","position":2,"name":"Cultura de seguridad en las UCIN: un esfuerzo colectivo para evitar el error"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/cl\/#website","url":"https:\/\/campusvygon.com\/cl\/","name":"Campus Vygon Chile","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/d0c0d6e48a7c32c1b48c28e70eb783d0","name":"Karine Fric","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/09ecbec787eab7d7afeec9f3413d48e4de2ca55710b77c7c5b6a567bc59b28f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09ecbec787eab7d7afeec9f3413d48e4de2ca55710b77c7c5b6a567bc59b28f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09ecbec787eab7d7afeec9f3413d48e4de2ca55710b77c7c5b6a567bc59b28f2?s=96&d=mm&r=g","caption":"Karine Fric"},"description":"Soy Delegada especialista en Anestesia-Emergencias en Catalu\u00f1a \u2022 EXPERIENCIA Mi pasi\u00f3n por la comunicaci\u00f3n, los acuerdos beneficiosos entre personas y el servicio al cliente me han llevado al sector de las ventas desde hace unos 20 a\u00f1os y m\u00e1s concretamente desde hace 11 a\u00f1os en el sector sanitario, donde he podido ampliar mi compromiso social desarrollando una relaci\u00f3n estrecha con el profesional sanitario para ayudarle en la tarea de mejorar la calidad de vida de los pacientes hospitalizados. \u2022 PUEDO AYUDARTE EN... Mi trabajo se basa en el compromiso claro de Vygon en proporcionar material quir\u00fargico de alta calidad a los profesionales de la salud, estar a su escucha para la resoluci\u00f3n de cualquier necesidad y acompa\u00f1arles en su aprendizaje continuo.","sameAs":["https:\/\/www.vygon.es\/","https:\/\/www.linkedin.com\/in\/karinefric\/"],"url":"https:\/\/campusvygon.com\/cl\/author\/kfric\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/12415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/comments?post=12415"}],"version-history":[{"count":16,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/12415\/revisions"}],"predecessor-version":[{"id":27649,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/12415\/revisions\/27649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/media\/12432"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/media?parent=12415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/categories?post=12415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/tags?post=12415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}