{"id":13854,"date":"2020-11-11T01:31:32","date_gmt":"2020-11-11T00:31:32","guid":{"rendered":"http:\/\/campusvygon.com\/cl\/?p=13854"},"modified":"2020-12-18T09:54:20","modified_gmt":"2020-12-18T08:54:20","slug":"vmni-pacientes-covid","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/","title":{"rendered":"Conferencia: qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid. Dr. Alonso"},"content":{"rendered":"<a href='#' class='small-button smallblue'>Ebook \u00abPr\u00e1cticas sanitarias durante la pandemia Covid-19 en Espa\u00f1a\u00bb<\/a>\n<p>El dr. Jos\u00e9 Miguel Alonso es un m\u00e9dico anestesi\u00f3logo espa\u00f1ol que trabaja en el hospital Polit\u00e9cnico y Universitario La Fe de Valencia. \u00c9l es uno de los principales expertos en VMNI en Espa\u00f1a y dirige el grupo VMNI-CR, que durante la pandemia ha servido como referente para muchos profesionales con poca formaci\u00f3n en el uso de las Terapias No Invasivas. En la conferencia que pod\u00e9is ver aqu\u00ed, nos explica por qu\u00e9 la VMNI, y en concreto, la CPAP de Boussignac es un aliado para salvar vidas en esta pandemia.<\/p>\n<p><iframe loading=\"lazy\" title=\"CPAP de Boussignac, una herramienta para hacer frente a la COVID en Per\u00fa\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/-Cetqz5u7OY?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>La conferencia, enfocada a ayudar a los profesionales sanitarios peruanos a aumentar sus opciones de tratamiento en una situaci\u00f3n sanitaria de escasez de ox\u00edgeno y de material como la que est\u00e1 viviendo el pa\u00eds andino, puede ser de utilidad para todos los profesionales que se est\u00e1n enfrentando al virus en su d\u00eda a d\u00eda, pues plantea opciones de tratamiento que garantizan la seguridad del profesional.<\/p>\n<h3>Ventajas de la VMNI en pacientes Covid<\/h3>\n<ul>\n<li>Forma parte de todas las <a href=\"http:\/\/campusvygon.com\/cl\/cpap-boussignac-ira-hipoxemica-covid\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>t\u00e9cnicas de soporte ventilatorio disponibles en la actualidad, ante las dificultades log\u00edsticas<\/strong><\/a> para disponer de respiradores y camas de cuidados intensivos en muchos centros hospitalarios.<\/li>\n<li>El material de <a href=\"http:\/\/campusvygon.com\/cl\/cpap-boussignac-sistema-versatil\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>uso \u00fanico<\/strong> <strong>reduce el riesgo de contaminaci\u00f3n<\/strong><\/a> entre pacientes tratados por el mismo profesional de salud.<\/li>\n<li><a href=\"http:\/\/campusvygon.com\/cl\/cpap-boussignac-sistema-versatil\/\" target=\"_blank\" rel=\"noopener noreferrer\">La CPAP de Boussignac ofrece <strong>versatilidad<\/strong><\/a> en cuanto a interfases, filtros, nebulizadores e incluso terapias, como <a href=\"http:\/\/campusvygon.com\/cl\/cpap-vs-alto-flujo-combinar\/\" target=\"_blank\" rel=\"noopener noreferrer\">el alto flujo<\/a>.<\/li>\n<li>El adecuado empleo de CPAP durante la TNI por personal adecuadamente entrenado, <a href=\"https:\/\/www.youtube.com\/watch?v=0H9OV7eUXQA&amp;ab_channel=VygonSpain\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>no aumenta la dispersi\u00f3n de las part\u00edculas infecciosas<\/strong><\/a> por lo que no deber\u00eda asociarse con un aumento de la transmisi\u00f3n a\u00e9rea de la enfermedad.<\/li>\n<li>Puede ser <a href=\"http:\/\/campusvygon.com\/cl\/ira-en-la-infeccion-por-covid-19-estrategias-de-tratamiento-y-perfil-del-paciente\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>una terapia de inicio en casos seleccionados<\/strong><\/a> tratados por expertos en TNI y en condiciones de seguridad.<\/li>\n<li>Puede ser una <a href=\"http:\/\/campusvygon.com\/cl\/ira-en-la-infeccion-por-covid-19-estrategias-de-tratamiento-y-perfil-del-paciente\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>terapia puente<\/strong><\/a> hasta el inicio de la VMI.<\/li>\n<li>Puede ser la <a href=\"http:\/\/campusvygon.com\/cl\/ira-en-la-infeccion-por-covid-19-estrategias-de-tratamiento-y-perfil-del-paciente\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>\u00fanica terapia cuando no se prevea disponibilidad de un respirador<\/strong> de VMI<\/a>.<\/li>\n<li>Puede utilizarse para el <strong><a href=\"http:\/\/campusvygon.com\/cl\/ira-en-la-infeccion-por-covid-19-estrategias-de-tratamiento-en-la-atencion-de-emergencias\/\" target=\"_blank\" rel=\"noopener noreferrer\">transporte sanitario de pacientes<\/a>.<\/strong><\/li>\n<li>Puede usarlo para el <a href=\"http:\/\/campusvygon.com\/cl\/ira-en-la-infeccion-por-covid-19-estrategias-de-tratamiento-en-la-atencion-de-emergencias\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>soporte ventilatorio extrahospitalario<\/strong><\/a> en centros de atenci\u00f3n primaria o puntos de atenci\u00f3n continuada hasta la llegada o traslado a un centro hospitalario<\/li>\n<li>Puede ser usado como <a href=\"http:\/\/campusvygon.com\/cl\/recomendaciones-manejo-paciente-anciano-sospecha-infeccion\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>terapia paliativa<\/strong><\/a> en casos seleccionados.<\/li>\n<li>Puede ser usado en la <strong>fase de \u201c<em>weaning<\/em>\u201d de la VMI<\/strong><\/li>\n<\/ul>\n<p>Repasa la conferencia del dr. Alonso y aprende c\u00f3mo utilizar la VMNI para garantizar tu seguridad, cu\u00e1ndo y con qu\u00e9 tipos de paciente Covid est\u00e1n recomendadas las TNI, qu\u00e9 ventajas ofrecen en tiempos de escasez de material y qu\u00e9 evidencia cient\u00edfica hay al respecto de su uso en pacientes covid.<\/p>\n<p><iframe loading=\"lazy\" title=\"CPAP de Boussignac, una herramienta para hacer frente a la COVID en Per\u00fa\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/-Cetqz5u7OY?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>[infobox title=&#8217;Art\u00edculos relacionados&#8217;]<\/p>\n<ul>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/humidificacion-activa-vmni\/\" target=\"_blank\" rel=\"noopener noreferrer\">El papel de la humidificaci\u00f3n activa en las terapias de ventilaci\u00f3n mec\u00e1nica no invasiva<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/montar-una-cpap-de-boussignac\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tutorial: c\u00f3mo montar una CPAP de Boussignac<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/swing-ventilacion-no-invasiva\/\" target=\"_blank\" rel=\"noopener noreferrer\">Qu\u00e9 es el SWING en VMNI<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/retos-sistemas-presion-positiva-continua\/\" target=\"_blank\" rel=\"noopener noreferrer\">3 retos y sus soluciones en los sistemas de CPAP<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/origen-cpap-boussignac\/\" target=\"_blank\" rel=\"noopener noreferrer\">El origen de la CPAP de Boussignac<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/ira-en-la-infeccion-por-covid-19-estrategias-de-tratamiento-en-la-atencion-de-emergencias\/\" target=\"_blank\" rel=\"noopener noreferrer\">IRA en la infecci\u00f3n por COVID-19: estrategias de tratamiento en emergencias<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/ira-en-la-infeccion-por-covid-19-estrategias-de-tratamiento-y-perfil-del-paciente\/\" target=\"_blank\" rel=\"noopener noreferrer\">IRA en la infecci\u00f3n por COVID-19: estrategias de tratamiento en urgencias<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/terapias-no-invasivas-servicios-urgencias\/\" target=\"_blank\" rel=\"noopener noreferrer\">Criterios de uso de las Terapias No Invasivas en la IRA en urgencias y emergencias<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/entrevista-al-doctor-jose-miguel-alonso-inigo-sobre-el-tratamiento-de-la-ira-por-covid\/\" target=\"_blank\" rel=\"noopener noreferrer\">Entrevista al dr. Jos\u00e9 Miguel Alonso sobre la IRA por COVID-19<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/cpap-boussignac-sistema-versatil\/\" target=\"_blank\" rel=\"noopener noreferrer\">La CPAP de Boussignac, un sistema vers\u00e1til de presi\u00f3n positiva continua<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/cpap-vs-alto-flujo-combinar\/\" target=\"_blank\" rel=\"noopener noreferrer\">CPAP vs Alto Flujo: \u00bfpor qu\u00e9 elegir si las puedes combinar con mejores resultados?<\/a><\/li>\n<li style=\"text-align: left;\"><a href=\"http:\/\/campusvygon.com\/cl\/cpap-boussignac-ira-hipoxemica-covid\/\" target=\"_blank\" rel=\"noopener noreferrer\">Por qu\u00e9 utilizar CPAP de Boussignac en pacientes con IRA hipox\u00e9mica: la experiencia COVID<\/a><\/li>\n<\/ul>\n<p>[\/infobox]<\/p>\n<p>[infobox title=&#8217;BIBLIOGRAF\u00cdA&#8217;]<\/p>\n<ul>\n<li><a href=\"http:\/\/www.areavmni.es\/images\/Actualizados%2021%20Marzo\/Recomendaciones%20VMNI-CR%20Covid%2019%20Marzo%202020.pdf\">Alonso \u00cd\u00f1igo, JM. et al.\u00a0<em>Recomendaciones para el uso de ventilaci\u00f3n mec\u00e1nica no invasiva, sistemas de CPAP no mec\u00e1nicos y terapia de alto flujo en pacientes con infecci\u00f3n respiratoria por covid-19<\/em>. Marzo 2020.<\/a><\/li>\n<li><a href=\"http:\/\/www.areavmni.es\/images\/Actualizados%2021%20Marzo\/Apendice%20VMNI-CR%20Covid%2019%20Marzo%202020.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Alonso \u00cd\u00f1igo, JM. et al. Ap\u00e9ndice recomendaciones TNI IRA COVID-19. Figuras y algoritmos. Marzo 2020.<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/watch?v=Zyn5eHa1FZM&amp;t=659s&amp;ab_channel=VygonSpain\" target=\"_blank\" rel=\"noopener noreferrer\">V\u00eddeo\u00a0<em>Por qu\u00e9 utilizar CPAP de Boussignac en pacientes con IRA hipox\u00e9mica: la experiencia COVID<\/em> del dr. Jos\u00e9 Manuel Carratal\u00e1.<\/a><\/li>\n<\/ul>\n<p>[\/infobox]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dr. Jos\u00e9 Miguel Alonso es un m\u00e9dico anestesi\u00f3logo espa\u00f1ol que trabaja en el hospital Polit\u00e9cnico y Universitario La Fe de Valencia. \u00c9l es uno de los principales expertos en VMNI en Espa\u00f1a y dirige el grupo VMNI-CR, que durante la pandemia ha servido como referente para muchos profesionales con poca formaci\u00f3n en el uso [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[80,1,258],"tags":[],"class_list":["post-13854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-entrevistas","category-emergencias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid<\/title>\n<meta name=\"description\" content=\"El dr. Alonso nos explica en esta conferencia qu\u00e9 han aprendido los sanitarios sobre el uso de la VMNI en pacientes Covid\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid\" \/>\n<meta property=\"og:description\" content=\"El dr. Alonso nos explica en esta conferencia qu\u00e9 han aprendido los sanitarios sobre el uso de la VMNI en pacientes Covid\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Chile\" \/>\n<meta property=\"article:author\" content=\"Array\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-11T00:31:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-18T08:54:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/11\/portada-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campus Vygon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/vygon_es\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campus Vygon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/\"},\"author\":{\"name\":\"Campus Vygon\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/75f06ca9d47ad2da0ff801057b0588fe\"},\"headline\":\"Conferencia: qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid. Dr. Alonso\",\"datePublished\":\"2020-11-11T00:31:32+00:00\",\"dateModified\":\"2020-12-18T08:54:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/\"},\"wordCount\":730,\"commentCount\":3,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/portada-blog.jpg\",\"articleSection\":[\"Art\u00edculos\",\"Entrevistas\",\"Urgencias y Emergencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/\",\"name\":\"Qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/portada-blog.jpg\",\"datePublished\":\"2020-11-11T00:31:32+00:00\",\"dateModified\":\"2020-12-18T08:54:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/75f06ca9d47ad2da0ff801057b0588fe\"},\"description\":\"El dr. Alonso nos explica en esta conferencia qu\u00e9 han aprendido los sanitarios sobre el uso de la VMNI en pacientes Covid\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/portada-blog.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/11\\\/portada-blog.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Conferencia: qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid. Dr. Alonso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/vmni-pacientes-covid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conferencia: qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid. Dr. Alonso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/\",\"name\":\"Campus Vygon Chile\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/75f06ca9d47ad2da0ff801057b0588fe\",\"name\":\"Campus Vygon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g\",\"caption\":\"Campus Vygon\"},\"description\":\"A place to learn about\u00a0health procedures\u00a0and techniques from\u00a0leading professionals.\",\"sameAs\":[\"https:\\\/\\\/www.vygon.es\\\/\",\"Array\",\"https:\\\/\\\/www.instagram.com\\\/vygonespana\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vygon-espaa\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/vygon_es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VygonSpain\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/author\\\/vygon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid","description":"El dr. Alonso nos explica en esta conferencia qu\u00e9 han aprendido los sanitarios sobre el uso de la VMNI en pacientes Covid","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid","og_description":"El dr. Alonso nos explica en esta conferencia qu\u00e9 han aprendido los sanitarios sobre el uso de la VMNI en pacientes Covid","og_url":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/","og_site_name":"Campus Vygon Chile","article_author":"Array","article_published_time":"2020-11-11T00:31:32+00:00","article_modified_time":"2020-12-18T08:54:20+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/11\/portada-blog.jpg","type":"image\/jpeg"}],"author":"Campus Vygon","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/vygon_es","twitter_misc":{"Escrito por":"Campus Vygon","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/"},"author":{"name":"Campus Vygon","@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/75f06ca9d47ad2da0ff801057b0588fe"},"headline":"Conferencia: qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid. Dr. Alonso","datePublished":"2020-11-11T00:31:32+00:00","dateModified":"2020-12-18T08:54:20+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/"},"wordCount":730,"commentCount":3,"image":{"@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/11\/portada-blog.jpg","articleSection":["Art\u00edculos","Entrevistas","Urgencias y Emergencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/","url":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/","name":"Qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid","isPartOf":{"@id":"https:\/\/campusvygon.com\/cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/11\/portada-blog.jpg","datePublished":"2020-11-11T00:31:32+00:00","dateModified":"2020-12-18T08:54:20+00:00","author":{"@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/75f06ca9d47ad2da0ff801057b0588fe"},"description":"El dr. Alonso nos explica en esta conferencia qu\u00e9 han aprendido los sanitarios sobre el uso de la VMNI en pacientes Covid","breadcrumb":{"@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/#primaryimage","url":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/11\/portada-blog.jpg","contentUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/11\/portada-blog.jpg","width":1920,"height":1080,"caption":"Conferencia: qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid. Dr. Alonso"},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/cl\/vmni-pacientes-covid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/cl\/"},{"@type":"ListItem","position":2,"name":"Conferencia: qu\u00e9 hemos aprendido sobre el uso de la VMNI en pacientes Covid. Dr. Alonso"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/cl\/#website","url":"https:\/\/campusvygon.com\/cl\/","name":"Campus Vygon Chile","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/75f06ca9d47ad2da0ff801057b0588fe","name":"Campus Vygon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g","caption":"Campus Vygon"},"description":"A place to learn about\u00a0health procedures\u00a0and techniques from\u00a0leading professionals.","sameAs":["https:\/\/www.vygon.es\/","Array","https:\/\/www.instagram.com\/vygonespana\/","https:\/\/www.linkedin.com\/company\/vygon-espaa","https:\/\/x.com\/https:\/\/twitter.com\/vygon_es","https:\/\/www.youtube.com\/user\/VygonSpain"],"url":"https:\/\/campusvygon.com\/cl\/author\/vygon\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/13854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/comments?post=13854"}],"version-history":[{"count":4,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/13854\/revisions"}],"predecessor-version":[{"id":14930,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/13854\/revisions\/14930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/media\/13861"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/media?parent=13854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/categories?post=13854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/tags?post=13854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}