{"id":31087,"date":"2022-02-15T00:15:00","date_gmt":"2022-02-14T23:15:00","guid":{"rendered":"http:\/\/campusvygon.com\/cl\/?p=31087"},"modified":"2022-02-15T12:00:46","modified_gmt":"2022-02-15T11:00:46","slug":"monitorizacion-hemodinamica-cirugia-cardiaca","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/","title":{"rendered":"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca"},"content":{"rendered":"\n<p class=\"has-text-color\" style=\"color:#a6a6a6\">La cirug\u00eda card\u00edaca es una intervenci\u00f3n de alto riesgo, durante la cual podemos observar cambios hemodin\u00e1micos de un momento a otro.<\/p>\n\n\n\n<h4 class=\"has-text-color wp-block-heading\" id=\"que-encontraras-en-este-articulo\" style=\"color:#a6a6a6\"><strong>\u00bfQU\u00c9 ENCONTRAR\u00c1S EN ESTE ART\u00cdCULO?<\/strong><\/h4>\n\n\n\n<ul class=\"has-text-color wp-block-list\" style=\"color:#a6a6a6\"><li>Tipos de cirug\u00edas card\u00edacas<\/li><li>Contraindicaciones<\/li><li>Preparaci\u00f3n<\/li><li>Riesgos y complicaciones de la cirug\u00eda card\u00edaca<\/li><li>Terapia perioperatoria guiada por objetivos<\/li><li>Monitorizaci\u00f3n hemodin\u00e1mica<\/li><\/ul>\n\n\n\n<p class=\"has-text-color\" style=\"color:#a6a6a6\">\u00bfQuieres conocer todos los desaf\u00edos que plantea la cirug\u00eda card\u00edaca y c\u00f3mo hacerles frente? Permanece en esta p\u00e1gina y lee la entrada completa. <\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La cirug\u00eda card\u00edaca representa un alto riesgo quir\u00fargico y perioperatorio, por ello, se requiere de personal experimentado y de un equipo de monitorizaci\u00f3n avanzado.<sup>1<\/sup><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"tipos-de-cirugias-cardiacas\">Tipos de cirug\u00edas card\u00edacas<\/h2>\n\n\n\n<p>Existen muchos tipos de cirug\u00eda card\u00edaca, pero algunas de las m\u00e1s comunes son:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Injerto de derivaci\u00f3n aorto-coronario<\/strong>.<\/li><li><strong>Reparaci\u00f3n o reemplazo de v\u00e1lvulas card\u00edacas<\/strong>.&nbsp;<\/li><li><strong>Inserci\u00f3n de un marcapasos o un desfibrilador autom\u00e1tico implantable<\/strong>.&nbsp;<\/li><li><strong>Reparaci\u00f3n de aneurismas<\/strong>.&nbsp;<\/li><li><strong>Trasplante de coraz\u00f3n<\/strong>.&nbsp;<\/li><li><strong>Inserci\u00f3n de un dispositivo de asistencia ventricular o coraz\u00f3n artificial total<\/strong>.&nbsp;<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"contraindicaciones\">Contraindicaciones<\/h2>\n\n\n\n<p>Al igual que sucede con cualquier otro procedimiento, durante el preoperatorio de la cirug\u00eda cardiaca, se deben evaluar los factores de riesgo y las contraindicaciones.&nbsp;<sup>1<\/sup><\/p>\n\n\n\n<p>Este tipo de intervenciones suelen limitarse a enfermedades card\u00edacas avanzadas y suponen, a menudo, la \u00faltima opci\u00f3n de tratamiento. En estos casos, los beneficios de la operaci\u00f3n superan los riesgos.&nbsp;<sup>1<\/sup><\/p>\n\n\n\n<p>Para evaluar el riesgo operatorio se han desarrollado diferentes herramientas de estratificaci\u00f3n del riesgo como <strong>EuroScore<\/strong>, la <strong>puntuaci\u00f3n de Parsonnet<\/strong> o la <strong>puntuaci\u00f3n de la Sociedad de Cirujanos Tor\u00e1cicos<\/strong> para identificar a los pacientes que son susceptibles de cirug\u00eda card\u00edaca. <sup>1<\/sup><\/p>\n\n\n\n<p>Uno de los motivos m\u00e1s habituales por los que se postpone una cirug\u00eda card\u00edaca es la inestabilidad del paciente en el momento en que est\u00e1 planificada la operaci\u00f3n.<sup> 1<\/sup><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"preparacion\">Preparaci\u00f3n<\/h2>\n\n\n\n<p>Antes de entrar a quir\u00f3fano, se debe evaluar el estado actual del paciente para tomar todas las precauciones posibles que permitan identificar posibles contratiempos<sup> 1<\/sup>:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>An\u00e1lisis de sangre<\/strong> para evaluar una amplia gama de funciones de los sistemas corporales (pruebas de funci\u00f3n renal y hep\u00e1tica, coagulaci\u00f3n, hemograma completo, electrolitos).<sup> 1<\/sup><\/li><li><strong>ECG<\/strong> para verificar la actividad r\u00edtmica card\u00edaca normal.<sup> 1<\/sup><\/li><li><strong>Ecocardiograf\u00eda y cateterismo card\u00edaco<\/strong> para detectar enfermedad arterial coronaria y valvulopat\u00edas.<sup> 1<\/sup><\/li><li><strong>Radiograf\u00eda de t\u00f3rax o tomograf\u00eda computarizada de t\u00f3rax<\/strong> para visualizar comorbilidades tor\u00e1cicas y planificar la t\u00e9cnica operatoria.<sup> 1<\/sup><\/li><li><strong>Ecograf\u00eda de los vasos del cuello <\/strong>para evaluar el riesgo de accidente cerebrovascular.<sup> 1<\/sup><\/li><li><strong>Ecograf\u00eda de las venas de las extremidades inferiore<\/strong>s como posibles injertos.<sup> 1<\/sup><\/li><li><strong>Ecograf\u00eda doppler carot\u00eddea<\/strong> en pacientes con enfermedad del tronco com\u00fan izquierdo, vasculopat\u00eda perif\u00e9rica, soplos carotideos, antecedentes de accidente cerebrovascular, antecedentes de tabaquismo intenso y edad mayor de 65 a\u00f1os.&nbsp;<sup>1<\/sup><\/li><li><strong>Endarterectom\u00eda previa a la intervenci\u00f3n<\/strong> cuando se detecta una estenosis significativa.<sup> 1<\/sup><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"riesgos-y-complicaciones-de-la-cirugia-cardiaca\">Riesgos y complicaciones de la cirug\u00eda card\u00edaca<\/h2>\n\n\n\n<p>El elevado \u00edndice de complicaciones asociadas a la cirug\u00eda card\u00edaca ocasiona grandes problemas para la salud del paciente, como morbilidad o invalidez, pero tambi\u00e9n un gran consumo de recursos. Cuando estas complicaciones aparecen, la estancia hospitalaria aumenta y, con ello, los costes por proceso. <sup>4,7<\/sup><\/p>\n\n\n\n<p>Los riesgos var\u00edan de un tipo de cirug\u00eda card\u00edaca a otro y pueden ser mayores si se emplean dispositivos de circulaci\u00f3n extracorp\u00f3rea (CEC) durante la intervenci\u00f3n.<sup> 2<\/sup><\/p>\n\n\n\n<p>Para reducir la probabilidad de enfrentarnos a complicaciones derivadas de la cirug\u00eda, se debe controlar y monitorizar de cerca al paciente tanto durante la cirug\u00eda como durante el postoperatorio.<sup> 4<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"complicaciones\"><strong>Complicaciones <\/strong><\/h3>\n\n\n\n<p>En los \u00faltimos 30 a\u00f1os, la cirug\u00eda card\u00edaca ha presentado un gran desarrollo, con una actualizaci\u00f3n constante de la t\u00e9cnica quir\u00fargica que ha permitido un mejor manejo de la patolog\u00eda. No obstante, no deja de ser un procedimiento de alto riesgo con graves complicaciones tanto intraoperatorias como postoperatorias. <sup>4<\/sup><\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"algunas-de-las-complicaciones-que-podemos-encontrarnos-durante-la-cirugia-son-4\"><strong>Algunas de las complicaciones que podemos encontrarnos durante la cirug\u00eda son:<\/strong><sup>4<\/sup><\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li>Inestabilidad hemodin\u00e1mica.<sup> 4<\/sup><\/li><li>Bloqueo auriculoventricular completo.<sup> 4<\/sup><\/li><li>Taquicardia ventricular. <sup>4<\/sup><\/li><li>Fibrilaci\u00f3n ventricular.<sup> 4<\/sup><\/li><li>Asistolia.<sup> 4<\/sup><\/li><li>Bloqueo de rama izquierda.<sup> 4<\/sup><\/li><li>Taquicardia supraventricular.<sup> 4<\/sup><\/li><li>Hipertensi\u00f3n arterial.<sup> 4<\/sup><\/li><li>Hipoxemia.<sup> 4<\/sup><\/li><li>Vasoplejia.<sup> 4<\/sup><\/li><li>Shock hemorr\u00e1gico.<sup> 4<\/sup><\/li><li>Shock cardiog\u00e9nico.<sup> 4<\/sup><\/li><li>Sangrados.<sup> 4<\/sup><\/li><li>Paro cardiorrespiratorio.<sup> 4<\/sup><\/li><li>Coagulopat\u00edas.<sup> 4<\/sup><\/li><li>Fibrilaci\u00f3n auricular.<sup> 4<\/sup><\/li><li>Muerte.<sup> 4<\/sup><\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"complicaciones-postoperatorias\"><strong>Complicaciones postoperatorias<\/strong><\/h3>\n\n\n\n<p>Debido a la alta magnitud de este tipo de cirug\u00eda, el postoperatorio cobra una gran importancia.<sup> 4<\/sup><\/p>\n\n\n\n<p>Un correcto seguimiento durante el postoperatorio inmediato de cirug\u00eda card\u00edaca, permite obtener informaci\u00f3n objetiva en cuanto a la naturaleza de los cambios fisiol\u00f3gicos, as\u00ed como, la identificaci\u00f3n de los riesgos reales y potenciales que puedan comprometer correcta evoluci\u00f3n del paciente. 4<\/p>\n\n\n\n<p>Cada vez son m\u00e1s los pacientes con m\u00faltiples comorbilidades que se someten a cirug\u00eda card\u00edaca. Estos pacientes, considerados de alto riesgo, a menudo tienen una reserva fisiol\u00f3gica limitada, lo que se traduce en un mayor riesgo de morbilidad posoperatoria.&nbsp;<\/p>\n\n\n\n<p>Tanto es as\u00ed, que las<strong> complicaciones postoperatorias graves <\/strong>oscilan entre el <strong>15 % y el 30%<\/strong>, e incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S\u00edndrome de bajo gasto card\u00edaco.<sup>8<\/sup><\/li><li>Accidente cerebrovascular. <sup>7<\/sup><\/li><li>Insuficiencia renal. <sup>7<\/sup><\/li><li>Intubaci\u00f3n prolongada. <sup>7<\/sup><\/li><li>Infecci\u00f3n de la herida del estern\u00f3n. <sup>7<\/sup><\/li><\/ul>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"otras-complicaciones-que-podemos-encontrarnos-durante-el-postoperatorio-son\"><strong>Otras complicaciones <\/strong>que podemos encontrarnos durante el postoperatorio son:<\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li>Taponamiento card\u00edaco.<sup> 4<\/sup><\/li><li>Bloqueo de rama izquierda.<sup> 4<\/sup><\/li><li>Paro cardiorrespiratorio.<sup> 4<\/sup><\/li><li>Sangrado posoperatorio.<sup> 4<\/sup><\/li><li>Vasoplejia posoperatoria.<sup> 4<\/sup><\/li><li>Shock cardiog\u00e9nico.<sup> 4<\/sup><\/li><li>Anemia severa.<sup> 4<\/sup><\/li><\/ul>\n\n\n\n<p>Aproximadamente entre el <strong>19 y el 45%<\/strong> de los pacientes operados de cirug\u00eda cardiaca pasan por <strong>cuidados intensivos prolongados <\/strong>despu\u00e9s de la intervenci\u00f3n.&nbsp;<sup>7<\/sup><\/p>\n\n\n\n<p>Estos \u00edndices sugieren la necesidad continua de buscar \u00e1reas de mejora. Algunos profesionales ven la <strong>terapia guiada por objetivos<\/strong> como una de las herramientas que permitir\u00eda disminuir estos porcentajes y, de esta forma, incrementar el \u00e9xito en la operaci\u00f3n. &nbsp;<sup>7<\/sup><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"terapia-perioperatoria-guiada-por-objetivos\">Terapia perioperatoria guiada por objetivos<\/h2>\n\n\n\n<p>La&nbsp;terapia guiada por objetivos, GDT en sus siglas en ingl\u00e9s,&nbsp;se basa en la <strong>monitorizaci\u00f3n de par\u00e1metros hemodin\u00e1micos para guiar la administraci\u00f3n de fluidos, inotr\u00f3picos y posibles transfusiones de sangre <\/strong>con el fin de lograr un s<strong>uministro \u00f3ptimo de ox\u00edgeno a los tejidos<\/strong>.<sup> 7<\/sup><\/p>\n\n\n\n<p>En cirug\u00eda no card\u00edaca, existen multitud de ensayos y estudios que han demostrado que <strong>disminuye las complicaciones y mejora el resultado postoperatorio <\/strong>en pacientes de cirug\u00eda de alto riesgo. Debido a su utilidad, est\u00e1 recogido por diversas gu\u00edas de pr\u00e1ctica cl\u00ednica.<sup> 7<\/sup><\/p>\n\n\n\n<p>No obstante, en la cirug\u00eda card\u00edaca que requiere CEC, la aplicaci\u00f3n generalizada de GDT esta en sus fases inciales.&nbsp;A lo largo de los a\u00f1os, varios estudios han demostrado la utilidad tanto de la GDT intraoperatoria como postoperatoria en este tipo de intervenciones.&nbsp; Estos ensayos han puesto de manifiesto que una terapia guiada por objetivos permite <strong>reducir las complicaciones generales y la duraci\u00f3n de la estancia hospitalaria<\/strong>.&nbsp;Tanto es as\u00ed, que en las recientes <strong>Directrices de la Enhanced Recovery After Surgery Society<\/strong> para el cuidado perioperatorio en cirug\u00eda card\u00edaca lo recogen entre sus recomendaciones.<sup> 7<\/sup><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"689\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/protocolo-terapia-guiada-por-objetivos-cardiaca-1024x689.jpg\" alt=\"Protocolo de optimizaci\u00f3n hemodin\u00e1mica cardiaca\" class=\"wp-image-31090\" srcset=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/protocolo-terapia-guiada-por-objetivos-cardiaca-980x659.jpg 980w, http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/protocolo-terapia-guiada-por-objetivos-cardiaca-480x323.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/Protocolo-de-optimizacion-hemodinamica-cardiaca.pdf\">Descargar protocolo de optimizaci\u00f3n hemodin\u00e1mica card\u00edaca<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"monitorizacion-hemodinamica\">Monitorizaci\u00f3n hemodin\u00e1mica<\/h2>\n\n\n\n<p>El aspecto m\u00e1s importante en el seguimiento de los pacientes de cirug\u00eda card\u00edaca es la detecci\u00f3n de trastornos de las funciones vitales que ponen en peligro la vida, tanto durante el intraoperatorio, como durante la estancia en cuidados intensivos. <sup>5<\/sup><\/p>\n\n\n\n<p>Como coment\u00e1bamos, en los \u00faltimos a\u00f1os, la cirug\u00eda card\u00edaca se ha desarrollado r\u00e1pidamente, ello ha tra\u00eddo una mejora en el tratamiento anest\u00e9sico y en la monitorizaci\u00f3n hemodin\u00e1mica, reduci\u00e9ndose la mortalidad perioperatoria significativamente en las \u00faltimas d\u00e9cadas. <sup>6<\/sup><\/p>\n\n\n\n<p>Un seguimiento hemodin\u00e1mico estricto permite una<strong> terapia individualizada<\/strong>, lo cual <strong>disminuye la morbimortalidad postoperatoria<\/strong>, la <strong>duraci\u00f3n de la hospitalizaci\u00f3n<\/strong> y el <strong>coste asistencial<\/strong>. <sup>6<\/sup><\/p>\n\n\n\n<p>En cirug\u00edas de alto riesgo, como es la card\u00edaca, es imprescindible una monitorizaci\u00f3n en tiempo real, ya que la hemodin\u00e1mica del paciente puede variar de un momento a otro. No obstante, no todos los sistemas de monitorizaci\u00f3n est\u00e1n validados en escenarios cl\u00ednicos complejos, especialmente en pacientes con presiones de perfusi\u00f3n muy reducidas. <sup>5<\/sup><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"parametros-hemodinamicos\"><strong>Par\u00e1metros hemodin\u00e1micos<\/strong><\/h3>\n\n\n\n<p>Durante la cirug\u00eda card\u00edaca son diversas las razones por las que puede producirse una inestabilidad hemodin\u00e1mica importante, por ello, se debe contar con un dispositivo de monitorizaci\u00f3n que permita evaluar la respuesta del paciente en <strong>tiempo real<\/strong>, siendo posible <strong>prevenir la hipoxia tisular y la posibilidad de realizar una terapia temprana dirigida por objetivos<\/strong>. <sup>9<\/sup><\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"perfusion-tisular\"><strong>Perfusi\u00f3n tisular<\/strong><\/h4>\n\n\n\n<p>Como hemos comentado, una de las grandes preocupaciones durante la intervenci\u00f3n es mantener un <strong>correcto suministro de ox\u00edgeno a los tejidos y \u00f3rganos<\/strong>, el cual puede verse comprometido tanto durante las distintas fases de la cirug\u00eda como en el postoperatorio.<sup>12<\/sup><\/p>\n\n\n\n<p>El <strong>gasto card\u00edaco (GC) <\/strong>es un factor com\u00fan al suministro de ox\u00edgeno y a la presi\u00f3n arterial, por lo tanto, la evaluaci\u00f3n y optimizaci\u00f3n de este sigue siendo una piedra angular para el mantenimiento de la homeostasis circulatoria. La cirug\u00eda card\u00edaca y la CEC crean invariablemente cambios din\u00e1micos en el gasto card\u00edaco debido a las fluctuaciones del volumen sangu\u00edneo, el retorno venoso y la contractilidad. <sup>12<\/sup><\/p>\n\n\n\n<p>A parte del <strong>gasto card\u00edaco<\/strong> y la<strong> presi\u00f3n arterial<\/strong>, contar con par\u00e1metros espec\u00edficos como el <strong>aporte de ox\u00edgeno (DO2)<\/strong> permitir\u00e1 conocer de forma m\u00e1s exacta si el suministro est\u00e1 siendo correcto.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"hipovolemia\"><strong>Hipovolemia<\/strong><\/h4>\n\n\n\n<p>En los pacientes de cirug\u00eda cardiaca es habitual encontrar alteraciones en la curva de rendimiento cardiaco, causadas por la enfermedad subyacente, lo que provoca una <strong>tolerancia muy limitada a la hipervolemia e hipovolemia<\/strong>, por ello, una optimizaci\u00f3n de la <strong>precarga <\/strong>es imprescindible para el \u00e9xito de la intervenci\u00f3n. <sup>10<\/sup><\/p>\n\n\n\n<p>Para identificar y actuar desde los primeros indicios de la hipovolemia es importante contar con un sistema que muestre diferentes par\u00e1metros hemodin\u00e1micos cl\u00e1sicos y avanzados latido a latido.<\/p>\n\n\n\n<p>Ante estados, o posibles estados, de hipovolemia, los <strong>par\u00e1metros hemodin\u00e1micos din\u00e1micos<\/strong> ser\u00e1n m\u00e1s precisos para determinar su etiolog\u00eda y la respuesta del paciente a la reposici\u00f3n de l\u00edquidos.&nbsp;<sup>11<\/sup><\/p>\n\n\n\n<p>Por ello, al evaluar y monitorizar la respuesta del paciente, adem\u00e1s de contar con par\u00e1metros cl\u00e1sicos de presi\u00f3n arterial, deberemos disponer de otra serie de par\u00e1metros que permitan hacer un an\u00e1lisis global del estado hemodin\u00e1mico paciente.<\/p>\n\n\n\n<p>Algunos de los par\u00e1metros m\u00e1s \u00fatiles ante la hipovolemia son: <strong>variaci\u00f3n de la presi\u00f3n del pulso (PPV)<\/strong>, <strong>variaci\u00f3n del volumen sist\u00f3lico (SVV)<\/strong>,<strong> elastancia din\u00e1mica (PPV\/VVS)<\/strong>, <strong>elastancia arterial (Ea)<\/strong> o <strong>eficiencia del ciclo card\u00edaco (CCE)<\/strong>. Aunque su uso es limitado con el t\u00f3rax abierto durante la intervenci\u00f3n, su uso durante el periodo postoperatorio puede ser de gran utilidad. Veremos estos par\u00e1metros en profundidad a continuaci\u00f3n.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"respuesta-a-fluidos\"><strong>Respuesta a fluidos<\/strong><\/h4>\n\n\n\n<p>Para poder optimizar el tratamiento, tambi\u00e9n es importante conocer c\u00f3mo responde el paciente a los fluidos administrados. La&nbsp;<strong>variaci\u00f3n de la presi\u00f3n del pulso (PPV)&nbsp;<\/strong>y la&nbsp;<strong>variaci\u00f3n del volumen sist\u00f3lico (SVV)<\/strong>, son dos par\u00e1metros muy relevantes para predecir respuesta del paciente a la infusi\u00f3n de volumen, aunque no todos los monitores cuentan con ellos. En caso de no disponer de estas variables, utilizando los cambios en la precarga y la presi\u00f3n de la aur\u00edcula derecha, la presi\u00f3n arterial, la presi\u00f3n del pulso o el volumen sist\u00f3lico es posible calcularlos, no obstante, eso&nbsp;<strong>retrasar\u00eda nuestra actuaci\u00f3n con el riesgo que esto conlleva<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Tanto la PPV como la VVS est\u00e1n consideradas como&nbsp;<strong>predictores fiables para medir la respuesta del gasto card\u00edaco (GC) a la infusi\u00f3n de fluidos<\/strong>, por lo que permitir\u00e1n seguir de cerca la evoluci\u00f3n del tratamiento administrado.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"poscarga\"><strong>Poscarga<\/strong><\/h4>\n\n\n\n<p>Entre los par\u00e1metros de poscarga encontramos diferentes par\u00e1metros. En primer lugar, las <strong>resistencias vasculares sist\u00e9micas (RVS)<\/strong> aportar\u00e1n informaci\u00f3n sobre el componente est\u00e1tico del sistema cardiovascular. Por su parte, la <strong>elastancia arterial (Ea)<\/strong> y la <strong>elastancia din\u00e1mica (PPV\/SVV) <\/strong>hablar\u00e1n de su componente din\u00e1mico.<\/p>\n\n\n\n<p>La<strong>&nbsp;elastancia arterial (Ea)<\/strong> es el cociente entre los cambios de presi\u00f3n telesist\u00f3lica y los cambios de volumen sist\u00f3lico, analizados desde un punto de vista din\u00e1mico. En cambio, la&nbsp;<strong>elastancia din\u00e1mica (PPV\/SVV)<\/strong>&nbsp;es el cociente entre la variaci\u00f3n de la presi\u00f3n del pulso (PPV) y la variaci\u00f3n del volumen sist\u00f3lico (SVV) durante una sola respiraci\u00f3n con presi\u00f3n positiva, lo cual permite evaluar el tono arterial din\u00e1mico.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"eficiencia\"><strong>Eficiencia<\/strong><\/h4>\n\n\n\n<p>Por \u00faltimo, la&nbsp;<strong>eficiencia del ciclo card\u00edaco (CCE)<\/strong>&nbsp;tambi\u00e9n resultar\u00e1 \u00fatil ya que aporta informaci\u00f3n sobre la cantidad de energ\u00eda que est\u00e1 gastando el sistema cardiovascular en eyectar la sangre en cada s\u00edstole, es decir, indica si el sistema est\u00e1 siendo eficiente o no.<\/p>\n\n\n\n<p>Para conocer m\u00e1s sobre&nbsp;<strong>monitorizaci\u00f3n hemodin\u00e1mica con el m\u00e9todo P.R.A.M.<\/strong>, matric\u00falate en el&nbsp;<strong>curso impartido por el Dr.<\/strong>&nbsp;<strong>Jos\u00e9 Miguel Alonso I\u00f1igo<\/strong>, m\u00e9dico especialista en Anestesiolog\u00eda-Reanimaci\u00f3n y Tratamiento del dolor. Para ello, solo tienes que&nbsp;hacer <a href=\"https:\/\/formacion.campusvygon.com\/cl\/cursos\/acreditado-monitorizacion-hemodinamica-con-metodo-p-r-a-m-44-77?edicion=93&amp;tab=info\">clic aqu\u00ed<\/a>&nbsp;o en el siguiente banner.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/formacion.campusvygon.com\/cl\/cursos\/acreditado-monitorizacion-hemodinamica-con-metodo-p-r-a-m-44-77?edicion=93&amp;tab=info\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/monitorizacion-hemodinamica-PRAM-curso-acreditado.jpg\" alt=\"\" class=\"wp-image-31082\" srcset=\"http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/monitorizacion-hemodinamica-PRAM-curso-acreditado.jpg 1024w, http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/monitorizacion-hemodinamica-PRAM-curso-acreditado-980x490.jpg 980w, http:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/monitorizacion-hemodinamica-PRAM-curso-acreditado-480x240.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"sabox-plus-item\"><div class=\"saboxplugin-wrap\" itemtype=\"http:\/\/schema.org\/Person\" itemscope itemprop=\"author\"><div class=\"saboxplugin-tab saboxplugin-tab-about\"><div class=\"saboxplugin-gravatar\"><img alt='' src='https:\/\/secure.gravatar.com\/avatar\/d51c3812cc3e7ae46633a25296fff4ad1d9761290f6460ef0164f87f06df2645?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/d51c3812cc3e7ae46633a25296fff4ad1d9761290f6460ef0164f87f06df2645?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' itemprop=\"image\"\/><\/div><div class=\"saboxplugin-authorname\"><a href=\"https:\/\/campusvygon.com\/cl\/author\/fcarrillo\/\" class=\"vcard author\" rel=\"author\" itemprop=\"url\"><span class=\"fn\" itemprop=\"name\">Federico Carrillo Garc\u00eda<\/span><\/a><\/div><div class=\"saboxplugin-desc\"><div itemprop=\"description\"><p>Delegado de ventas de Vygon Espa\u00f1a en Pa\u00eds Vasco, Cantabria , Rioja, Navarra, Burgos y Soria.<\/p>\n<ul>\n<li><strong>EXPERIENCIA<\/strong><\/li>\n<\/ul>\n<p>De formaci\u00f3n, soy Licenciado en Ciencias de la Comunicaci\u00f3n, rama Periodismo, pero llevo desarrollando toda mi carrera profesional en el sector comercial , \u00e1mbito sanitario y biotecnol\u00f3gico<\/p>\n<ul>\n<li><strong>PUEDO AYUDARTE EN&#8230;<\/strong><\/li>\n<\/ul>\n<p>Puedo ofrecerte ayuda a la hora de elegir el material m\u00e9dico-quir\u00fargico que precises para tu labor asistencial.<\/p>\n<\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><\/div>\n\n<div class=\"sabox-plus-item\"><div class=\"saboxplugin-wrap\" itemtype=\"http:\/\/schema.org\/Person\" itemscope itemprop=\"author\"><div class=\"saboxplugin-tab saboxplugin-tab-about\"><div class=\"saboxplugin-gravatar\"><img alt='' src='https:\/\/secure.gravatar.com\/avatar\/7eced5a93e03c21ccd898ceea564850777968a26d65e738ae6409caa33f86f91?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/7eced5a93e03c21ccd898ceea564850777968a26d65e738ae6409caa33f86f91?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' itemprop=\"image\"\/><\/div><div class=\"saboxplugin-authorname\"><a href=\"https:\/\/campusvygon.com\/cl\/author\/jperez\/\" class=\"vcard author\" rel=\"author\" itemprop=\"url\"><span class=\"fn\" itemprop=\"name\">Javier P\u00e9rez Mart\u00ednez<\/span><\/a><\/div><div class=\"saboxplugin-desc\"><div itemprop=\"description\"><p>Delgado especialista Cuidados Intensivos y Anestesia \u2013 Emergencias \u2013 Madrid &#8211; Vygon Espa\u00f1a<\/p>\n<ul>\n<li><strong>EXPERIENCIA<\/strong><\/li>\n<\/ul>\n<p>Desde hace 10 a\u00f1os trabajo en Vygon intentado mejorar las pr\u00e1cticas y conocimientos de mis clientes para que esto repercuta en los pacientes. He desempe\u00f1ado muchas y variadas funciones con esfuerzo e ilusi\u00f3n.<\/p>\n<ul>\n<li><strong>PUEDO AYUDARTE EN&#8230;<\/strong><\/li>\n<\/ul>\n<p>Mi trabajo es dar soluciones a las necesidades de los clientes y estar a su lado en todo momento.<\/p>\n<\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><\/div>\n\n<div class=\"sabox-plus-item\"><div class=\"saboxplugin-wrap\" itemtype=\"http:\/\/schema.org\/Person\" itemscope itemprop=\"author\"><div class=\"saboxplugin-tab saboxplugin-tab-about\"><div class=\"saboxplugin-gravatar\"><img alt='' src='https:\/\/secure.gravatar.com\/avatar\/77b6e2fef5e6af22cafea7d4f28f51a7181fa4e2686673ac7adda29d5b37a7c6?s=100&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/77b6e2fef5e6af22cafea7d4f28f51a7181fa4e2686673ac7adda29d5b37a7c6?s=200&#038;d=mm&#038;r=g 2x' class='avatar avatar-100 photo' height='100' width='100' itemprop=\"image\"\/><\/div><div class=\"saboxplugin-authorname\"><a href=\"https:\/\/campusvygon.com\/cl\/author\/sperez\/\" class=\"vcard author\" rel=\"author\" itemprop=\"url\"><span class=\"fn\" itemprop=\"name\">Santiago P\u00e9rez Espartero<\/span><\/a><\/div><div class=\"saboxplugin-desc\"><div itemprop=\"description\"><p>Delegado de ventas &#8211; Granada, Almer\u00eda y Ja\u00e9n<\/p>\n<\/div><\/div><div class=\"clearfix\"><\/div><\/div><\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"bibliografia\"><strong>Bibliograf\u00eda<\/strong><\/h3>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>1. Senst B, Kumar A, Diaz RR. Cardiac Surgery. [Updated 2021 Sep 18]. In: StatPearls [Internet]. Treasure Island (FL): StatPearls Publishing; 2021 Jan-.&nbsp;Available from: <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK532935\/\">https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK532935\/<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>2. N. Fogoros, R., &amp; Whitlock, J. (2020, 2 enero).&nbsp;Open Heart Surgery Risks and Complications. Verywell Health. <a href=\"https:\/\/www.verywellhealth.com\/heart-surgery-complications-and-risks-3156953\">https:\/\/www.verywellhealth.com\/heart-surgery-complications-and-risks-3156953<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>3. American Society of Anesthesiologists.&nbsp;Heart Surgery: Types, Recovery and Risks &#8211; Made for This Moment. Made For This Moment | Anesthesia, Pain Management &amp; Surgery. <a href=\"https:\/\/www.asahq.org\/madeforthismoment\/preparing-for-surgery\/procedures\/heart-surgery\/\">https:\/\/www.asahq.org\/madeforthismoment\/preparing-for-surgery\/procedures\/heart-surgery\/<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>4. Gonz\u00e1lez Kadashinskaia, Galina Orlandovna, Bello Carrasco, Lourdes Maribel, &amp; Anchundia Alvia, Dolores Alexandra. (2020). Cirug\u00eda card\u00edaca, complicaciones inmediatas post operatorias.&nbsp;Revista Universidad y Sociedad,&nbsp;12(2), 293-300. Epub 02 de abril de 2020. Recuperado en 11 de enero de 2022, de <a href=\"http:\/\/scielo.sld.cu\/scielo.php?script=sci_arttext&amp;pid=S2218-36202020000200293&amp;lng=es&amp;tlng=es\">http:\/\/scielo.sld.cu\/scielo.php?script=sci_arttext&amp;pid=S2218-36202020000200293&amp;lng=es&amp;tlng=es<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>5. Boldt J., Hempelmann G. (1991) Hemodynamic Monitoring in Cardiac Surgery. In: Dhainaut JF., Payen D. (eds) Strategy in Bedside Hemodynamic Monitoring. Update in Intensive Care and Emergency Medicine, vol 11. Springer, Berlin, Heidelberg. <a href=\"https:\/\/doi.org\/10.1007\/978-3-642-84167-5_11\">https:\/\/doi.org\/10.1007\/978-3-642-84167-5_11<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>6. Coelembier, C., &amp; Fellahi, J. L. (2020). Monitorizaci\u00f3n hemodin\u00e1mica del paciente en cirug\u00eda no card\u00edaca.&nbsp;EMC &#8211; Anestesia-Reanimaci\u00f3n,&nbsp;46(3). <a href=\"https:\/\/doi.org\/10.1016\/s1280-4703(20)43986-6\">https:\/\/doi.org\/10.1016\/s1280-4703(20)43986-6<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>7. Ramsingh, D., Hu, H., Yan, M., Lauer, R., Rabkin, D., Gatling, J., Floridia, R., Martinez, M., Dorotta, I., &amp; Razzouk, A. (2021). Perioperative Individualized Goal Directed Therapy for Cardiac Surgery: A Historical-Prospective, Comparative Effectiveness Study.&nbsp;Journal of Clinical Medicine,&nbsp;10(3). <a href=\"https:\/\/doi.org\/10.3390\/jcm10030400\">https:\/\/doi.org\/10.3390\/jcm10030400<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>8. Sociedad Uruguaya de Cardiolog\u00eda. (2020). S\u00edndrome de baja gasto card\u00edaco en el posoperatorio de cirug\u00eda card\u00edaca.&nbsp;Revista Uruguaya de cardiolog\u00eda,&nbsp;35(5). <a href=\"https:\/\/doi.org\/10.29277\/cardio.35.3.18\">https:\/\/doi.org\/10.29277\/cardio.35.3.18<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>9. Arora, D., &amp; Mehta, Y. (2016). Recent trends on hemodynamic monitoring in cardiac surgery.&nbsp;Annals of cardiac anaesthesia,&nbsp;19(4), 580\u2013583. <a href=\"https:\/\/doi.org\/10.4103\/0971-9784.191557\">https:\/\/doi.org\/10.4103\/0971-9784.191557<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>10. Boix, E., Vicente, R., &amp; P\u00e9rez-Artacho, J. (2014). Fluidoterapia en cirug\u00eda cardiaca. Puesta al d\u00eda.&nbsp;Revista Espa\u00f1ola de Anestesiolog\u00eda y Reanimaci\u00f3n,&nbsp;61(1), 21\u201327. <a href=\"https:\/\/doi.org\/10.1016\/j.redar.2013.01.006\">https:\/\/doi.org\/10.1016\/j.redar.2013.01.006<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>11. Melendez Rivera JG, Anjum F. Hypovolemia. . In: StatPearls . Treasure Island (FL): StatPearls Publishing; 2021 Jan-.&nbsp;Available from:&nbsp;<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK565845\/\">https:\/\/www.ncbi.nlm.nih.gov\/books\/NBK565845\/<\/a><\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"bibliografia\"><strong>12. Lighthall, G. K., &amp; Singh, S. (2014). Perioperative Maintenance of Tissue Perfusion and Cardiac Output in Cardiac Surgery Patients.&nbsp;Seminars in Cardiothoracic and Vascular Anesthesia,&nbsp;18(2), 117\u2013136. <a href=\"https:\/\/doi.org\/10.1177\/1089253214534781\">https:\/\/doi.org\/10.1177\/1089253214534781<\/a><\/strong><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La cirug\u00eda card\u00edaca es una intervenci\u00f3n de alto riesgo, durante la cual podemos observar cambios hemodin\u00e1micos de un momento a otro. \u00bfQU\u00c9 ENCONTRAR\u00c1S EN ESTE ART\u00cdCULO? Tipos de cirug\u00edas card\u00edacas Contraindicaciones Preparaci\u00f3n Riesgos y complicaciones de la cirug\u00eda card\u00edaca Terapia perioperatoria guiada por objetivos Monitorizaci\u00f3n hemodin\u00e1mica \u00bfQuieres conocer todos los desaf\u00edos que plantea la cirug\u00eda [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[285,80,115],"tags":[640,61],"class_list":["post-31087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anestesia-y-cuidados-intensivos","category-articulos","category-cuidados-intensivos","tag-cirugia-cardiaca","tag-monitorizacion-hemodinamica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca - Campus Vygon Chile<\/title>\n<meta name=\"description\" content=\"La cirug\u00eda card\u00edaca representa un alto riesgo quir\u00fargico y perioperatorio, por ello, se requiere de una monitorizaci\u00f3n precisa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca - Campus Vygon Chile\" \/>\n<meta property=\"og:description\" content=\"La cirug\u00eda card\u00edaca representa un alto riesgo quir\u00fargico y perioperatorio, por ello, se requiere de una monitorizaci\u00f3n precisa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Chile\" \/>\n<meta property=\"article:author\" content=\"Array\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-14T23:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-15T11:00:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/CIRUGIA-CARDIACA-PORTADA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campus Vygon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/vygon_es\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campus Vygon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/\"},\"author\":{\"name\":\"Campus Vygon\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/75f06ca9d47ad2da0ff801057b0588fe\"},\"headline\":\"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca\",\"datePublished\":\"2022-02-14T23:15:00+00:00\",\"dateModified\":\"2022-02-15T11:00:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/\"},\"wordCount\":2650,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/CIRUGIA-CARDIACA-PORTADA.jpg\",\"keywords\":[\"cirug\u00eda card\u00edaca\",\"Monitorizaci\u00f3n hemodin\u00e1mica\"],\"articleSection\":[\"Anestesia y Cuidados Intensivos\",\"Art\u00edculos\",\"Cuidados Intensivos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/\",\"name\":\"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca - Campus Vygon Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/CIRUGIA-CARDIACA-PORTADA.jpg\",\"datePublished\":\"2022-02-14T23:15:00+00:00\",\"dateModified\":\"2022-02-15T11:00:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/75f06ca9d47ad2da0ff801057b0588fe\"},\"description\":\"La cirug\u00eda card\u00edaca representa un alto riesgo quir\u00fargico y perioperatorio, por ello, se requiere de una monitorizaci\u00f3n precisa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/CIRUGIA-CARDIACA-PORTADA.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/CIRUGIA-CARDIACA-PORTADA.jpg\",\"width\":1024,\"height\":512,\"caption\":\"monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/monitorizacion-hemodinamica-cirugia-cardiaca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/\",\"name\":\"Campus Vygon Chile\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/75f06ca9d47ad2da0ff801057b0588fe\",\"name\":\"Campus Vygon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g\",\"caption\":\"Campus Vygon\"},\"description\":\"A place to learn about\u00a0health procedures\u00a0and techniques from\u00a0leading professionals.\",\"sameAs\":[\"https:\\\/\\\/www.vygon.es\\\/\",\"Array\",\"https:\\\/\\\/www.instagram.com\\\/vygonespana\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vygon-espaa\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/vygon_es\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/VygonSpain\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/author\\\/vygon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca - Campus Vygon Chile","description":"La cirug\u00eda card\u00edaca representa un alto riesgo quir\u00fargico y perioperatorio, por ello, se requiere de una monitorizaci\u00f3n precisa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/","og_locale":"es_ES","og_type":"article","og_title":"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca - Campus Vygon Chile","og_description":"La cirug\u00eda card\u00edaca representa un alto riesgo quir\u00fargico y perioperatorio, por ello, se requiere de una monitorizaci\u00f3n precisa.","og_url":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/","og_site_name":"Campus Vygon Chile","article_author":"Array","article_published_time":"2022-02-14T23:15:00+00:00","article_modified_time":"2022-02-15T11:00:46+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/CIRUGIA-CARDIACA-PORTADA.jpg","type":"image\/jpeg"}],"author":"Campus Vygon","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/vygon_es","twitter_misc":{"Escrito por":"Campus Vygon","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/"},"author":{"name":"Campus Vygon","@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/75f06ca9d47ad2da0ff801057b0588fe"},"headline":"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca","datePublished":"2022-02-14T23:15:00+00:00","dateModified":"2022-02-15T11:00:46+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/"},"wordCount":2650,"commentCount":0,"image":{"@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/CIRUGIA-CARDIACA-PORTADA.jpg","keywords":["cirug\u00eda card\u00edaca","Monitorizaci\u00f3n hemodin\u00e1mica"],"articleSection":["Anestesia y Cuidados Intensivos","Art\u00edculos","Cuidados Intensivos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/","url":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/","name":"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca - Campus Vygon Chile","isPartOf":{"@id":"https:\/\/campusvygon.com\/cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/CIRUGIA-CARDIACA-PORTADA.jpg","datePublished":"2022-02-14T23:15:00+00:00","dateModified":"2022-02-15T11:00:46+00:00","author":{"@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/75f06ca9d47ad2da0ff801057b0588fe"},"description":"La cirug\u00eda card\u00edaca representa un alto riesgo quir\u00fargico y perioperatorio, por ello, se requiere de una monitorizaci\u00f3n precisa.","breadcrumb":{"@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/#primaryimage","url":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/CIRUGIA-CARDIACA-PORTADA.jpg","contentUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2022\/02\/CIRUGIA-CARDIACA-PORTADA.jpg","width":1024,"height":512,"caption":"monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca"},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/cl\/monitorizacion-hemodinamica-cirugia-cardiaca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/cl\/"},{"@type":"ListItem","position":2,"name":"Monitorizaci\u00f3n hemodin\u00e1mica en cirug\u00eda card\u00edaca"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/cl\/#website","url":"https:\/\/campusvygon.com\/cl\/","name":"Campus Vygon Chile","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/75f06ca9d47ad2da0ff801057b0588fe","name":"Campus Vygon","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4c1c9a88bb2c005fcd0de077a296cfc37a425cbeddf6e461cc8ed707cd90d1d?s=96&d=mm&r=g","caption":"Campus Vygon"},"description":"A place to learn about\u00a0health procedures\u00a0and techniques from\u00a0leading professionals.","sameAs":["https:\/\/www.vygon.es\/","Array","https:\/\/www.instagram.com\/vygonespana\/","https:\/\/www.linkedin.com\/company\/vygon-espaa","https:\/\/x.com\/https:\/\/twitter.com\/vygon_es","https:\/\/www.youtube.com\/user\/VygonSpain"],"url":"https:\/\/campusvygon.com\/cl\/author\/vygon\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/31087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/comments?post=31087"}],"version-history":[{"count":7,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/31087\/revisions"}],"predecessor-version":[{"id":31145,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/31087\/revisions\/31145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/media\/31092"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/media?parent=31087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/categories?post=31087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/tags?post=31087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}