{"id":8171,"date":"2020-05-07T17:28:29","date_gmt":"2020-05-07T15:28:29","guid":{"rendered":"http:\/\/campusvygon.com\/cl\/?p=8171"},"modified":"2020-05-07T17:28:29","modified_gmt":"2020-05-07T15:28:29","slug":"entrevista-escriba-protocolo-eras","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/","title":{"rendered":"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1"},"content":{"rendered":"<p>El Dr. Paco Escrib\u00e1 trabaja como anestesi\u00f3logo en el Hospital Universitari i Polit\u00e8cnic La Fe. Entre los muchos proyectos en los que participa, encabeza el nuevo protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica en su hospital.<\/p>\n<p>Un proyecto novedoso que busca dar soporte a los pacientes oncol\u00f3gicos en nutrici\u00f3n, preparaci\u00f3n f\u00edsica y apoyo psicol\u00f3gico, con fin de acortar y mejorar el tiempo de recuperaci\u00f3n.<\/p>\n<p>En esta entrevista hablamos sobre este protocolo y temas relacionados con una buena gesti\u00f3n de las tres fases por las que pasa el paciente: preoperatorio, intraoperatorio y postoperatorio.<\/p>\n<p>Puedes ver la entrevista completa\u00a0este <a href=\"https:\/\/youtu.be\/OGzI4vHUNk8\">enlace<\/a>.<\/p>\n<p><iframe loading=\"lazy\" title=\"Protocolos ERAS, anestesiolog\u00eda pedi\u00e1trica. Dr.  Paco Escrib\u00e1\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/OGzI4vHUNk8?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Los <strong>protocolos ERAS<\/strong> (Enhanced Recovery After Surgery) tiene su origen en la d\u00e9cada de los 90, cuando dos grupos de investigadores presentaron diferentes propuestas con el fin de mejorar la evoluci\u00f3n postoperatoria de los pacientes intervenidos en una cirug\u00eda.<\/p>\n<p>La implementaci\u00f3n de estos protocolos permite disminuir los tiempos de hospitalizaci\u00f3n y de recuperaci\u00f3n, as\u00ed como posibles complicaciones y costes derivados de una recuperaci\u00f3n m\u00e1s prolongada.<\/p>\n<blockquote><p>Persiguen una amalgama de maniobras y de gestos, como un checklist, que se hace sobre el paciente, tanto en el preoperatorio, como intraoperatorio y postoperatorio que parte de la medicina basal en la evidencia, y con fuertes recomendaciones de grupos de expertos. Trata de conseguir la mejor recuperaci\u00f3n del paciente, disminuir las complicaciones mayores y menores, y disminuir los tiempos de ingreso<\/p><\/blockquote>\n<p>El Dr. Escrib\u00e1 tambi\u00e9n nos habla de la <strong>prehabilitaci\u00f3n<\/strong>, un nuevo enfoque en el manejo preoperatorio de los pacientes quir\u00fargicos que ha demostrado una mejor\u00eda en la recuperaci\u00f3n de estos.<\/p>\n<p>A pesar, de estar muy relacionada con los protocolos ERAS y estar incluida normalmente en estos proyectos, no son exactamente lo mismo.<\/p>\n<p>La prehabilitaci\u00f3n consiste en un acompa\u00f1amiento individualizado, adaptado a la capacidad funcional de cada paciente que incluye la realizaci\u00f3n de ejercicio f\u00edsico, nutrici\u00f3n adecuada y apoyo psicol\u00f3gico.<\/p>\n<blockquote><p>La prehabilitaci\u00f3n no es solo optimizar al paciente, consiste en estudiar su condici\u00f3n vital y hacer una serie de maniobras basadas en diferentes enfoques para mejorar su optimizaci\u00f3n desde el punto de vista de su salud, el paciente tiene que ser el luchador y el protagonista.<\/p>\n<p>El paciente tiene un rol activo, tiene cosas que hacer para llegar de la mejor manera posible a la intervenci\u00f3n, en este caso hay un <strong>empoderamiento importante del paciente<\/strong>.<\/p><\/blockquote>\n<p>A pesar de que ya exist\u00edan muchos proyectos con muy buenos resultados en adultos, en pediatr\u00eda todav\u00eda no se hab\u00eda adaptado ning\u00fan protocolo similar.<\/p>\n<p>Un d\u00eda, Aitana, antigua residente en el servicio de Anestesiolog\u00eda Pedi\u00e1trica del Hospital Universitari i Polit\u00e8cnic La Fe, laz\u00f3 una pregunta al Dr. Paco Escrib\u00e1 \u201c<em>\u00bfesto no se podr\u00eda adaptar tambi\u00e9n a pediatr\u00eda?<\/em>\u201d.<\/p>\n<p>Una pregunta que despert\u00f3 el inter\u00e9s del doctor y que le llev\u00f3 a seguir investigando. Hasta que encontr\u00f3 protocolos que se pod\u00edan adaptar a pediatr\u00eda.<\/p>\n<p>A partir de ah\u00ed construyeron un proyecto que permite:<\/p>\n<blockquote><p>Convertir a estos pacientes en h\u00e9roes, que se sientan importantes, protagonistas, como deportistas de \u00e9lite, con su preparador f\u00edsico, su nutricionista, su coach personal\u2026 y <strong>que vayan a jugar el partido de sus vidas en las mejores condiciones posibles<\/strong>.<\/p><\/blockquote>\n<p>Este proyecto est\u00e1 presente en todas las fases por las que pasa el paciente: preoperatorio, intraoperatorio y postoperatorio. Un tratamiento integral que permite una recuperaci\u00f3n mejor y m\u00e1s r\u00e1pida.<\/p>\n<p>Durante la entrevista hablamos de estas tres fases, teniendo la oportunidad de tratar temas t\u00e9cnicos como la <a href=\"http:\/\/campusvygon.com\/cl\/terapia-guiada-por-objetivos\/\"><strong>terapia guiada por objetivos<\/strong><\/a>, los <strong>par\u00e1metros hemodin\u00e1micos m\u00e1s habituales<\/strong>, as\u00ed como la importancia de medir en todo momento qu\u00e9 sucede en el organismo del paciente, controlando por ejemplo <strong>el \u00e1cido l\u00e1ctico<\/strong>, relacionado con el \u00edndice de supervivencia.<\/p>\n<p>Puedes ver aqu\u00ed la entrevista completa:<\/p>\n<p><iframe loading=\"lazy\" title=\"Protocolos ERAS, anestesiolog\u00eda pedi\u00e1trica. Dr.  Paco Escrib\u00e1\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/OGzI4vHUNk8?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Dr. Paco Escrib\u00e1 trabaja como anestesi\u00f3logo en el Hospital Universitari i Polit\u00e8cnic La Fe. Entre los muchos proyectos en los que participa, encabeza el nuevo protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica en su hospital. Un proyecto novedoso que busca dar soporte a los pacientes oncol\u00f3gicos en nutrici\u00f3n, preparaci\u00f3n f\u00edsica y apoyo psicol\u00f3gico, con fin de [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":8175,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[285,80,115,1],"tags":[],"class_list":["post-8171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anestesia-y-cuidados-intensivos","category-articulos","category-cuidados-intensivos","category-entrevistas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1 - Campus Vygon Chile<\/title>\n<meta name=\"description\" content=\"El Dr. Escrib\u00e1 encabeza del nuevo protocolo ERAS de anestesiolog\u00eda pedi\u00e1trica, el cual ofrece un programa de nutrici\u00f3n, preparaci\u00f3n f\u00edsica y psicol\u00f3gica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1 - Campus Vygon Chile\" \/>\n<meta property=\"og:description\" content=\"El Dr. Escrib\u00e1 encabeza del nuevo protocolo ERAS de anestesiolog\u00eda pedi\u00e1trica, el cual ofrece un programa de nutrici\u00f3n, preparaci\u00f3n f\u00edsica y psicol\u00f3gica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Chile\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-07T15:28:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/05\/PORTADAS-escrib\u00e1-1024x576.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roc\u00edo Peco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roc\u00edo Peco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/\"},\"author\":{\"name\":\"Roc\u00edo Peco\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/043ee941f716c145765baba57d1ee43a\"},\"headline\":\"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1\",\"datePublished\":\"2020-05-07T15:28:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/\"},\"wordCount\":682,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/PORTADAS-escrib\u00e1.png\",\"articleSection\":[\"Anestesia y Cuidados Intensivos\",\"Art\u00edculos\",\"Cuidados Intensivos\",\"Entrevistas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/\",\"name\":\"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1 - Campus Vygon Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/PORTADAS-escrib\u00e1.png\",\"datePublished\":\"2020-05-07T15:28:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/043ee941f716c145765baba57d1ee43a\"},\"description\":\"El Dr. Escrib\u00e1 encabeza del nuevo protocolo ERAS de anestesiolog\u00eda pedi\u00e1trica, el cual ofrece un programa de nutrici\u00f3n, preparaci\u00f3n f\u00edsica y psicol\u00f3gica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/PORTADAS-escrib\u00e1.png\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/PORTADAS-escrib\u00e1.png\",\"width\":1920,\"height\":1080,\"caption\":\"Dr. Escrib\u00e1 protocolos ERAS\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/entrevista-escriba-protocolo-eras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/\",\"name\":\"Campus Vygon Chile\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/#\\\/schema\\\/person\\\/043ee941f716c145765baba57d1ee43a\",\"name\":\"Roc\u00edo Peco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/945b0261bcb16fd7f25d68d8de52b48dd93878c2169172db32be1d268ec2155c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/945b0261bcb16fd7f25d68d8de52b48dd93878c2169172db32be1d268ec2155c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/945b0261bcb16fd7f25d68d8de52b48dd93878c2169172db32be1d268ec2155c?s=96&d=mm&r=g\",\"caption\":\"Roc\u00edo Peco\"},\"description\":\"Soy responsable de contenidos de las unidades de negocio Cuidados Intensivos y Anestesia y Emergencias. EXPERIENCIA Me form\u00e9 en comunicaci\u00f3n audiovisual y realizaci\u00f3n televisiva. Aunque arranqu\u00e9 mi carrera en programas y ficci\u00f3n, desde hace unos a\u00f1os me he centrado en la comunicaci\u00f3n y el marketing digital. PUEDO AYUDARTE EN... Mi trabajo se basa en una apuesta clara de Vygon por la formaci\u00f3n digital y el aprendizaje continuo. Puedes contactarme si buscas material digital sobre alg\u00fan procedimiento o t\u00e9cnica habitual en los servicios de Cuidados Intensivos o Anestesia, Urgencias, Emergencias.\",\"sameAs\":[\"https:\\\/\\\/www.vygon.es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/roc%C3%ADompeco-comunicaci%C3%B3n\\\/?originalSubdomain=es\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/cl\\\/author\\\/rpeco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1 - Campus Vygon Chile","description":"El Dr. Escrib\u00e1 encabeza del nuevo protocolo ERAS de anestesiolog\u00eda pedi\u00e1trica, el cual ofrece un programa de nutrici\u00f3n, preparaci\u00f3n f\u00edsica y psicol\u00f3gica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/","og_locale":"es_ES","og_type":"article","og_title":"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1 - Campus Vygon Chile","og_description":"El Dr. Escrib\u00e1 encabeza del nuevo protocolo ERAS de anestesiolog\u00eda pedi\u00e1trica, el cual ofrece un programa de nutrici\u00f3n, preparaci\u00f3n f\u00edsica y psicol\u00f3gica.","og_url":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/","og_site_name":"Campus Vygon Chile","article_published_time":"2020-05-07T15:28:29+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/05\/PORTADAS-escrib\u00e1-1024x576.png","type":"image\/png"}],"author":"Roc\u00edo Peco","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Roc\u00edo Peco","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/"},"author":{"name":"Roc\u00edo Peco","@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/043ee941f716c145765baba57d1ee43a"},"headline":"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1","datePublished":"2020-05-07T15:28:29+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/"},"wordCount":682,"commentCount":1,"image":{"@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/05\/PORTADAS-escrib\u00e1.png","articleSection":["Anestesia y Cuidados Intensivos","Art\u00edculos","Cuidados Intensivos","Entrevistas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/","url":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/","name":"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1 - Campus Vygon Chile","isPartOf":{"@id":"https:\/\/campusvygon.com\/cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/05\/PORTADAS-escrib\u00e1.png","datePublished":"2020-05-07T15:28:29+00:00","author":{"@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/043ee941f716c145765baba57d1ee43a"},"description":"El Dr. Escrib\u00e1 encabeza del nuevo protocolo ERAS de anestesiolog\u00eda pedi\u00e1trica, el cual ofrece un programa de nutrici\u00f3n, preparaci\u00f3n f\u00edsica y psicol\u00f3gica.","breadcrumb":{"@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/#primaryimage","url":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/05\/PORTADAS-escrib\u00e1.png","contentUrl":"https:\/\/campusvygon.com\/cl\/wp-content\/uploads\/sites\/2\/2020\/05\/PORTADAS-escrib\u00e1.png","width":1920,"height":1080,"caption":"Dr. Escrib\u00e1 protocolos ERAS"},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/cl\/entrevista-escriba-protocolo-eras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/cl\/"},{"@type":"ListItem","position":2,"name":"Protocolo ERAS en anestesiolog\u00eda pedi\u00e1trica. Entrevista al Dr. Paco Escrib\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/cl\/#website","url":"https:\/\/campusvygon.com\/cl\/","name":"Campus Vygon Chile","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/cl\/#\/schema\/person\/043ee941f716c145765baba57d1ee43a","name":"Roc\u00edo Peco","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/945b0261bcb16fd7f25d68d8de52b48dd93878c2169172db32be1d268ec2155c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/945b0261bcb16fd7f25d68d8de52b48dd93878c2169172db32be1d268ec2155c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/945b0261bcb16fd7f25d68d8de52b48dd93878c2169172db32be1d268ec2155c?s=96&d=mm&r=g","caption":"Roc\u00edo Peco"},"description":"Soy responsable de contenidos de las unidades de negocio Cuidados Intensivos y Anestesia y Emergencias. EXPERIENCIA Me form\u00e9 en comunicaci\u00f3n audiovisual y realizaci\u00f3n televisiva. Aunque arranqu\u00e9 mi carrera en programas y ficci\u00f3n, desde hace unos a\u00f1os me he centrado en la comunicaci\u00f3n y el marketing digital. PUEDO AYUDARTE EN... Mi trabajo se basa en una apuesta clara de Vygon por la formaci\u00f3n digital y el aprendizaje continuo. Puedes contactarme si buscas material digital sobre alg\u00fan procedimiento o t\u00e9cnica habitual en los servicios de Cuidados Intensivos o Anestesia, Urgencias, Emergencias.","sameAs":["https:\/\/www.vygon.es\/","https:\/\/www.linkedin.com\/in\/roc%C3%ADompeco-comunicaci%C3%B3n\/?originalSubdomain=es"],"url":"https:\/\/campusvygon.com\/cl\/author\/rpeco\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/8171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/comments?post=8171"}],"version-history":[{"count":6,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/8171\/revisions"}],"predecessor-version":[{"id":8179,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/posts\/8171\/revisions\/8179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/media\/8175"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/media?parent=8171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/categories?post=8171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/cl\/wp-json\/wp\/v2\/tags?post=8171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}