{"id":15455,"date":"2021-01-21T08:43:07","date_gmt":"2021-01-21T07:43:07","guid":{"rendered":"http:\/\/campusvygon.com\/es\/?p=15455"},"modified":"2025-09-26T12:17:09","modified_gmt":"2025-09-26T10:17:09","slug":"jeringa-ldt-sobredosis","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/","title":{"rendered":"\u00bfPor qu\u00e9 la jeringa de bajo volumen (LDT) NO elimina los riesgos de sobredosis en neonatos?"},"content":{"rendered":"\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size has-small-font-size\"><a class=\"wp-block-button__link\" href=\"http:\/\/campusvygon.com\/es\/project\/whitepaper-por-que-la-jeringa-de-bajo-volumen-ldt-no-elimina-los-riesgos-de-sobredosis-en-neonato\" target=\"_blank\" rel=\"noreferrer noopener\">Descarga en pdf<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n\n<p class=\"wp-block-paragraph\">Debido a las dudas planteadas en el uso de la jeringa LDT (Low Dose Tip) en la poblaci\u00f3n neonatal, la Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n corrigi\u00f3 el pasado mes de marzo&nbsp;la <strong>norma ISO 20695 para&nbsp;<em>eliminar&nbsp;la jeringa LDT de los&nbsp;requisitos&nbsp;normativos al no demostrarse su capacidad&nbsp;de aumentar&nbsp;la precisi\u00f3n de la dosis<sup>1<\/sup><\/em><\/strong><em>.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1les han sido los motivos que le han llevado realizar esta correcci\u00f3n? Resolvemos las inc\u00f3gnitas en este art\u00edculo.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/formacion.campusvygon.com\/es\/cursos\/curso-pendiente-de-acreditacion---nutricion-enteral-segura-en-neonatos-86?edicion=101&amp;tab=info\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/12\/twitter-facebook-2.jpg\" alt=\"Curso: Nutrici\u00f3n enteral seguro en neonatos\" class=\"wp-image-31559\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/12\/twitter-facebook-2.jpg 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/12\/twitter-facebook-2-980x490.jpg 980w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/12\/twitter-facebook-2-480x240.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>El riesgo de sobredosis en neonatos<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los<strong> prematuros y reci\u00e9n nacidos enfermos <\/strong>son probablemente el grupo pedi\u00e1trico de pacientes m\u00e1s importante en la que<strong> se administra la nutrici\u00f3n con sondas enterales<\/strong>. Diariamente se administran dosis muy peque\u00f1as de f\u00e1rmacos a pacientes neonatales en las UCIN. <strong><a href=\"http:\/\/campusvygon.com\/es\/dosis-neonatologia\/\">Una dosis incorrecta<\/a> de muchos medicamentos administrados por v\u00eda enteral puede ser perjudicial para la salud del paciente<\/strong>&nbsp; ya que puede provocar da\u00f1os irreparables en su salud, incluso llegando a causar la muerte de estos peque\u00f1os pacientes<sup>2<\/sup><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los profesionales del campo de la neonatolog\u00eda est\u00e1n preocupados por la necesidad de asegurar que la dosis administrada a este tipo de pacientes sea lo m\u00e1s exacta posible<sup>3,4<\/sup><\/strong> debido a la falta de informaci\u00f3n existente sobre como el exceso de peque\u00f1as dosis puede afectar a la salud de este a largo plazo.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"http:\/\/campusvygon.com\/es\/6-razones-no-enfit-neonatos\/dosis-medicamento\/\" rel=\"attachment wp-att-12843\"><img loading=\"lazy\" decoding=\"async\" width=\"2760\" height=\"2221\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento.png\" alt=\"Multiplicaci\u00f3n de la dosis con ENFit\" class=\"wp-image-12843\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento.png 2760w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento-300x241.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento-1024x824.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento-768x618.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento-1536x1236.png 1536w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento-2048x1648.png 2048w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento-1080x869.png 1080w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento-116x92.png 116w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/09\/Dosis-medicamento-335x270.png 335w\" sizes=\"(max-width: 2760px) 100vw, 2760px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La Organizaci\u00f3n Internacional de Estandarizaci\u00f3n (ISO) en el Anexo E de la ISO 80369-3 \u2013norma global de regulaci\u00f3n de un dise\u00f1o \u00fanico y seguro en dispositivos de nutrici\u00f3n enteral-, hace referencia a esta preocupaci\u00f3n<sup>5<\/sup>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>\u201cEn un reci\u00e9n nacido de 500 g, a menudo se prescriben f\u00e1rmacos enterales en vol\u00famenes de apenas 0,1 ml o incluso 0,01 ml.\u201d<\/strong><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Por este motivo, para la nutrici\u00f3n enteral, La ISO desarroll\u00f3 una serie de normas entre las que recomendaba el uso de la jeringa de bajo volumen (LDT) para precisi\u00f3n en vol\u00famenes muy peque\u00f1os (Low Dose Trip).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfJeringa LDT una soluci\u00f3n a la sobredosis?<\/strong><\/h3>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1.png\" rel=\"attachment wp-att-15456\"><img loading=\"lazy\" decoding=\"async\" width=\"4500\" height=\"4500\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1.png\" alt=\"Sobredosis acumulada en el cono de la jeringa\" class=\"wp-image-15456\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1.png 4500w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-300x300.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-1024x1024.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-150x150.png 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-768x768.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-1536x1536.png 1536w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-2048x2048.png 2048w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-1080x1080.png 1080w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-70x70.png 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-335x335.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Sobredosis-jeringas_Mesa-de-trabajo-1-360x360.png 360w\" sizes=\"(max-width: 4500px) 100vw, 4500px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los <strong>especialistas en neonatolog\u00eda<\/strong> consideraban <strong>que el dise\u00f1o del conector ENFit proporcionaba una precisi\u00f3n de dosis insuficiente para un uso universal en neonatolog\u00eda<\/strong>. &nbsp;Una opini\u00f3n que qued\u00f3 recogida en un estudio sobre la precisi\u00f3n de la jeringa y el impacto de los conectores ENFIT en las UCIN (Unidad de Cuidados Intensivos Neonata) de 2014 <sup>3<\/sup> .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, tambi\u00e9n, lo reconoc\u00eda la propia Organizaci\u00f3n en el Anexo A de la norma ISO 80369-3<sup>5<\/sup>:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cHan surgido <strong>inquietudes sobre los posibles riesgos de administraci\u00f3n de dosis inexactas de medicamentos en determinadas pr\u00e1cticas cl\u00ednicas de subpoblaciones de alto riesgo<\/strong> (p. ej. pacientes neonatales) si se utiliza un sistema de conexi\u00f3n inversa (hembra macho). Los ensayos de laboratorio revelan que un par de conectores de tolerancia media en una orientaci\u00f3n hembra-macho desplaza una media de 0,148 ml (m\u00ednimo de 0,089ml y m\u00e1ximo de 0,179 con n=32) de l\u00edquido\u201d.<\/p><\/blockquote>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>jeringa LDT fue una de las soluciones aportadas ISO para responder a los problemas de sobredosificaci\u00f3n<\/strong> del nuevo modelo \u00fanico de conexi\u00f3n de nutrici\u00f3n enteral ENFit.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Art\u00edculos relacionados<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li><a href=\"http:\/\/campusvygon.com\/es\/iso-803693-enfit-nutricion-enteral\/\">Nutrici\u00f3n Enteral: de la preocupaci\u00f3n a la norma ISO 80369-3, ENFit<\/a><\/li><li><a href=\"http:\/\/campusvygon.com\/es\/enfit-no-seguro-neonatos\/\">Enfit un sistema incompatible con la seguridad neonatal<\/a><\/li><\/ol>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Con este dise\u00f1o se pretend\u00eda acabar con los problemas de sobredosis que se hab\u00edan observado en la administraci\u00f3n de f\u00e1rmacos y otros fluidos en pacientes. &nbsp;Sin embargo, <strong>su aplicaci\u00f3n en pacientes de alto riesgo provoc\u00f3 un debate sobre la precisi\u00f3n del dispositivo entre los profesionales del mundo sanitario<sup>3,6,7<\/sup>. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jeringa LDT fue puesta a prueba por expertos cl\u00ednicos para comprobar su precisi\u00f3n y fiabilidad. <strong>Los ensayos demostraron que la jeringa LDT no presentaba diferencias en la pr\u00e1ctica de administraci\u00f3n de fluidos viscosos respecto a las jeringas macho existentes en los mercados<sup>1,8.<\/sup><\/strong><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Overdosing risk with Low Dose Tip syringe\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/ZGGM9DQvbTI?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Cambio en los protocolos de administraci\u00f3n de NE<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, los resultados apuntaron que el nuevo dise\u00f1o de dispositivos de nutrici\u00f3n enteral de ENFit alcanzaba unos un nivel de precisi\u00f3n de +\/- 10, siempre y cuando<strong>, se utilizase siguiendo el manual de instrucciones del fabricante, para asegurar<\/strong>, que el l\u00edquido que quedaba en el cono de la jeringa fuese eliminado<sup>8.9,10<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta matizaci\u00f3n en el uso de la jeringa, sin embargo, significar\u00eda una alteraci\u00f3n del modo de empleo habitual&nbsp;que, no solo incrementar\u00eda el tiempo destinado al procedimiento,&nbsp;tambi\u00e9n&nbsp;los profesionales sanitarios podr\u00edan no&nbsp;conocerlo&nbsp;u olvidarlo.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"http:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/enfti-vs-nutrisafe_mesa-de-trabajo-1\/\" rel=\"attachment wp-att-15480\"><img loading=\"lazy\" decoding=\"async\" width=\"1811\" height=\"2560\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-scaled.jpg\" alt=\"Inquietudes jeringa LDT\" class=\"wp-image-15480\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-scaled.jpg 1811w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-212x300.jpg 212w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-724x1024.jpg 724w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-768x1086.jpg 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-1086x1536.jpg 1086w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-1448x2048.jpg 1448w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-1080x1527.jpg 1080w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/01\/Enfti-vs-nutrisafe_Mesa-de-trabajo-1-237x335.jpg 237w\" sizes=\"(max-width: 1811px) 100vw, 1811px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, como para todo dispositivo m\u00e9dico nuevo, la jeringa LDT debe pasar una evaluaci\u00f3n exhaustiva del riesgo en las que asegure que, siguiendo las instrucciones del fabricante, se den las condiciones de seguridad del uso de esta jeringa. La jeringa LDT, sin embargo, tampoco pasa con \u00e9xito estas evaluaciones, por lo que entra en conflicto, tambi\u00e9n, la norma ISO 14971.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Estudios sobre la precisi\u00f3n de la jeringa LDT<sup>8<\/sup><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa ANDEHO, una compa\u00f1\u00eda especializada en ingenier\u00eda para la Concepci\u00f3n de Simulaciones realiz\u00f3 un experimento, a trav\u00e9s un modelo 3D, con la jeringa LDT de simulaci\u00f3n de desplazamiento de l\u00edquidos utilizando el m\u00e9todo Lattice-Boltzman, que se basa en el estudio de las leyes de comportamiento de las part\u00edculas. El objetivo de dicho estudio era <strong>conocer la seguridad y precisi\u00f3n de las jeringas LDT cuando se utiliza el procedimiento convencional de administraci\u00f3n de sustancias<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ensayo de laboratorio revel\u00f3 que la sobredosificaci\u00f3n con la jeringa LDT es posible si hay l\u00edquido presente en el pabell\u00f3n\/barril del dispositivo.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Puede administrarse una sobredosis de 0,120 ml<\/strong> en caso de presencia de l\u00edquido en el cono de la jeringa LDT.<\/li><li><strong>El exceso de dosis puede aumentar hasta 0,153 ml <\/strong>en algunos casos.<\/li><li>No existe fuga a las roscas del conector ENFit macho durante la conexi\u00f3n. En las diferentes configuraciones posibles todo <strong>el l\u00edquido se desplaza hacia el tubo de alimentaci\u00f3n. <\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo tanto, este estudio, llegaba a la conclusi\u00f3n de que la <strong>jeringa LDT no eliminaba el riesgo de sobredosis en el caso de seguir el protocolo convencional actual<\/strong>. El riesgo era al uso de una jeringa ENFit convencional, por lo que la jeringa de bajo volumen no pod\u00eda considerarse una alternativa para la administraci\u00f3n de dosis en peque\u00f1o volumen<sup>11<\/sup>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La norma ISO 20695<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la demostraci\u00f3n de la posibilidad de que se produzcan errores de sobredosis en caso de que quede fluido en el cono de la conexi\u00f3n de la jeringa LDT y la confirmaci\u00f3n por parte de las simulaciones num\u00e9ricas de que la sobredosis de esta nueva jeringa es similar a la de la jeringa ENfit est\u00e1ndar, <strong>la norma ISO 20695<\/strong> sobre los requisitos de los dispositivos de nutrici\u00f3n enteral tuvo que <strong>actualizarse<\/strong> el pasado mes de marzo<sup>1<\/sup>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el ap\u00e9ndice K, relativo a la jeringa de bajo volumen, la ISO recoge que<sup>1,12<\/sup>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La <strong>jeringa LDT<\/strong> <strong>es eliminada de los requisitos normativos<\/strong> (obligatorios) y ahora s\u00f3lo se incluye con dines informativos<\/li><li>La <strong>jeringa LDT pasa a llamarse \u201cpunta de jeringa enteral alternativa\u201d<\/strong> porque no puede asegurar la precisi\u00f3n de una dosis baja<\/li><li>No se ha llegado <strong>a ning\u00fan consenso sobre la capacidad de la punta de jeringa alternativa para aumentar de forma fiable la precisi\u00f3n de la dosis.<\/strong><\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Art\u00edculo de inter\u00e9s <a href=\"http:\/\/campusvygon.com\/es\/6-razones-no-enfit-neonatos\/\">6 razones por las que no utilizar ENFit en neonatos<\/a><\/p><\/blockquote>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La elecci\u00f3n de estos dispositivos, pues, no es la m\u00e1s indicada si existe una preocupaci\u00f3n por la sobredosis ante pacientes vulnerables. <strong><a href=\"https:\/\/www.vygon.es\/productos\/jeringas-transparentes_1340_001015002\">Los profesionales sanitarios deben elegir una jeringa que garantice una verdadera seguridad para los pacientes neonatales ingresados en la UCIN. <\/a><\/strong><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Te puede interesar\u2026<a href=\"https:\/\/www.safe-enteral.com\/es\/\">safe-enteral.com <\/a> en ella encontrar\u00e1s toda la informaci\u00f3n relacionada con la ISO-20695, as\u00ed las inquietudes de los profesionales sobre la importancia de la dosis, las caracter\u00edsticas de un conector seguro en nutrici\u00f3n enteral para neonatos y, otra informaci\u00f3n imprescindible, para saber TODO lo que necesitas de ENFit.<\/p><\/blockquote>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Bibliograf\u00eda<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li><em>ISO 20695 And The \u00ab Low Dose Tip \u00bb Syringe<\/em>. [ebook] Ecouen. Disponible en: &lt;<a href=\"https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2020\/11\/iso-20695-and-low-dose-tip-_2020.07.pdf\">https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2020\/11\/iso-20695-and-low-dose-tip-_2020.07.pdf<\/a>&gt; [Acceso 19 enero 2021].<\/li><li>\u00ad2014.&nbsp;<em>Estudio Neonatal Sobre Los Posibles Impactos Del Conector Enfittm En La Precisi\u00f3n De La Jeringa<\/em>. [PDF] Disponible en: &lt;<a href=\"https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2017\/09\/abstract_potential-impact-of-enfit-on-syringe-accuracy_es.pdf\">https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2017\/09\/abstract_potential-impact-of-enfit-on-syringe-accuracy_es.pdf<\/a>&gt; [Acceso 17 enero 2021].<\/li><li>Safe Enteral. 2021.&nbsp;<em>Inquietudes &#8211; Safe Enteral<\/em>. [online] Disponible en: &lt;<a href=\"https:\/\/www.safe-enteral.com\/es\/low-dose-concerns\/\">https:\/\/www.safe-enteral.com\/es\/low-dose-concerns\/<\/a>&gt; [Acceso 17 enero 2021].<\/li><li>Chassin, M. and Pujols-McKee, A., 2021. [PDF] Coalici\u00f3n Estadounidense de Salud Infantil (NCfIH). Disponible en: &lt;<a href=\"https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2019\/01\/08-es-10.4.17-jc-ncfih-tubing-carta.pdf\">https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2019\/01\/08-es-10.4.17-jc-ncfih-tubing-carta.pdf<\/a>&gt; [Acceso 19 enero 2021].<\/li><li>Safe Enteral. 2021.&nbsp;<em>ISO 80369 Content<\/em>. [online] Disponible: &lt;<a href=\"https:\/\/www.safe-enteral.com\/es\/content\/\">https:\/\/www.safe-enteral.com\/es\/content\/<\/a>&gt; [Acceso 16 January 2021].<\/li><li>Saliba, E., 2016. &gt; Nouveau raccord de nutrition ent\u00e9rale de la norme ISO 80369-3 : un syst\u00e8me pr\u00e9sentant un risque r\u00e9el chez les pr\u00e9matur\u00e9s et les jeunes enfants.&nbsp;<em>Soceidad Francesa de Neonatolog\u00eda<\/em>, [online] (7). Disponible en: &lt;<a href=\"https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2017\/01\/newsletter_sfn_mars2016_fr.pdf\">https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2017\/01\/newsletter_sfn_mars2016_fr.pdf<\/a>&gt; [Acceso 15 enero 2021].<\/li><li>Castro, G., 2017. [PDF] The Joint Commission. Disponible en: &lt;<a href=\"https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2019\/01\/10-ncfih-11.10.17-respuesta.pdf\">https:\/\/www.safe-enteral.com\/wp-content\/uploads\/sites\/7\/2019\/01\/10-ncfih-11.10.17-respuesta.pdf<\/a>&gt; [Acceso 17 enero 2021].<\/li><li>An\u00e1lisis \u00abthe report GEDSA Low Dose Syringe Accuracy test, 31 de Enero 2016, by SMTL\u00bb \u2013 SELECT Report \u2013 Revisado el :22 de Septiembre de 2020.<\/li><li>ISO 20695:2020 Enteral feeding systems \u2014 Design and testing. (2020). Revisado 22 Septiembre 2020, en <a href=\"https:\/\/www.une.org\/encuentra-tu-norma\/busca-tu-norma\/iso?c=068853\">https:\/\/www.une.org\/encuentra-tu-norma\/busca-tu-norma\/iso?c=068853<\/a><\/li><li>Espacio muerto y volumen desplazado del conector [ENFit] ISO 80369-3:2016 de Solidworks, Vygon<\/li><li>Safe Enteral. 2021.&nbsp;<em>ISO 20695 &#8211; Safe Enteral<\/em>. [online] Disponible en: &lt;<a href=\"https:\/\/www.safe-enteral.com\/es\/iso-20695\/\">https:\/\/www.safe-enteral.com\/es\/iso-20695\/<\/a>&gt; Acceso18 Enero 2021.<\/li><\/ol>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a las dudas planteadas en el uso de la jeringa LDT (Low Dose Tip) en la poblaci\u00f3n neonatal, la Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n corrigi\u00f3 el pasado mes de marzo&nbsp;la norma ISO 20695 para&nbsp;eliminar&nbsp;la jeringa LDT de los&nbsp;requisitos&nbsp;normativos al no demostrarse su capacidad&nbsp;de aumentar&nbsp;la precisi\u00f3n de la dosis1.&nbsp; \u00bfCu\u00e1les han sido los motivos que [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":47782,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[286,510],"tags":[468,108,87,460],"class_list":["post-15455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neonatologia","category-nutrisafe","tag-jeringa-ldt","tag-neonatos","tag-nutricion-enteral","tag-sobredosis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 la jeringa LDT NO elimina el riesgo de sobredosis en neonatos?<\/title>\n<meta name=\"description\" content=\"Debido a las dudas sobre la jeringa LDT, la Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n corrigi\u00f3 la norma ISO 20695 para\u00a0eliminarla de los\u00a0requisitos\u00a0normativos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 la jeringa LDT NO elimina el riesgo de sobredosis en neonatos?\" \/>\n<meta property=\"og:description\" content=\"Debido a las dudas sobre la jeringa LDT, la Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n corrigi\u00f3 la norma ISO 20695 para\u00a0eliminarla de los\u00a0requisitos\u00a0normativos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-21T07:43:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-26T10:17:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sobredosis-neonatos-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hiba Malek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hiba Malek\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/\"},\"author\":{\"name\":\"Hiba Malek\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/00232c1410da1c96291ba4ad132d92a3\"},\"headline\":\"\u00bfPor qu\u00e9 la jeringa de bajo volumen (LDT) NO elimina los riesgos de sobredosis en neonatos?\",\"datePublished\":\"2021-01-21T07:43:07+00:00\",\"dateModified\":\"2025-09-26T10:17:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/\"},\"wordCount\":1667,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-sobredosis-neonatos-scaled.jpeg\",\"keywords\":[\"jeringa LDT\",\"neonatos\",\"nutrici\u00f3n enteral\",\"sobredosis\"],\"articleSection\":[\"Neonatolog\u00eda\",\"Nutrisafe\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/\",\"name\":\"\u00bfPor qu\u00e9 la jeringa LDT NO elimina el riesgo de sobredosis en neonatos?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-sobredosis-neonatos-scaled.jpeg\",\"datePublished\":\"2021-01-21T07:43:07+00:00\",\"dateModified\":\"2025-09-26T10:17:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/00232c1410da1c96291ba4ad132d92a3\"},\"description\":\"Debido a las dudas sobre la jeringa LDT, la Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n corrigi\u00f3 la norma ISO 20695 para\u00a0eliminarla de los\u00a0requisitos\u00a0normativos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-sobredosis-neonatos-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-sobredosis-neonatos-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\".\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/jeringa-ldt-sobredosis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 la jeringa de bajo volumen (LDT) NO elimina los riesgos de sobredosis en neonatos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/00232c1410da1c96291ba4ad132d92a3\",\"name\":\"Hiba Malek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fa83b1d1e4f568dc8843e832b1c3b10170aaf8419baf09e1eb5f1533635bb05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fa83b1d1e4f568dc8843e832b1c3b10170aaf8419baf09e1eb5f1533635bb05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fa83b1d1e4f568dc8843e832b1c3b10170aaf8419baf09e1eb5f1533635bb05?s=96&d=mm&r=g\",\"caption\":\"Hiba Malek\"},\"description\":\"Responsable de las Unidades de Negocio de Terapias Intravasculares - Obstetricia, Neonatolog\u00eda y Nutrici\u00f3n Enteral - Vygon Espa\u00f1a\",\"sameAs\":[\"https:\\\/\\\/www.vygon.es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/hiba-malek-b7b4655a\\\/\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/author\\\/hmalek\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 la jeringa LDT NO elimina el riesgo de sobredosis en neonatos?","description":"Debido a las dudas sobre la jeringa LDT, la Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n corrigi\u00f3 la norma ISO 20695 para\u00a0eliminarla de los\u00a0requisitos\u00a0normativos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 la jeringa LDT NO elimina el riesgo de sobredosis en neonatos?","og_description":"Debido a las dudas sobre la jeringa LDT, la Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n corrigi\u00f3 la norma ISO 20695 para\u00a0eliminarla de los\u00a0requisitos\u00a0normativos","og_url":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/","og_site_name":"Campus Vygon Espa\u00f1a","article_published_time":"2021-01-21T07:43:07+00:00","article_modified_time":"2025-09-26T10:17:09+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sobredosis-neonatos-scaled.jpeg","type":"image\/jpeg"}],"author":"Hiba Malek","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Hiba Malek","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/"},"author":{"name":"Hiba Malek","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/00232c1410da1c96291ba4ad132d92a3"},"headline":"\u00bfPor qu\u00e9 la jeringa de bajo volumen (LDT) NO elimina los riesgos de sobredosis en neonatos?","datePublished":"2021-01-21T07:43:07+00:00","dateModified":"2025-09-26T10:17:09+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/"},"wordCount":1667,"commentCount":5,"image":{"@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sobredosis-neonatos-scaled.jpeg","keywords":["jeringa LDT","neonatos","nutrici\u00f3n enteral","sobredosis"],"articleSection":["Neonatolog\u00eda","Nutrisafe"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/","url":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/","name":"\u00bfPor qu\u00e9 la jeringa LDT NO elimina el riesgo de sobredosis en neonatos?","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sobredosis-neonatos-scaled.jpeg","datePublished":"2021-01-21T07:43:07+00:00","dateModified":"2025-09-26T10:17:09+00:00","author":{"@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/00232c1410da1c96291ba4ad132d92a3"},"description":"Debido a las dudas sobre la jeringa LDT, la Organizaci\u00f3n Internacional para la Estandarizaci\u00f3n corrigi\u00f3 la norma ISO 20695 para\u00a0eliminarla de los\u00a0requisitos\u00a0normativos","breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sobredosis-neonatos-scaled.jpeg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sobredosis-neonatos-scaled.jpeg","width":2560,"height":1707,"caption":"."},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/jeringa-ldt-sobredosis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 la jeringa de bajo volumen (LDT) NO elimina los riesgos de sobredosis en neonatos?"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/00232c1410da1c96291ba4ad132d92a3","name":"Hiba Malek","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2fa83b1d1e4f568dc8843e832b1c3b10170aaf8419baf09e1eb5f1533635bb05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fa83b1d1e4f568dc8843e832b1c3b10170aaf8419baf09e1eb5f1533635bb05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fa83b1d1e4f568dc8843e832b1c3b10170aaf8419baf09e1eb5f1533635bb05?s=96&d=mm&r=g","caption":"Hiba Malek"},"description":"Responsable de las Unidades de Negocio de Terapias Intravasculares - Obstetricia, Neonatolog\u00eda y Nutrici\u00f3n Enteral - Vygon Espa\u00f1a","sameAs":["https:\/\/www.vygon.es\/","https:\/\/www.linkedin.com\/in\/hiba-malek-b7b4655a\/"],"url":"https:\/\/campusvygon.com\/es\/author\/hmalek\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/15455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=15455"}],"version-history":[{"count":17,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/15455\/revisions"}],"predecessor-version":[{"id":47785,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/15455\/revisions\/47785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/47782"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=15455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/categories?post=15455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/tags?post=15455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}