{"id":18751,"date":"2021-03-31T17:27:20","date_gmt":"2021-03-31T15:27:20","guid":{"rendered":"http:\/\/campusvygon.com\/es\/?p=18751"},"modified":"2022-07-20T09:49:01","modified_gmt":"2022-07-20T07:49:01","slug":"mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/","title":{"rendered":"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular?"},"content":{"rendered":"\n<p>En esta mesa redonda, Maite Parejo, Vicky Armenteros y Vicky Solaz expertas en acceso vascular y enfermeras referentes de EAV (o ETI: Equipo de Terapia Intravenosa), comparten con nosotros su experiencia: c\u00f3mo empezaron para crear el EAV en sus respectivos centros, qu\u00e9 bases, recursos han necesitado para ello y de qu\u00e9 manera han podido integrar en el hospital.<\/p>\n\n\n\n<div class=\"wp-block-divi-layout\">[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb3.22&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb3.25&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/168PdcSPlHk\u00bb image_src=\u00bb\/\/i.ytimg.com\/vi\/168PdcSPlHk\/hqdefault.jpg\u00bb _builder_version=\u00bb4.10.7&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb play_icon_color=\u00bb#E02B20&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/div>\n\n\n\n<p>Si solo puedes dedicarle algunos minutos, te proponemos este resumen en 5 puntos:<\/p>\n\n\n\n<p><strong>ORIGEN DE LA CREACI\u00d3N DE UN EAV<\/strong>: la <strong>preocupaci\u00f3n por el capital venoso<\/strong> de los pacientes y la voluntad de <strong>mejora en la elecci\u00f3n del acceso vascular<\/strong> son en general los motores que activan la creaci\u00f3n de un EAV.<\/p>\n\n\n\n<p><strong>FUNCIONAMIENTO DE UN EAV:<\/strong> consiste en un equipo de profesionales sanitarios <strong>formados<\/strong> en general enfermeros\/enfermeras, <strong>dedicados al 100% a la colocaci\u00f3n de dispositivos de acceso vascular<\/strong> y que en general disponen de una consulta. Otro modelo, aunque no sea muy com\u00fan, es un equipo virtual compuesto por profesionales de distintos servicios, formados tambi\u00e9n y organizados para poder cubrir las demandas en acceso venoso. Son tambi\u00e9n <strong>responsables del mantenimiento de las v\u00edas<\/strong>, en primera persona o formando a los servicios correspondientes.<\/p>\n\n\n\n<p><strong>APOYOS FUNDAMENTALES<\/strong>: la <strong>direcci\u00f3n de enfermer\u00eda<\/strong> es un apoyo clave en la creaci\u00f3n de un EAV, el <strong>equipo m\u00e9dico<\/strong> y <strong>recursos materiales<\/strong> pueden ser tambi\u00e9n de mucha ayuda. No hay que olvidar que la <strong>industria<\/strong> tiene un papel fundamental a nivel de material y de formaci\u00f3n. Es importante poder contar con una <strong>persona de contacto en los servicios<\/strong> que van a manipular los accesos venosos colocados por el EAV, para, de esta manera, tener a alguien que coordine y releve los beneficios del EAV.<\/p>\n\n\n\n<p><strong>PASOS CLAVES PARA EL \u00c9XITO<\/strong>: es primordial <strong>definir con exactitud el tipo de demanda<\/strong> que va a ser (patolog\u00eda, tipo de cat\u00e9ter), <strong>a qu\u00e9 unidades se va a poder dar servicio<\/strong> (incluido la extrahospitalaria), usar <strong>canales adecuados de comunicaci\u00f3n<\/strong> para ello. Una vez recogida toda la informaci\u00f3n, <strong>determinar cual ser\u00eda el beneficio tanto para el paciente como para el hospital con la puesta en marcha de un EAV<\/strong>.<\/p>\n\n\n\n<p><strong>NO TE OLVIDES<\/strong>: &nbsp;de que es fundamental considerar que <strong>el mantenimiento es igual de importante que la colocaci\u00f3n <\/strong>de las v\u00edas. La <strong>formaci\u00f3n<\/strong> tiene un papel fundamental en el \u00e9xito y la continuidad de un EAV.<\/p>\n\n\n\n<p>Si quieres saber m\u00e1s sobre este tema, sigue leyendo y descubre como lo han hecho nuestras ponentes a trav\u00e9s de testimonios e infograf\u00edas que te pueden ser \u00fatiles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>SOBRE QU\u00c9 BASES SE CONSTRUYE UN EAV <\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 modelo de EAV ten\u00e9is?<\/strong><\/h4>\n\n\n\n<p><strong>Maite P<\/strong>.: Hoy en d\u00eda tenemos un EAV que funciona en una <strong>consulta propia<\/strong>, donde nos llegan pacientes de los <strong>distintos servicios del hospital<\/strong> a trav\u00e9s de una <strong>interconsulta<\/strong>. Nos encargamos principalmente de la<strong> inserci\u00f3n de los cat\u00e9teres y de una parte de las curas<\/strong> ya que el volumen actual no nos permite abarcar todo (formamos y delegamos). Cuando es necesario <strong>nos desplazamos a las habitaciones<\/strong> para colocar el cat\u00e9ter requerido.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/accesos-vasculares-media-larga-duracion\/\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/08\/Accesos-vasculares-banner.jpg\" alt=\"\" class=\"wp-image-26576\" width=\"525\" height=\"375\" srcset=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/08\/Accesos-vasculares-banner.jpg 525w, http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/08\/Accesos-vasculares-banner-480x343.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 525px, 100vw\" \/><\/a><\/figure><\/div>\n\n\n\n<p><strong>Vicky A<\/strong>.: tenemos un modelo similar al de Maite con una consulta en la cual atendemos \u00fanicamente a pacientes de <strong>extrahospitalaria<\/strong>. Para los pacientes <strong>intrahospitalarios<\/strong> vamos siempre <strong>a pie de cama<\/strong>. Dependemos directamente de direcci\u00f3n de enfermer\u00eda.<\/p>\n\n\n\n<p><strong>Vicky S<\/strong>.: actualmente tenemos una <strong>consulta<\/strong> que depende de la UCI pero cuando arrancamos creamos lo que llamamos un <strong>EAV virtual<\/strong>. No \u00e9ramos un EAV como tal, es decir, miembros todos ubicados en esta unidad sino un grupo de enfermer<strong>os formados que segu\u00edan perteneciendo y trabajando en su servicio de origen<\/strong>. Nos organizamos <strong>por turnos<\/strong> en funci\u00f3n de la demanda, programando a los pacientes.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"http:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/captura-5\/\" rel=\"attachment wp-att-18775\"><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"353\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/Captura-1.jpg\" alt=\"\" class=\"wp-image-18775\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/Captura-1.jpg 418w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/Captura-1-300x253.jpg 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/Captura-1-335x283.jpg 335w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/><\/a><figcaption>EAV del hospital Sant Joan de Reus (colocaci\u00f3n de un acceso vascular en su consulta) &#8211; Cortes\u00eda de Maite Parejo<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">&nbsp;<strong>\u00bfC\u00f3mo hab\u00e9is empezado para crear un EAV? <\/strong><\/h4>\n\n\n\n<p><strong>Maite P<\/strong>.:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Todo empez\u00f3 con los <strong>problemas de acceso vascular<\/strong> que ten\u00edamos dentro de nuestro servicio de <strong>oncolog\u00eda<\/strong> en la \u00e9poca, en particular en pacientes con c\u00e1ncer de mama. Buscando soluciones, nuestra investigaci\u00f3n nos hizo descubrir los cat\u00e9teres <strong>PICC<\/strong> que empezamos entonces a colocar.<\/p><\/blockquote>\n\n\n\n<p>Los dem\u00e1s servicios del hospital vieron que estos dispositivos funcionaban bien, as\u00ed como el equipo que \u00e9ramos. Todo ello nos permiti\u00f3 seguir y crear una <strong>consulta<\/strong> en la cual nos llevaban a los pacientes necesitados o si era requerido, \u00edbamos tambi\u00e9n a proceder a la colocaci\u00f3n a pie de cama.<\/p>\n\n\n\n<p>Al principio nos encarg\u00e1bamos de <strong>todas las curas ya que el volumen era asumible<\/strong>, lo cual cambi\u00f3 con la evoluci\u00f3n del EAV como dicho anteriormente.<\/p>\n\n\n\n<p><strong>Vicky A<\/strong>.: tuvimos un arranque muy parecido, nuestra problem\u00e1tica era la misma en el servicio de <strong>onco-hematolog\u00eda<\/strong>. Fue gracias a la industria que pudimos empezar a colocar cat\u00e9teres PICC.<\/p>\n\n\n\n<p>El salto a EAV como tal, fue a trav\u00e9s de una <strong>beca<\/strong> que solicitamos al gobierno vasco para llevar a cabo un <strong>ensayo cl\u00ednico sobre la efectividad y el impacto que tiene un EAV en el hospital<\/strong> en cuanto al<strong> acceso vascular<\/strong>, la<strong> satisfacci\u00f3n del paciente<\/strong> y la <strong>estancia hospitalaria<\/strong>. Durante este ensayo creamos tal necesidad de cara a otros servicios que el equipo ya ten\u00eda raz\u00f3n de ser, no se pod\u00eda dar marcha atr\u00e1s.<\/p>\n\n\n\n<p><strong>Vicky S<\/strong>.: nuestros principios fueron c\u00f3mo indican aqu\u00ed mis compa\u00f1eras, todo empieza por una <strong>necesidad<\/strong> y gracias a la <strong>investigaci\u00f3n<\/strong> de enfermeros preocupados por el tema. Los tratamientos evolucionan, el perfil de los pacientes tambi\u00e9n y hay que adaptarse ofreciendo un cuidado adecuado. Hay que tener en cuenta el <strong>tama\u00f1o del hospital<\/strong> (necesidad en funci\u00f3n del n\u00famero de camas) porque determinar\u00e1 cuanto personal se tendr\u00e1 que dedicar al acceso vascular.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/vicky\/\" rel=\"attachment wp-att-18759\"><img decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/vicky.png\" alt=\"\" class=\"wp-image-18759\" width=\"500\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/vicky.png 739w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/vicky-300x254.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/vicky-335x283.png 335w\" sizes=\"(max-width: 739px) 100vw, 739px\" \/><\/a><figcaption> EAV del hospital OSI Araba de Vitoria  (colocaci\u00f3n de un acceso vascular a pie de cama) &#8211; Cortes\u00eda de Vicky Armenteros y Arantza Tom\u00e1s<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfSobre qu\u00e9 y\/o qui\u00e9n os hab\u00e9is apoyado (otros EAVs)?<\/strong><\/h4>\n\n\n\n<p><strong>Vicky S.: <\/strong>La <strong>industria es fundamental<\/strong> para poder acceder a los dispositivos y evolucionar al mismo tiempo que la tecnolog\u00eda. El apoyo de<strong> direcci\u00f3n de enfermer\u00eda<\/strong> es muy importante en este proyecto.<\/p>\n\n\n\n<p><strong>Maite P<\/strong>.: en mi caso fue clave el apoyo del <strong>equipo de m\u00e9dicos onc\u00f3logos<\/strong> que eran muy conscientes del <strong>capital venoso<\/strong> y del <strong>dolor<\/strong> de los pacientes de esta especialidad. La industria ha tenido un papel muy importante dej\u00e1ndonos material para poder posteriormente demostrar que el proyecto funciona. Y como no, el <strong>respaldo de direcci\u00f3n de enfermer\u00eda<\/strong> es tambi\u00e9n muy importante.<\/p>\n\n\n\n<p><strong>Vicky A.:<\/strong> coincido con lo que comentan mis compa\u00f1eras,<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>el apoyo de direcci\u00f3n de enfermer\u00eda es fundamental<\/strong> y nosotros tuvimos la suerte que siempre nos ha respaldado. En este sentido para mantener este apoyo es importante <strong>dar feedback a direcci\u00f3n de enfermer\u00eda, a recursos materiales<\/strong> que siempre te pueden ayudar.<\/p><\/blockquote>\n\n\n\n<p>La industria es tambi\u00e9n clave porque te permite abrir puertas y cuando no sabes, ellos te ense\u00f1an.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>En mi opini\u00f3n es muy importante contar con <strong>una persona en cada servicio<\/strong> que entienda y apoya el proyecto ya que este profesional va a actuar <strong>como relevo y difundir la informaci\u00f3n y los beneficios del E<\/strong>AV.<\/p><\/blockquote>\n\n\n\n<p>No hay que olvidar que apoyarse en la <strong>literatura<\/strong> es tambi\u00e9n algo muy valioso, permite tener <strong>conocimiento<\/strong>, una \u201cexpertise\u201d y as\u00ed <strong>credibilidad<\/strong> frente a interlocutores que pueden poner en duda el proyecto.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/vicky-colocacion\/\" rel=\"attachment wp-att-19093\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/Vicky-colocacion-.jpeg\" alt=\"\" class=\"wp-image-19093\" width=\"439\" height=\"703\" \/><\/a><figcaption> EAV del hospital Arnau de Vilanova de Valencia (colocaci\u00f3n de un acceso vascular en su consulta) &#8211; Cortes\u00eda de Vicky Solaz<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 pasos claves hay que dar para que sea un proyecto exitoso? <\/strong><\/h4>\n\n\n\n<p><strong>Vicky A.: <\/strong>Uno de los pilares es establecer estrategias. Para ello es necesario <strong>tener claro en qu\u00e9 tipo de hospital est\u00e1s<\/strong>: la demanda ser\u00e1 muy distinta entre un centro de 300 camas y uno de 1500.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Define muy bien <strong>qu\u00e9 tipo de demanda<\/strong> va a ser: qu\u00e9 <strong>patolog\u00edas<\/strong> (cr\u00f3nicos agudos) qu\u00e9 tipo de <strong>cat\u00e9teres<\/strong> (midlines, PICCs). Analiza qu\u00e9 servicios ser\u00edan susceptibles de pedir servicio y cuantif\u00edcalos. Selecciona luego uno o 2 y <strong>determina cual hubiera sido el impacto si estos servicios se hubieran beneficiado de un EAV<\/strong>.<\/p><\/blockquote>\n\n\n\n<p><strong>Los canales de comunicaci\u00f3n<\/strong> son tambi\u00e9n un aspecto relevante especialmente al principio, <strong>el \u00e9xito depender\u00e1 de como habr\u00e1s informado a los distintos profesionales sobre tu proyecto<\/strong> (\u00bfdirecci\u00f3n general, de enfermer\u00eda, por videoconferencia, por sesi\u00f3n presencial?).<\/p>\n\n\n\n<p><strong>Maite P.:<\/strong> estoy muy de acuerdo con lo que comenta Vicky, en nuestro caso hay que tener en cuenta <strong>el factor extrahospitalari<\/strong>o. Nuestro hospital tiene un poco m\u00e1s de 300 camas, pero cubrimos un \u00e1rea muy grande y nos llegan muchos pacientes en ambulatorio (1700 cada a\u00f1o).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Tener muy presente que <strong>el mantenimiento es igual de importante que la colocaci\u00f3n<\/strong>. <strong>Sin una manipulaci\u00f3n adecuada, no sirve colocar cat\u00e9teres porque fracasar\u00e1n<\/strong>. En cuanto hay una persona con formaci\u00f3n insuficiente, enseguida se nota en la incidencia de complicaciones.<\/p><\/blockquote>\n\n\n\n<p><strong>Vicky S.: <\/strong>el apoyo de <strong>direcci\u00f3n<\/strong> fue en nuestro caso clave para desarrollar el proyecto.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Dar la posibilidad a enfermer\u00eda de pedir midlines desde su servicio permite una mejor gesti\u00f3n y una mayor coordinaci\u00f3n (para los PICCs est\u00e1 consensuado)<\/strong>.<\/p><\/blockquote>\n\n\n\n<p>Quiero reforzar el mensaje sobre la formaci\u00f3n: <strong>es imprescindible que las enfermeras que vayan a manipular el cat\u00e9ter sepan c\u00f3mo hacerlo<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/bases\/\" rel=\"attachment wp-att-18754\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/bases.jpg\" alt=\"\" class=\"wp-image-18754\" width=\"700\" height=\"700\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/bases.jpg 1000w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/bases-300x300.jpg 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/bases-150x150.jpg 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/bases-768x768.jpg 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/bases-70x70.jpg 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/bases-335x335.jpg 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/bases-360x360.jpg 360w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>RECURSOS MATERIALES Y HUMANOS NECESARIOS PARA SU FUNCIONAMIENTO<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 formaci\u00f3n se requiere para colocar v\u00edas y hacer parte de este equipo?<\/strong><\/h4>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Una cosa fundamental a tener en cuenta desde el principio es que hacer parte de un EAV <strong>no es solo ser implantador, es mucho m\u00e1s que eso<\/strong>. Hay que tener un <strong>conocimiento global y completo del acceso vascular<\/strong> en general para poder <strong>elegir adecuadamente las v\u00edas, aplicar una t\u00e9cnica correcta y asegurar un buen mantenimiento<\/strong>.<\/p><\/blockquote>\n\n\n\n<p>De hecho, el acceso vascular concierne<strong> a todas las enfermeras<\/strong> porque la inmensa de los pacientes son portadores de una v\u00eda. Y es algo que echo de menos en la carrera universitaria, necesitar\u00edamos una <strong>formaci\u00f3n sobre los cuidados de la v\u00eda<\/strong> que fuera m\u00e1s reglada, oficializada e integrada al mismo nivel que otros cuidados de enfermer\u00eda (formaci\u00f3n sobre capital venoso y dispositivos de acceso vascular).<\/p>\n\n\n\n<p>En lo que se refiere a miembros de EAV, esta formaci\u00f3n deber\u00eda ser mucho <strong>m\u00e1s estructurada,<\/strong> no solo a nivel de tiempos (cuantas horas requeridas para controlar la t\u00e9cnica de inserci\u00f3n). No tendr\u00eda que ser centrada \u00fanicamente en alcanzar un nivel de tecnicidad respecto a la colocaci\u00f3n, pero<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>tendr\u00eda que ser <strong>algo din\u00e1mico en el tiempo que permitiese una evaluaci\u00f3n continua sobre toda la gesti\u00f3n del acceso vascular<\/strong>. A trav\u00e9s de ex\u00e1menes de capacitaci\u00f3n, se podr\u00eda evaluar cada profesional en relaci\u00f3n con los avances tecnol\u00f3gicos, la evoluci\u00f3n de las t\u00e9cnicas.<\/p><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfDe cu\u00e1ntas personas se deber\u00eda componer el equipo y de qu\u00e9 material hay que disponer para trabajar en condiciones?<\/strong><\/h4>\n\n\n\n<p>Estar<strong> m\u00ednimo 2 personas<\/strong> para formar el equipo es el primer requisito m\u00e1s importante. <strong>Llevar un proyecto de esta envergadura solo es imposible<\/strong>. No significa que tienen que ser las 2 personas insertadores, pero quiere decir que alguien en el equipo, tiene que hacer de gestor ya que son muchos los factores a tener en cuenta.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Respecto al material, el <strong>ec\u00f3grafo<\/strong> es lo m\u00e1s importante. <strong>Hoy en d\u00eda no se puede hacer punciones a ciegas<\/strong>.<\/p><\/blockquote>\n\n\n\n<p>Supone<strong> demasiados riesgos<\/strong> durante el gesto y <strong>muchas complicaciones<\/strong> posteriores que pueden llegar a ser graves.<\/p>\n\n\n\n<p>Tener unos <strong>cat\u00e9teres de buena calidad<\/strong>, <strong>material est\u00e9ril<\/strong> para respetar las condiciones de asepsia que requiere la t\u00e9cnica. Poder trabajar en una <strong>sala<\/strong>, un habit\u00e1culo tambi\u00e9n tiene mucha importancia tanto para <strong>hacer el procedimiento<\/strong> como para existir f\u00edsicamente para los dem\u00e1s servicios.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/recursos-4\/\" rel=\"attachment wp-att-18756\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/recursos.jpg\" alt=\"\" class=\"wp-image-18756\" width=\"700\" height=\"700\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/recursos.jpg 1000w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/recursos-300x300.jpg 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/recursos-150x150.jpg 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/recursos-768x768.jpg 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/recursos-70x70.jpg 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/recursos-335x335.jpg 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/recursos-360x360.jpg 360w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>ESTRATEGIAS PARA LA INTEGRACI\u00d3N DEL ETI EN EL HOSPITAL<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfA cu\u00e1ntas unidades es recomendable dar servicio para empezar?<\/strong><\/h4>\n\n\n\n<p>Depender\u00e1 del <strong>tipo de hospital<\/strong>: el numero de camas y qu\u00e9 <strong>tipos de especialidad<\/strong> hay, qu\u00e9 <strong>tipo de patolog\u00edas<\/strong> atiende. Puede ser un <strong>error<\/strong> creer que se puede abarcar <strong>todas las demandas desde un principi<\/strong>o. En el caso de que los recursos previstos no sean los adecuados para una demanda tan grande,<strong> el EAV puede no dar abasto<\/strong>. Adem\u00e1s, puede dar el caso que el grupo se dedica entonces <strong>solo a la inserci\u00f3n<\/strong> y <strong>no tenga tiempo de cumplir con la labor de mantenimiento y de formaci\u00f3n sobre el mismo<\/strong>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Es mejor empezar con <strong>2 o 3 servicios<\/strong> y ver como el equipo se va desenvolviendo.<\/p><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo se hace la coordinaci\u00f3n con estos servicios y con otros profesionales implicados?<\/strong><\/h4>\n\n\n\n<p>Es primordial poder tener un <strong>canal de comunicaci\u00f3n adecuado<\/strong> con los compa\u00f1eros, en este caso un<strong> programa inform\u00e1tico<\/strong> a trav\u00e9s del cual se puede consultar la <strong>historia<\/strong> del paciente y hacer una <strong>interconsulta<\/strong> para que pongan la petici\u00f3n y expliquen el motivo. Obviamente indispensable tener un tel\u00e9fono para que los servicios nos puedan contactar.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Es importante que las unidades conozcan bien nuestra<strong> cartera de servicios<\/strong>: <strong>qu\u00e9 tipos de patolog\u00edas abarca el EAV y qu\u00e9 tipos de dispositivos puede colocar<\/strong>. Tener perfilado el paciente ayuda mucho a las enfermeras de las unidades par saber cu\u00e1ndo se requiere un DAV especifico que implica llamar al EAV.<\/p><\/blockquote>\n\n\n\n<p>Un punto destacable que aparece cuando el EAV ya lleva un cierto recorrido es <strong>el trabajo multidisciplinar al que se tiene que llegar<\/strong>. Al principio est\u00e1 centrado en enfermer\u00eda al arrancar el proyecto, pero poco a poco <strong>los distintos profesionales involucrados se pueden coordinar con el EAV<\/strong> para la gesti\u00f3n del acceso vascular en el paciente. Se trata de tener un enlace con radiolog\u00eda intervencionista, m\u00e9dicos de infecciosas para prevenir las infecciones relacionadas con cateterismo, primaria para asegurar la continuidad de los cuidados de los pacientes extrahospitalarios, entre otros.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfC\u00f3mo se consigue el apoyo de la direcci\u00f3n?<\/strong><\/h4>\n\n\n\n<p>La direcci\u00f3n del hospital tiene que ver que el EAV es <strong>necesario<\/strong>, que es un recurso genera un <strong>beneficio tanto para el centro como para los pacientes y que sin su existencia no se puede alcanzar<\/strong>. Gracias al grupo se va a <strong>evitar una serie complicaciones<\/strong> que suponen un <strong>gasto<\/strong> para el hospital. Por ejemplo, en el caso de terapias cortas, con solo demostrar que se usan 3 dispositivos en lugar de 1, y\/o que se provoca una flebitis evitable, se puede hacer ver de forma concreta las ventajas de este proyecto (gasto).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Si se plantea la presentaci\u00f3n con este enfoque, direcci\u00f3n entender\u00e1 la <strong>eficacia del EAV<\/strong>, c\u00f3mo<strong> se reducen los costos<\/strong>, c\u00f3mo <strong>se reduce la estancia hospitalaria<\/strong>, a veces <strong>evitando ingresos<\/strong> derivando a los pacientes a domiciliaria, por ejemplo. Sin olvidar que la buena gesti\u00f3n de los cat\u00e9teres <strong>reduce el tiempo de trabajo de los equipos de enfermer\u00eda en los servicios de cara a la gesti\u00f3n de las v\u00edas<\/strong>.<\/p><\/blockquote>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/integracion\/\" rel=\"attachment wp-att-18757\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/integracion.jpg\" alt=\"\" class=\"wp-image-18757\" width=\"700\" height=\"700\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/integracion.jpg 1000w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/integracion-300x300.jpg 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/integracion-150x150.jpg 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/integracion-768x768.jpg 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/integracion-70x70.jpg 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/integracion-335x335.jpg 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/integracion-360x360.jpg 360w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>PREGUNTAS DE LA AUDIENCIA<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 opini\u00f3n tienen en relaci\u00f3n con incluir personal de farmacia al EAV?<\/strong><\/h4>\n\n\n\n<p>Es <strong>fundamental<\/strong>. Farmacia tiene un papel clave para ayudar al ETI sobre la <strong>compatibilidad<\/strong> o <strong>incompatibilidad<\/strong> de los f\u00e1rmacos a infundir y tambi\u00e9n en lo que se refiere a las <strong>nutriciones parenterales<\/strong>.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfEs indispensable que el EAV se encargue de todas las curas de los accesos vasculares?<\/strong><\/h4>\n\n\n\n<p>No, es fundamental <strong>formar<\/strong> para poder <strong>delegar<\/strong> a enfermer\u00eda de los servicios las <strong>curas<\/strong> y m\u00e1s cuando la distancia es grande por ejemplo en el caso de <strong>extrahospitalaria<\/strong> (domicilio, primaria).<\/p>\n\n\n\n<p>Al principio s\u00ed se puede asumir las curas porque el volumen es poco, y conforme va evolucionando el EAV se forma a la gente que manipula. El EAV es accesible en cualquier momento para las dudas de las enfermeras que manipulan los dispositivos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfLa interconsulta la realizan las propias enfermeras de los servicios o el m\u00e9dico?<\/strong><\/h4>\n\n\n\n<p>Los 2 pueden realizarla. Lo ideal es cuando <strong>se consensua<\/strong>. Desde el EAV a veces decidimos nosotras tambi\u00e9n de qu\u00e9 dispositivo tiene que llevar el paciente en funci\u00f3n de su <strong>historia cl\u00ednica<\/strong>, <strong>patolog\u00eda<\/strong> y <strong>tratamiento<\/strong>, y a veces cambiando la decisi\u00f3n anterior de los compa\u00f1eros explic\u00e1ndoles el por qu\u00e9. Por ello es importante haber establecido unas bases anteriormente, con unos canales de comunicaci\u00f3n adecuados para que la decisi\u00f3n se haga de la mejor forma posible (rapidez y adecuaci\u00f3n).<\/p>\n\n\n\n<p><strong>Si quieres saber m\u00e1s sobre este tema, no dudes en hacer un comentario abajo e intentaremos ayudarte.<\/strong><\/p>\n\n\n\n<p><strong>Tranquil@, esto NO es una lista de SPAM.&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size has-small-font-size\"><a class=\"wp-block-button__link\" href=\"http:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#respond\"><span class=\"has-inline-color has-white-color\">Deja tu comentario<\/span><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Te puede interesar<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"http:\/\/campusvygon.com\/es\/pautas-sobre-gestion-de-avs-en-pacientes-covid-19-colocacion-ubicacion-y-fijacion\/\"><strong>MAXIMIZAR EL RENDIMIENTO DE UN ACCESO VASCULAR EN PACIENTES COVID: COLOCACI\u00d3N Y MANTENIMIENTO<\/strong><\/a><\/li><li><a href=\"http:\/\/campusvygon.com\/es\/nutricion-parenteral-y-accesos-vasculares\/\"><strong>NUTRICI\u00d3N PARENTERAL \u00bfQU\u00c9 ES Y QU\u00c9 ACCESO VASCULAR ELEGIR?<\/strong><\/a><\/li><li><a href=\"http:\/\/campusvygon.com\/es\/metodo-rapeva-en-ecografia-valoracion-venosa-y-tecnica-de-puncion\/\"><strong>M\u00c9TODO RAPEVA EN ECOGRAF\u00cdA: VALORACI\u00d3N VENOSA Y T\u00c9CNICA DE PUNCI\u00d3N<\/strong><\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En esta mesa redonda, Maite Parejo, Vicky Armenteros y Vicky Solaz expertas en acceso vascular y enfermeras referentes de EAV (o ETI: Equipo de Terapia Intravenosa), comparten con nosotros su experiencia: c\u00f3mo empezaron para crear el EAV en sus respectivos centros, qu\u00e9 bases, recursos han necesitado para ello y de qu\u00e9 manera han podido integrar [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":28113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[116],"tags":[314,102,142,316,219,230],"class_list":["post-18751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-terapias-intravasculares","tag-ecg-intracavitario","tag-ecografia","tag-eti","tag-midlines","tag-picc-port","tag-piccs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular? - Campus Vygon Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Crear un ETI lleva un proceso con m\u00faltiples factores a tener en cuenta, para ayudarnos 3 expertas nos explican c\u00f3mo conseguirlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular? - Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Crear un ETI lleva un proceso con m\u00faltiples factores a tener en cuenta, para ayudarnos 3 expertas nos explican c\u00f3mo conseguirlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-31T15:27:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-20T07:49:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/mesa-redonda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marie Pineau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Pineau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/\"},\"author\":{\"name\":\"Marie Pineau\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/3115f9edfc217688bdca3dcb2a969787\"},\"headline\":\"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular?\",\"datePublished\":\"2021-03-31T15:27:20+00:00\",\"dateModified\":\"2022-07-20T07:49:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/\"},\"wordCount\":2961,\"commentCount\":3,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/03\\\/mesa-redonda.jpg\",\"keywords\":[\"ecg intracavitario\",\"ecograf\u00eda\",\"ETI\",\"midlines\",\"PICC-PORT\",\"PICCs\"],\"articleSection\":[\"Terapias Intravasculares\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/\",\"name\":\"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular? - Campus Vygon Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/03\\\/mesa-redonda.jpg\",\"datePublished\":\"2021-03-31T15:27:20+00:00\",\"dateModified\":\"2022-07-20T07:49:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/3115f9edfc217688bdca3dcb2a969787\"},\"description\":\"Crear un ETI lleva un proceso con m\u00faltiples factores a tener en cuenta, para ayudarnos 3 expertas nos explican c\u00f3mo conseguirlo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/03\\\/mesa-redonda.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/03\\\/mesa-redonda.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/3115f9edfc217688bdca3dcb2a969787\",\"name\":\"Marie Pineau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/12\\\/mpineau-150x150.jpg\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/12\\\/mpineau-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/12\\\/mpineau-150x150.jpg\",\"caption\":\"Marie Pineau\"},\"description\":\"Soy responsable de contenidos de las unidades de negocio de Terapias Intravasculares y Obstetricia-Neonatolog\u00eda-Nutrici\u00f3n enteral en Vygon Espa\u00f1a \u2022 EXPERIENCIA He podido ejercer como enfermera durante varios a\u00f1os al principio de mi carrera, en m\u00faltiples \u00e1mbitos, entre otros como la neonatolog\u00eda, la pediatr\u00eda, la medicina interna y la cirug\u00eda. Desde mi llegada en Vygon en el a\u00f1o 2010, he podido desarrollar competencias en el terreno y adquirir conocimiento sobre productos, desarrollando una labor marketing y comercial. \u2022 PUEDO AYUDARTE EN\u2026 Resolver dudas sobre productos y sus aplicaciones ya que mi perfil combina a la vez marketing, comunicaci\u00f3n y pr\u00e1ctica cl\u00ednica Encontrar material digital sobre protocolos y t\u00e9cnicas as\u00ed como literatura existentes en terapia intravascular, tambi\u00e9n en neonatolog\u00eda, obstetricia y nutrici\u00f3n enteral.\",\"sameAs\":[\"https:\\\/\\\/www.vygon.es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marie-pineau\\\/\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/author\\\/mpineau\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular? - Campus Vygon Espa\u00f1a","description":"Crear un ETI lleva un proceso con m\u00faltiples factores a tener en cuenta, para ayudarnos 3 expertas nos explican c\u00f3mo conseguirlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/","og_locale":"es_ES","og_type":"article","og_title":"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular? - Campus Vygon Espa\u00f1a","og_description":"Crear un ETI lleva un proceso con m\u00faltiples factores a tener en cuenta, para ayudarnos 3 expertas nos explican c\u00f3mo conseguirlo.","og_url":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/","og_site_name":"Campus Vygon Espa\u00f1a","article_published_time":"2021-03-31T15:27:20+00:00","article_modified_time":"2022-07-20T07:49:01+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/mesa-redonda.jpg","type":"image\/jpeg"}],"author":"Marie Pineau","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marie Pineau","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/"},"author":{"name":"Marie Pineau","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/3115f9edfc217688bdca3dcb2a969787"},"headline":"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular?","datePublished":"2021-03-31T15:27:20+00:00","dateModified":"2022-07-20T07:49:01+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/"},"wordCount":2961,"commentCount":3,"image":{"@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/mesa-redonda.jpg","keywords":["ecg intracavitario","ecograf\u00eda","ETI","midlines","PICC-PORT","PICCs"],"articleSection":["Terapias Intravasculares"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/","url":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/","name":"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular? - Campus Vygon Espa\u00f1a","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/mesa-redonda.jpg","datePublished":"2021-03-31T15:27:20+00:00","dateModified":"2022-07-20T07:49:01+00:00","author":{"@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/3115f9edfc217688bdca3dcb2a969787"},"description":"Crear un ETI lleva un proceso con m\u00faltiples factores a tener en cuenta, para ayudarnos 3 expertas nos explican c\u00f3mo conseguirlo.","breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/mesa-redonda.jpg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/03\/mesa-redonda.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/mesa-redonda-como-crear-un-equipo-de-terapia-intravenosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"Mesa redonda: \u00bfC\u00f3mo crear un Equipo de acceso vascular?"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/3115f9edfc217688bdca3dcb2a969787","name":"Marie Pineau","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/12\/mpineau-150x150.jpg","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/12\/mpineau-150x150.jpg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/12\/mpineau-150x150.jpg","caption":"Marie Pineau"},"description":"Soy responsable de contenidos de las unidades de negocio de Terapias Intravasculares y Obstetricia-Neonatolog\u00eda-Nutrici\u00f3n enteral en Vygon Espa\u00f1a \u2022 EXPERIENCIA He podido ejercer como enfermera durante varios a\u00f1os al principio de mi carrera, en m\u00faltiples \u00e1mbitos, entre otros como la neonatolog\u00eda, la pediatr\u00eda, la medicina interna y la cirug\u00eda. Desde mi llegada en Vygon en el a\u00f1o 2010, he podido desarrollar competencias en el terreno y adquirir conocimiento sobre productos, desarrollando una labor marketing y comercial. \u2022 PUEDO AYUDARTE EN\u2026 Resolver dudas sobre productos y sus aplicaciones ya que mi perfil combina a la vez marketing, comunicaci\u00f3n y pr\u00e1ctica cl\u00ednica Encontrar material digital sobre protocolos y t\u00e9cnicas as\u00ed como literatura existentes en terapia intravascular, tambi\u00e9n en neonatolog\u00eda, obstetricia y nutrici\u00f3n enteral.","sameAs":["https:\/\/www.vygon.es\/","https:\/\/www.linkedin.com\/in\/marie-pineau\/"],"url":"https:\/\/campusvygon.com\/es\/author\/mpineau\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/18751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=18751"}],"version-history":[{"count":47,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/18751\/revisions"}],"predecessor-version":[{"id":34733,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/18751\/revisions\/34733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/28113"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=18751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/categories?post=18751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/tags?post=18751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}