{"id":29532,"date":"2021-11-12T10:58:18","date_gmt":"2021-11-12T09:58:18","guid":{"rendered":"http:\/\/campusvygon.com\/es\/?p=29532"},"modified":"2022-07-20T10:55:21","modified_gmt":"2022-07-20T08:55:21","slug":"gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/","title":{"rendered":"Gesti\u00f3n de personas en el entorno sanitario. \u00abCuida a qi\u00e9n te cuida\u00bb Entrevista con la Dra. Pilar Argente."},"content":{"rendered":"\n<p>Desde <a href=\"http:\/\/campusvygon.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">campus Vygon<\/a>, hemos tenido el placer de entrevistar a la <strong>Doctora Pilar Argente Navarro<\/strong>, <em>Jefa del Servicio de Anestesiolog\u00eda y Reanimaci\u00f3n y Directora del \u00c1rea Cl\u00ednica Anestesia-Reanimaci\u00f3n y B. Quir\u00fargico del&nbsp;Hospital Universitari i Polit\u00e8cnic La Fe de Valencia.&nbsp;Tambi\u00e9n vicepresidenta&nbsp; 1\u00aa de la SEDAR y Profesora de la Universidad de Valencia.<\/em><\/p>\n\n\n\n<p>Esta entrevista, pertenece al curso <a href=\"https:\/\/formacion.campusvygon.com\/es\/cursos\/-orgullosodeseranestesista-7?edicion=42&amp;tab=info\" target=\"_blank\" rel=\"noreferrer noopener\">OrgullosoDeSerAnestesista<\/a> que realizamos en colaboraci\u00f3n con la Sociedad Espa\u00f1ola de Anestesiolog\u00eda, Reanimaci\u00f3n y Terap\u00e9utica del Dolor (SEDAR) , un curso que ya tiene 2 ediciones m\u00e1s, una entrevista junto al <strong>Dr. Fernando Ramasco<\/strong>;<em> Vicepresidente de la secci\u00f3n de cuidados intensivos de S.E.D.A.R, y <\/em>otra junto al <strong>Dr. Javier Garc\u00eda Fern\u00e1ndez<\/strong>; <em>presidente de la SEDAR<\/em>, que os animamos a ver.<\/p>\n\n\n\n<p>Durante los pr\u00f3ximos meses, seguiremos con esta serie de entrevistas a jefes de servicios y profesionales destacados de la anestesia.<\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-light-green-cyan-background-color has-text-color has-background\" href=\"https:\/\/formacion.campusvygon.com\/es\/cursos\/-orgullosodeseranestesista-7?edicion=42&amp;tab=info\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-white-color\">Visualiza las entrevistas completas aqu\u00ed<\/span><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La <strong>Doctora Pilar argente,<\/strong> se define como una persona perfeccionista, trabajadora, valiente, emprendedora y que vive su especialidad con pasi\u00f3n.<\/p>\n\n\n\n<p>Lleg\u00f3 a la especialidad de anestesiolog\u00eda y reanimaci\u00f3n por casualidad, y por suerte, ya que agradecemos enormemente su trabajo y dedicaci\u00f3n. Como bien puntualiza durante la sesi\u00f3n, un profesional con <strong>coraje, valent\u00eda, empat\u00eda y escucha,<\/strong> es una persona preparada para afrontar cualquier reto. Las virtudes, nos ayudan a ser mejores.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong>Dedicaci\u00f3n, ilusi\u00f3n, generosidad<\/strong> y <strong>compromiso<\/strong> son actitudes y valores que deber\u00edan trabajarse continuamente, a nivel individual, y a nivel colectivo, dentro de las organizaciones.  <\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><em>UN PUNTO DE VISTA DIFERENTE<\/em><\/h2>\n\n\n\n<p>Durante esta charla, la <strong>Dra. Pilar Argente<\/strong> nos ha comentado cual es la situaci\u00f3n actual en los hospitales, como han vivido la pandemia y reflexiona sobre el papel que desempe\u00f1a el personal sanitario, y en especial, los anestesi\u00f3logos hoy en d\u00eda.  <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La especialidad de la anestesiolog\u00eda ha dado un paso al frente, se ha valorado la versatilidad y la capacidad del trabajo en equipo.<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-video\"><video controls poster=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/PORTADA-ENTREVISTA-DRA.-PILAR-ARGENTE.jpg\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/1.-visibilidad-de-los-anestesiologos.mp4\"><\/video><\/figure>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">La formaci\u00f3n continua, una herramienta necesaria<\/h2>\n\n\n\n<p>La formaci\u00f3n continua es necesaria, pero es dif\u00edcil debido a la falta de tiempo. Sin embargo, es algo que siempre se ha potenciado y se ha trabajado a nivel interno.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Es algo fundamental, pero se deben poner mecanismos, se deben formar equipos en los que se tengan las competencias, se mantengan y se mejoren.<\/p><\/blockquote>\n\n\n\n<p>La Doctora nos cuenta, como la falta de tiempo, debido a las demoras provocadas por la pandemia, han afectado a la formaci\u00f3n continua de los profesionales. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-light-green-cyan-background-color has-text-color has-background\" href=\"https:\/\/formacion.campusvygon.com\/es\/cursos\/-orgullosodeseranestesista-7?edicion=42&amp;tab=info\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-white-color\">Visualiza la entrevista completa aqu\u00ed<\/span><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-video\"><video controls poster=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/PORTADA-ENTREVISTA-DRA.-PILAR-ARGENTE.jpg\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/2.-pill-formacion-continua.mp4\"><\/video><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00abCUIDA A LOS QUE TE CUIDAN\u00bb<\/h2>\n\n\n\n<p>\u00bfC\u00f3mo se encuentra actualmente los sanitarios? \u00bfC\u00f3mo os afect\u00f3 la crisis por <strong>Covid-19<\/strong>&nbsp; en el centro, qu\u00e9 <strong>aprendizajes <\/strong>hab\u00e9is extra\u00eddo? \u00bfC\u00f3mo podemos ayudar como sociedad a la mejora de esta situaci\u00f3n? Son algunas de las preguntas que responde la Doctora.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>El Covid nos ha pasasado una factura muy grande, tenemos los efectos secundarios de esta pandemia, y ahora tenemos la era post-Covid. <\/p><cite>Hay que dar visibilidad, y cuidar al que te cuida, para tener resultados en salud dentro de la poblaci\u00f3n. <\/cite><\/blockquote>\n\n\n\n<figure class=\"wp-block-video\"><video controls poster=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/PORTADA-ENTREVISTA-DRA.-PILAR-ARGENTE.jpg\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/3.-el-covid-no-ha-pasado.mp4\"><\/video><\/figure>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00abSOMOS IMPORTANTES, SOMOS UNA PI\u00d1A\u00bb <\/h2>\n\n\n\n<p>\u00abLa fuerza de un equipo\u00bb frase que la Doctora utiliza para enfatizar el trabajo realizado por todo su equipo durante estos meses tan duros, \u00abDefine la uni\u00f3n y la valent\u00eda de los mismos\u00bb. <\/p>\n\n\n\n<p><strong>\u00bfH\u00e9roes o villanos? <\/strong>A pesar de c\u00f3mo est\u00e1n afectando las demoras, y la presi\u00f3n laboral, han aprendido a establecer prioridades dentro de un sistema alterado; \u00abNos esperan a\u00f1os duros, donde deberemos recuperar la ilusi\u00f3n, la motivaci\u00f3n y la confianza de la gente, pero somos un equipo fuerte\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video controls poster=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/PORTADA-ENTREVISTA-DRA.-PILAR-ARGENTE.jpg\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/4.somos-una-pina.mp4\"><\/video><\/figure>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">CONSEJOS Y APRENDIZAJES <\/h2>\n\n\n\n<p>En la primera ola se establecieron metodolog\u00edas, que en las siguientes olas pudieron aplicar; ya sab\u00edan como protegerse, como reaccionar, qu\u00e9 elecciones tomar ante determinadas situaciones&#8230; Pero el cansancio de tantas horas en el hospital, de tomar decisiones complicadas, el desgaste mental vivido ante situaciones familiares complicadas, de afrontar la enfermedad dentro del equipo y en s\u00ed mismos, pasa factura en la actualidad. Todo ello ha afectado y ha alterado el sistema dentro del equipo. Mantener la calma, saber escuchar, ser honestos y generosos, son algunos consejos que nos proporciona la Dra. Argente: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La capacidad de escucha para los jefes es muy importante, escuchar lo que se oye y lo que no se oye, que es lo m\u00e1s importante, donde est\u00e1n las debilidades de tu grupo y de tu gente y donde est\u00e1n los fuegos para poder pagaros antes de que se incendie todo. Que la paciencia, la generosidad, la honestidad y la coherencia son b\u00e1sicas y fundamentales.<\/p><\/blockquote>\n\n\n\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Desde <strong>Vygon<\/strong>, agradecemos una vez m\u00e1s la participaci\u00f3n de la <strong>Doctora Pilar Argente<\/strong>, y a todos los que asistieron al  evento en directo del curso. Pr\u00f3ximamente nos volveremos a ver con nuevas entrevistas a<strong> jefes de servicios<\/strong> y<strong> profesionales destacados de la anestesia<\/strong>. Recuerda que puedes volver a ver todas las sesiones en el curso  <span class=\"has-inline-color has-vivid-green-cyan-color\"><strong><a href=\"https:\/\/formacion.campusvygon.com\/es\/cursos\/-orgullosodeseranestesista-7?edicion=42&amp;tab=info\" target=\"_blank\" rel=\"noreferrer noopener\">OrgullosoDeSerAnestesista<\/a><\/strong><\/span>. \u00a1No te lo pierdas!<\/p>\n\n\n\n<div style=\"height:56px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><span class=\"has-inline-color has-light-green-cyan-color\">No te pierdas la entrevista completa de la Doctora Pillar Argente dentro del curso <strong> <a href=\"https:\/\/formacion.campusvygon.com\/es\/cursos\/-orgullosodeseranestesista-7?edicion=42&amp;tab=info\" target=\"_blank\" rel=\"noreferrer noopener\">OrgullosoDeSerAnestesista<\/a>:<\/strong><\/span><\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-light-green-cyan-background-color has-text-color has-background\" href=\"https:\/\/formacion.campusvygon.com\/es\/cursos\/-orgullosodeseranestesista-7?edicion=42&amp;tab=info\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"has-inline-color has-white-color\">Visualiza la entrevista completa aqu\u00ed<\/span><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:71px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/anestesia-locorregional\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/09\/banner-Anestesia-locorregional.jpg\" alt=\"\" class=\"wp-image-27036\" width=\"572\" height=\"409\" srcset=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/09\/banner-Anestesia-locorregional.jpg 572w, http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/09\/banner-Anestesia-locorregional-480x343.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 572px, 100vw\" \/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Desde campus Vygon, hemos tenido el placer de entrevistar a la Doctora Pilar Argente Navarro, Jefa del Servicio de Anestesiolog\u00eda y Reanimaci\u00f3n y Directora del \u00c1rea Cl\u00ednica Anestesia-Reanimaci\u00f3n y B. Quir\u00fargico del&nbsp;Hospital Universitari i Polit\u00e8cnic La Fe de Valencia.&nbsp;Tambi\u00e9n vicepresidenta&nbsp; 1\u00aa de la SEDAR y Profesora de la Universidad de Valencia. Esta entrevista, pertenece al [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":29541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[285],"tags":[62,114],"class_list":["post-29532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anestesia-y-cuidados-intensivos","tag-anestesia","tag-anestesia-y-emergencias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gesti\u00f3n de personas en el entorno sanitario. &quot;Cuida a qi\u00e9n te cuida&quot; Entrevista con la Dra. Pilar Argente. - Campus Vygon Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesti\u00f3n de personas en el entorno sanitario. &quot;Cuida a qi\u00e9n te cuida&quot; Entrevista con la Dra. Pilar Argente. - Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Desde campus Vygon, hemos tenido el placer de entrevistar a la Doctora Pilar Argente Navarro, Jefa del Servicio de Anestesiolog\u00eda y Reanimaci\u00f3n y Directora del \u00c1rea Cl\u00ednica Anestesia-Reanimaci\u00f3n y B. Quir\u00fargico del&nbsp;Hospital Universitari i Polit\u00e8cnic La Fe de Valencia.&nbsp;Tambi\u00e9n vicepresidenta&nbsp; 1\u00aa de la SEDAR y Profesora de la Universidad de Valencia. Esta entrevista, pertenece al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-12T09:58:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-20T08:55:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/ENTREVISTA-BYN-PILAR-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sara Colavecchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sara Colavecchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/\"},\"author\":{\"name\":\"Sara Colavecchi\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/b8162cdfab6922f38ab0c4f1a78d3993\"},\"headline\":\"Gesti\u00f3n de personas en el entorno sanitario. \u00abCuida a qi\u00e9n te cuida\u00bb Entrevista con la Dra. Pilar Argente.\",\"datePublished\":\"2021-11-12T09:58:18+00:00\",\"dateModified\":\"2022-07-20T08:55:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/\"},\"wordCount\":896,\"commentCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/11\\\/ENTREVISTA-BYN-PILAR-1.jpg\",\"keywords\":[\"Anestesia\",\"Anestesia y Emergencias\"],\"articleSection\":[\"Anestesia y Cuidados Intensivos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/\",\"name\":\"Gesti\u00f3n de personas en el entorno sanitario. \\\"Cuida a qi\u00e9n te cuida\\\" Entrevista con la Dra. Pilar Argente. - Campus Vygon Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/11\\\/ENTREVISTA-BYN-PILAR-1.jpg\",\"datePublished\":\"2021-11-12T09:58:18+00:00\",\"dateModified\":\"2022-07-20T08:55:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/b8162cdfab6922f38ab0c4f1a78d3993\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/11\\\/ENTREVISTA-BYN-PILAR-1.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2021\\\/11\\\/ENTREVISTA-BYN-PILAR-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesti\u00f3n de personas en el entorno sanitario. \u00abCuida a qi\u00e9n te cuida\u00bb Entrevista con la Dra. Pilar Argente.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/b8162cdfab6922f38ab0c4f1a78d3993\",\"name\":\"Sara Colavecchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/plugins\\\/wp-user-avatar\\\/deprecated\\\/wp-user-avatar\\\/images\\\/wpua-96x96.png\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/plugins\\\/wp-user-avatar\\\/deprecated\\\/wp-user-avatar\\\/images\\\/wpua-96x96.png\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/plugins\\\/wp-user-avatar\\\/deprecated\\\/wp-user-avatar\\\/images\\\/wpua-96x96.png\",\"caption\":\"Sara Colavecchi\"},\"description\":\"Soy responsable de contenidos de la unidad de negocio Gesti\u00f3n del Dolor y Manejo de la V\u00eda A\u00e9rea. \u2022 EXPERIENCIA Me defino como una apasionada del marketing, la comunicaci\u00f3n, el dise\u00f1o y las nuevas tecnolog\u00edas. Disciplinas en las cuales me he especializado a lo largo de estos a\u00f1os, y en las que sin duda seguir\u00e9 haci\u00e9ndolo.\u00a0 Graduada en Multimedia y Artes Digitales y he realizado un master en Gesti\u00f3n Comercial y Direcci\u00f3n de Marketing. Tengo experiencia en distintos sectores, pero actualmente, estoy centrada en adquirir conocimientos\u00a0del mundo sanitario en Vygon. \u2022 PUEDO AYUDARTE EN\u2026 Mi trabajo se basa en una apuesta clara de Vygon por la formaci\u00f3n digital y el aprendizaje continuo. Puedes contactarme si buscas material digital sobre alg\u00fan procedimiento o t\u00e9cnica habitual en los servicios de Anestesia, Urgencias y Emergencias.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/saracolavecchialarcon\\\/\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/author\\\/scolavecchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesti\u00f3n de personas en el entorno sanitario. \"Cuida a qi\u00e9n te cuida\" Entrevista con la Dra. Pilar Argente. - Campus Vygon Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/","og_locale":"es_ES","og_type":"article","og_title":"Gesti\u00f3n de personas en el entorno sanitario. \"Cuida a qi\u00e9n te cuida\" Entrevista con la Dra. Pilar Argente. - Campus Vygon Espa\u00f1a","og_description":"Desde campus Vygon, hemos tenido el placer de entrevistar a la Doctora Pilar Argente Navarro, Jefa del Servicio de Anestesiolog\u00eda y Reanimaci\u00f3n y Directora del \u00c1rea Cl\u00ednica Anestesia-Reanimaci\u00f3n y B. Quir\u00fargico del&nbsp;Hospital Universitari i Polit\u00e8cnic La Fe de Valencia.&nbsp;Tambi\u00e9n vicepresidenta&nbsp; 1\u00aa de la SEDAR y Profesora de la Universidad de Valencia. Esta entrevista, pertenece al [&hellip;]","og_url":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/","og_site_name":"Campus Vygon Espa\u00f1a","article_published_time":"2021-11-12T09:58:18+00:00","article_modified_time":"2022-07-20T08:55:21+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/ENTREVISTA-BYN-PILAR-1.jpg","type":"image\/jpeg"}],"author":"Sara Colavecchi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sara Colavecchi","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/"},"author":{"name":"Sara Colavecchi","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/b8162cdfab6922f38ab0c4f1a78d3993"},"headline":"Gesti\u00f3n de personas en el entorno sanitario. \u00abCuida a qi\u00e9n te cuida\u00bb Entrevista con la Dra. Pilar Argente.","datePublished":"2021-11-12T09:58:18+00:00","dateModified":"2022-07-20T08:55:21+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/"},"wordCount":896,"commentCount":4,"image":{"@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/ENTREVISTA-BYN-PILAR-1.jpg","keywords":["Anestesia","Anestesia y Emergencias"],"articleSection":["Anestesia y Cuidados Intensivos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/","url":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/","name":"Gesti\u00f3n de personas en el entorno sanitario. \"Cuida a qi\u00e9n te cuida\" Entrevista con la Dra. Pilar Argente. - Campus Vygon Espa\u00f1a","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/ENTREVISTA-BYN-PILAR-1.jpg","datePublished":"2021-11-12T09:58:18+00:00","dateModified":"2022-07-20T08:55:21+00:00","author":{"@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/b8162cdfab6922f38ab0c4f1a78d3993"},"breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/ENTREVISTA-BYN-PILAR-1.jpg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/11\/ENTREVISTA-BYN-PILAR-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/gestion-de-personas-en-el-entorno-sanitario-cuida-a-qien-te-cuida-entrevista-con-la-dra-pilar-argente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gesti\u00f3n de personas en el entorno sanitario. \u00abCuida a qi\u00e9n te cuida\u00bb Entrevista con la Dra. Pilar Argente."}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/b8162cdfab6922f38ab0c4f1a78d3993","name":"Sara Colavecchi","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png","url":"https:\/\/campusvygon.com\/es\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png","caption":"Sara Colavecchi"},"description":"Soy responsable de contenidos de la unidad de negocio Gesti\u00f3n del Dolor y Manejo de la V\u00eda A\u00e9rea. \u2022 EXPERIENCIA Me defino como una apasionada del marketing, la comunicaci\u00f3n, el dise\u00f1o y las nuevas tecnolog\u00edas. Disciplinas en las cuales me he especializado a lo largo de estos a\u00f1os, y en las que sin duda seguir\u00e9 haci\u00e9ndolo.\u00a0 Graduada en Multimedia y Artes Digitales y he realizado un master en Gesti\u00f3n Comercial y Direcci\u00f3n de Marketing. Tengo experiencia en distintos sectores, pero actualmente, estoy centrada en adquirir conocimientos\u00a0del mundo sanitario en Vygon. \u2022 PUEDO AYUDARTE EN\u2026 Mi trabajo se basa en una apuesta clara de Vygon por la formaci\u00f3n digital y el aprendizaje continuo. Puedes contactarme si buscas material digital sobre alg\u00fan procedimiento o t\u00e9cnica habitual en los servicios de Anestesia, Urgencias y Emergencias.","sameAs":["https:\/\/www.linkedin.com\/in\/saracolavecchialarcon\/"],"url":"https:\/\/campusvygon.com\/es\/author\/scolavecchi\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/29532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=29532"}],"version-history":[{"count":44,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/29532\/revisions"}],"predecessor-version":[{"id":34809,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/29532\/revisions\/34809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/29541"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=29532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/categories?post=29532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/tags?post=29532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}