{"id":43285,"date":"2024-08-19T12:30:00","date_gmt":"2024-08-19T10:30:00","guid":{"rendered":"https:\/\/campusvygon.com\/es\/?p=43285"},"modified":"2025-06-30T09:40:45","modified_gmt":"2025-06-30T07:40:45","slug":"puede-usarse-la-linea-media-como-un-cateter-central","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/","title":{"rendered":"\u00bfPuede usarse la l\u00ednea media como un cat\u00e9ter central?"},"content":{"rendered":"\n<p>Para responder a la pregunta de si una l\u00ednea media puede usarse como un cat\u00e9ter central, en primer lugar, se deben repasar las diferencias entre un <strong>PICC y<\/strong> un <strong>midline<\/strong>.&nbsp;<\/p>\n\n\n\n<p>Aunque en ambos casos son cat\u00e9teres largos, suaves y flexibles, biocompatibles insertados en venas perif\u00e9ricas (bas\u00edlica, braquiales o cef\u00e1lica), se diferencian en la punta.&nbsp;&nbsp;<\/p>\n\n\n\n<p>En el caso del <strong>PICC<\/strong>, como en cualquier otra v\u00eda central, la punta del cat\u00e9ter se coloca en la <strong>uni\u00f3n cavo-auricular<\/strong>, <strong>tercio inferior de la vena cava superio<\/strong>r (justo antes de entrar en dicha aur\u00edcula); mientras que en el <strong>midline<\/strong> la localizaci\u00f3n es en la <strong>vena axilar<\/strong> lo m\u00e1s <strong>cerca <\/strong>posible <strong>de la subclavia<\/strong> (la zona m\u00e1s distal de dicha vena axilar).&nbsp;<\/p>\n\n\n\n<p>En caso de duda sobre la correcta colocaci\u00f3n de la punta del cat\u00e9ter lo m\u00e1s sencillo es recurrir a una radiograf\u00eda que nos mostrar\u00e1 su ubicaci\u00f3n (vena cava superior en el caso de un cat\u00e9ter central, nivel de la axila para el midline).&nbsp;<\/p>\n\n\n\n<p><a>&nbsp;<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"438\" src=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/image-1024x438.png\" alt=\"\" class=\"wp-image-43286\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/image-1024x438.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/image-980x420.png 980w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/image-480x205.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Elecci\u00f3n del cat\u00e9ter. Valoraci\u00f3n proactiva&nbsp;<\/h3>\n\n\n\n<p>Al escoger el cat\u00e9ter se deben considerar las caracter\u00edsticas fisicoqu\u00edmicas del f\u00e1rmaco, ya que la medicaci\u00f3n que pueden administrar cada dispositivo es diferente.&nbsp;<\/p>\n\n\n\n<p>Debemos tener en cuenta:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Su <strong>osmolaridad<\/strong>&nbsp;<\/li>\n\n\n\n<li>Su <strong>pH<\/strong>&nbsp;<\/li>\n\n\n\n<li><strong>Si es<\/strong> o no <strong>vesicante<\/strong>&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Eligiendo una v\u00eda perif\u00e9rica o central de acuerdo con este gr\u00e1fico:&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1006\" height=\"444\" src=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/tratamiento-intravenoso.jpg\" alt=\"\" class=\"wp-image-43297\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/tratamiento-intravenoso.jpg 1006w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/tratamiento-intravenoso-980x433.jpg 980w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/tratamiento-intravenoso-480x212.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1006px, 100vw\" \/><\/figure>\n\n\n\n<p>Y la <strong>duraci\u00f3n del tratamiento<\/strong>. Pudiendo elegirse el dispositivo m\u00e1s adecuado en funci\u00f3n de lo indicado en este gr\u00e1fico:&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"930\" height=\"484\" src=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/canalizacion-cateter.jpg\" alt=\"\" class=\"wp-image-43298\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/canalizacion-cateter.jpg 930w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/canalizacion-cateter-480x250.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 930px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><a href=\"https:\/\/campusvygon.com\/es\/project\/un-vistazo-a-la-vaina-fibroblastica\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/03\/Vistazo-vaina-fibroblastica_Mesa-de-trabajo-1-1024x1024.jpg\" alt=\"\" class=\"wp-image-43287\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/03\/Vistazo-vaina-fibroblastica_Mesa-de-trabajo-1-980x980.jpg 980w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/03\/Vistazo-vaina-fibroblastica_Mesa-de-trabajo-1-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfPor qu\u00e9 es importante la localizaci\u00f3n de la punta del PICC en la VCS?&nbsp;<\/h3>\n\n\n\n<p>La <strong>punta del cat\u00e9ter <\/strong>queda colocada <strong>en paralelo a la vena sin da\u00f1arla<\/strong>, por lo que no hay riesgo de que se produzca una flebitis mec\u00e1nica. &nbsp;<br>Dejarla <strong>fuera de la CVS incrementa el riesgo de da\u00f1o en la \u00edntima<\/strong>, lo que desencadenar\u00eda la cascada de la <strong>coagulaci\u00f3n <\/strong>y favorecer\u00eda la <strong>adherencia de la vaina fibrinobl\u00e1stica<\/strong> en la punta del cat\u00e9ter, con todos los problemas que esto genera, como el <strong>no-reflujo<\/strong> o la <strong>dificultad en la infusi\u00f3n<\/strong>.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Seg\u00fan se va avanzando en el <strong>di\u00e1metro del vaso<\/strong> hay una <strong>mayor hemodiluci\u00f3n<\/strong>, por lo que las soluciones infundidas se distribuyen r\u00e1pidamente, evit\u00e1ndose la irritaci\u00f3n producida por las sustancias qu\u00edmicas administradas.&nbsp;<\/p>\n\n\n\n<p>En el caso de infusiones con un pH u osmolaridad extrema conviene seguir las indicaciones de la Infusion Nursing Society.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"896\" height=\"335\" src=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/tabla-infusion-medicamentos.jpg\" alt=\"\" class=\"wp-image-43299\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/tabla-infusion-medicamentos.jpg 896w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/08\/tabla-infusion-medicamentos-480x179.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 896px, 100vw\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfD\u00f3nde debe quedar colocada la punta dE LA L\u00cdNEA MEDIA?\u00a0<\/h3>\n\n\n\n<p>De acuerdo con las indicaciones de Nancy Moureau en su libro \u201cVessel health and preservation\u201d, <strong>la punta del midline se coloca en vena bas\u00edlica, cef\u00e1lica o braquial con una t\u00e9cnica est\u00e9ril muy parecida a la del PICC<\/strong>, con la excepci\u00f3n de que no necesita verificar la colocaci\u00f3n de la punta del cat\u00e9ter, puesto que el midline permanece en venas perif\u00e9ricas.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Para pacientes adultos y ni\u00f1os mayores la punta debe colocarse a nivel de la axila y distal al hombro. La vena axilar, donde debe instalarse la punta del midline, es la continuaci\u00f3n de las venas bas\u00edlica y braquial desde el borde inferior del m\u00fasculo redondo mayor hasta el borde superior exterior de la primera costilla, donde se convierte en subclavia.&nbsp;<\/p>\n\n\n\n<p>En el lugar en que queda la punta del midline <strong>una extravasaci\u00f3n puede suponer un riesgo ya que puede da\u00f1ar estructuras anat\u00f3micas como arterias y nervios<\/strong>, siendo m\u00e1s dif\u00edcil de detectar la extravasaci\u00f3n que en el antebrazo o en la mano.&nbsp;<\/p>\n\n\n\n<p>Algunos estudios recomiendan hacer <strong>comprobaci\u00f3n ecogr\u00e1fica a pie de cama <\/strong>durante la inserci\u00f3n, lo que reducir\u00eda la incidencia de complicaciones y prolongar\u00eda la vida \u00fatil del cat\u00e9ter.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"791\" height=\"774\" data-id=\"43291\" src=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/image-1.jpg\" alt=\"\" class=\"wp-image-43291\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/image-1.jpg 791w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/image-1-480x470.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 791px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Posibilidad de administrar irritantes mediante l\u00ednea media clavicular&nbsp;&nbsp;<\/h3>\n\n\n\n<p>El estudio llevado a cabo por el grupo de terapia intravenosa del OSI Araba, liderado por Vicky Armenteros, demuestra que <strong>la l\u00ednea media clavicular<\/strong> (midline medioclavicular) en su parte m\u00e1s distal, cerca de la vena subclavia, <strong>permite administrar f\u00e1rmacos irritantes<\/strong>, entre ellos la <strong>Vancomicina<\/strong>, f\u00e1rmaco que hasta ahora se administraba por v\u00eda venosa central.&nbsp;<\/p>\n\n\n\n<p><strong>Entonces, \u00bfpuede usarse la l\u00ednea media como un cat\u00e9ter central?&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p>No, la l\u00ednea media no puede sustituir a un cat\u00e9ter central debido a su ubicaci\u00f3n en el sistema venoso perif\u00e9rico y la menor hemodiluci\u00f3n que ofrece en comparaci\u00f3n con los cat\u00e9teres centrales. Los cat\u00e9teres centrales son esenciales para tratamientos prolongados con medicamentos de alta osmolaridad o pH extremos, donde una mayor hemodiluci\u00f3n en la vena cava superior es crucial para evitar complicaciones como flebitis y da\u00f1o venoso.&nbsp;<\/p>\n\n\n\n<p>Sin embargo, la l\u00ednea media juega un papel importante y complementario en el manejo vascular. Es \u00fatil en situaciones donde el acceso venoso es complicado o cuando se requiere una soluci\u00f3n intermedia que no justifique el uso de un cat\u00e9ter central. La l\u00ednea media puede ser adecuada para tratamientos de hasta 29 d\u00edas, reduciendo la necesidad de canulaciones repetidas y mejorando la experiencia del paciente. Seg\u00fan algunos estudios, podr\u00eda ser beneficiosa para administrar ciertos f\u00e1rmacos poco irritantes en su porci\u00f3n m\u00e1s distal, cerca de la vena subclavia, siempre y cuando se haga una cuidadosa evaluaci\u00f3n cl\u00ednica. Sin embargo, la decisi\u00f3n debe ser tomada tras una cuidadosa evaluaci\u00f3n cl\u00ednica de las caracter\u00edsticas del tratamiento y las necesidades del paciente.&nbsp;<\/p>\n\n\n\n<p>En resumen, aunque la l\u00ednea media no puede reemplazar a un cat\u00e9ter central, su uso en contextos espec\u00edficos y bien evaluados puede proporcionar una alternativa segura y eficiente, complementando el manejo integral del acceso vascular del paciente. La elecci\u00f3n entre una l\u00ednea media y un cat\u00e9ter central debe basarse en una evaluaci\u00f3n detallada de las necesidades del paciente, las caracter\u00edsticas del tratamiento y los riesgos asociados.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para responder a la pregunta de si una l\u00ednea media puede usarse como un cat\u00e9ter central, en primer lugar, se deben repasar las diferencias entre un PICC y un midline.\u00a0<\/p>\n<p>Aunque en ambos casos son cat\u00e9teres largos, suaves y flexibles, biocompatibles insertados en venas perif\u00e9ricas (bas\u00edlica, braquiales o cef\u00e1lica), se diferencian en la punta.\u00a0\u00a0<\/p>\n<p>En el caso del PICC, como en cualquier otra v\u00eda central, la punta del cat\u00e9ter se coloca en la uni\u00f3n cavo-auricular, tercio inferior de la vena cava superior (justo antes de entrar en dicha aur\u00edcula); mientras que en el midline la localizaci\u00f3n es en la vena axilar lo m\u00e1s cerca posible de la subclavia (la zona m\u00e1s distal de dicha vena axilar).<\/p>\n","protected":false},"author":181,"featured_media":45900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[80,116],"tags":[141,74,924,143,144],"class_list":["post-43285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-terapias-intravasculares","tag-acceso-vascular","tag-accesos-vasculares","tag-catetercentral","tag-linea-media","tag-midline"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u00ednea media: \u00bfPuede usarse como un cat\u00e9ter central?<\/title>\n<meta name=\"description\" content=\"La l\u00ednea media y el PICC son cat\u00e9teres perif\u00e9ricos largos; su diferencia clave es que la l\u00ednea media no llega a la vena cava superior.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00ednea media: \u00bfPuede usarse como un cat\u00e9ter central?\" \/>\n<meta property=\"og:description\" content=\"La l\u00ednea media y el PICC son cat\u00e9teres perif\u00e9ricos largos; su diferencia clave es que la l\u00ednea media no llega a la vena cava superior.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-19T10:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T07:40:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/06\/Portada-linea-media-como-cateter-central-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marian Cubero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marian Cubero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/\"},\"author\":{\"name\":\"Marian Cubero\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/b9445650ac809c60a09076e3418d084c\"},\"headline\":\"\u00bfPuede usarse la l\u00ednea media como un cat\u00e9ter central?\",\"datePublished\":\"2024-08-19T10:30:00+00:00\",\"dateModified\":\"2025-06-30T07:40:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/\"},\"wordCount\":1053,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/Portada-linea-media-como-cateter-central-scaled.jpeg\",\"keywords\":[\"acceso vascular\",\"Accesos vasculares\",\"cat\u00e9tercentral\",\"linea media\",\"midline\"],\"articleSection\":[\"Art\u00edculos\",\"Terapias Intravasculares\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/\",\"name\":\"L\u00ednea media: \u00bfPuede usarse como un cat\u00e9ter central?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/Portada-linea-media-como-cateter-central-scaled.jpeg\",\"datePublished\":\"2024-08-19T10:30:00+00:00\",\"dateModified\":\"2025-06-30T07:40:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/b9445650ac809c60a09076e3418d084c\"},\"description\":\"La l\u00ednea media y el PICC son cat\u00e9teres perif\u00e9ricos largos; su diferencia clave es que la l\u00ednea media no llega a la vena cava superior.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/Portada-linea-media-como-cateter-central-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/06\\\/Portada-linea-media-como-cateter-central-scaled.jpeg\",\"width\":2560,\"height\":1709,\"caption\":\"L\u00ednea media prevenci\u00f3n y complicaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/puede-usarse-la-linea-media-como-un-cateter-central\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPuede usarse la l\u00ednea media como un cat\u00e9ter central?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/b9445650ac809c60a09076e3418d084c\",\"name\":\"Marian Cubero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/07\\\/marian-cubero.jpg\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/07\\\/marian-cubero.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/07\\\/marian-cubero.jpg\",\"caption\":\"Marian Cubero\"},\"description\":\"Referente ETI Hospital Universitario Cl\u00ednico San Carlos\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/author\\\/mariancuberos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00ednea media: \u00bfPuede usarse como un cat\u00e9ter central?","description":"La l\u00ednea media y el PICC son cat\u00e9teres perif\u00e9ricos largos; su diferencia clave es que la l\u00ednea media no llega a la vena cava superior.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/","og_locale":"es_ES","og_type":"article","og_title":"L\u00ednea media: \u00bfPuede usarse como un cat\u00e9ter central?","og_description":"La l\u00ednea media y el PICC son cat\u00e9teres perif\u00e9ricos largos; su diferencia clave es que la l\u00ednea media no llega a la vena cava superior.","og_url":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/","og_site_name":"Campus Vygon Espa\u00f1a","article_published_time":"2024-08-19T10:30:00+00:00","article_modified_time":"2025-06-30T07:40:45+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/06\/Portada-linea-media-como-cateter-central-scaled.jpeg","type":"image\/jpeg"}],"author":"Marian Cubero","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marian Cubero","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/"},"author":{"name":"Marian Cubero","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/b9445650ac809c60a09076e3418d084c"},"headline":"\u00bfPuede usarse la l\u00ednea media como un cat\u00e9ter central?","datePublished":"2024-08-19T10:30:00+00:00","dateModified":"2025-06-30T07:40:45+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/"},"wordCount":1053,"commentCount":0,"image":{"@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/06\/Portada-linea-media-como-cateter-central-scaled.jpeg","keywords":["acceso vascular","Accesos vasculares","cat\u00e9tercentral","linea media","midline"],"articleSection":["Art\u00edculos","Terapias Intravasculares"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/","url":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/","name":"L\u00ednea media: \u00bfPuede usarse como un cat\u00e9ter central?","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/06\/Portada-linea-media-como-cateter-central-scaled.jpeg","datePublished":"2024-08-19T10:30:00+00:00","dateModified":"2025-06-30T07:40:45+00:00","author":{"@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/b9445650ac809c60a09076e3418d084c"},"description":"La l\u00ednea media y el PICC son cat\u00e9teres perif\u00e9ricos largos; su diferencia clave es que la l\u00ednea media no llega a la vena cava superior.","breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/06\/Portada-linea-media-como-cateter-central-scaled.jpeg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/06\/Portada-linea-media-como-cateter-central-scaled.jpeg","width":2560,"height":1709,"caption":"L\u00ednea media prevenci\u00f3n y complicaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/puede-usarse-la-linea-media-como-un-cateter-central\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfPuede usarse la l\u00ednea media como un cat\u00e9ter central?"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/b9445650ac809c60a09076e3418d084c","name":"Marian Cubero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/marian-cubero.jpg","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/marian-cubero.jpg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/07\/marian-cubero.jpg","caption":"Marian Cubero"},"description":"Referente ETI Hospital Universitario Cl\u00ednico San Carlos","url":"https:\/\/campusvygon.com\/es\/author\/mariancuberos\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/43285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/181"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=43285"}],"version-history":[{"count":4,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/43285\/revisions"}],"predecessor-version":[{"id":45902,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/43285\/revisions\/45902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/45900"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=43285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/categories?post=43285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/tags?post=43285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}