{"id":5880,"date":"2019-05-02T12:43:19","date_gmt":"2019-05-02T10:43:19","guid":{"rendered":"http:\/\/campusvygon.com\/es\/?p=5880"},"modified":"2025-09-28T10:27:46","modified_gmt":"2025-09-28T08:27:46","slug":"cateter-linea-media-midline","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/","title":{"rendered":"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es?"},"content":{"rendered":"\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link\" href=\"http:\/\/campusvygon.com\/es\/ebook-el-cateter-de-linea-media-nociones-basicas-sobre-indicaciones-y-tecnicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Descarga el Ebook \u00abEl cat\u00e9ter midline: nociones b\u00e1sicos sobre t\u00e9cnicas y procedimientos\u00bb<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El cat\u00e9ter corto es una v\u00eda de corta duraci\u00f3n que permite la perfusi\u00f3n de tratamientos con una duraci\u00f3n &lt; 7 d\u00edas. Para un tratamiento superior y por las limitaciones que supone es necesario considerar una alternativa que permita al profesional sanitario no irse a una v\u00eda central, recurso innecesario para una terpapia perif\u00e9rica.<\/p>\n\n\n\n<p>El cat\u00e9ter de l\u00ednea media representa hoy en d\u00eda la mejor soluci\u00f3n en estos contextos y tambi\u00e9n para pacientes DIVA (con muy poco acceso venoso). En este post te explicamos qu\u00e9 es.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Si solo le puedes dedicar muy poco tiempo a este art\u00edculo, ah\u00ed va un resumen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>al ser de material m\u00e1s duradero  (poliuretano) permite mantener la misma v\u00eda para todo el tratamiento<\/li><li>su t\u00e9cnica de inserci\u00f3n  (Seldinger) es poco invasiva y reduce las complicaciones inmediatas<\/li><li>la ecografia que acompa\u00f1a la inserci\u00f3n permite elegir la mejor vena y adecuar el di\u00e1metro del cat\u00e9ter a la vena. Lo cual reduce las complicaciones como la flebitis y la trombosis<\/li><li>al ser un cat\u00e9ter insertado en venas profundas alcanza un flujo importante que permite una administraci\u00f3n adecuada de la medicaci\u00f3n.<\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La <strong>l\u00ednea media<\/strong> es un cat\u00e9ter <strong>venoso <\/strong>cuya longitud puede variar entre <strong>4 y 30 cm<\/strong>.<\/p>\n\n\n\n<p>Su inserci\u00f3n es <strong>perif\u00e9rica <\/strong>y alcanza venas de<strong> di\u00e1metros importantes<\/strong>, ya que se introduce en el <strong>brazo <\/strong>(y no en el antebrazo, como en el caso del cat\u00e9ter corto). La inserci\u00f3n se hace con t\u00e9cnica <strong>Seldinger <\/strong>o <strong>MicroSeldinger <\/strong>(MST).<br>Est\u00e1 fabricado en <strong>Poliuretano <\/strong>de <strong>clase IIa <\/strong>(un mes de duraci\u00f3n) o <strong>de clase III<\/strong> (duraci\u00f3n superior a un mes), material conocido por tener una elevada biocompatibilidad, lo que se traduce en un <strong>menor riesgo de lesionar la \u00edntima venosa<\/strong> y una<strong> alta resistencia qu\u00edmica<\/strong>, por lo que los f\u00e1rmacos no lo debilitan.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><a href=\"http:\/\/campusvygon.com\/es\/accesos-vasculares-media-larga-duracion\/\">   <\/a><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/corp-avec-veines-midline\/\" rel=\"attachment wp-att-18045\"><img decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Corp-avec-veines-midline.png\" alt=\"\" class=\"wp-image-18045\" height=\"700\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Corp-avec-veines-midline.png 596w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Corp-avec-veines-midline-222x300.png 222w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Corp-avec-veines-midline-247x335.png 247w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/><\/a><\/figure><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La <strong>l\u00ednea media<\/strong> se inserta por encima de la fosa antecubital (en vena bas\u00edlica o cef\u00e1lica) y llega hasta la<strong> vena axilar<\/strong>: la punta se queda a una distancia media entre una localizaci\u00f3n perif\u00e9rica y una localizaci\u00f3n central. <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"beneficios-de-la-linea-media\">Beneficios de la l\u00ednea media<\/h2>\n\n\n\n<p>Seg\u00fan las gu\u00edas de buenas pr\u00e1cticas, los f\u00e1rmacos que no son vesicantes ni hiperosmolares se deben administrar por v\u00eda perif\u00e9rica ya que no necesitan tener la vena cava superior como punto de entrada en la circulaci\u00f3n.<br>Frente a las<strong> limitaciones del cat\u00e9ter corto perif\u00e9rico<\/strong>, la l\u00ednea media permite un acceso vascular perif\u00e9rico que facilita el acceso a un calibre de vena suficiente grande como para evitar las complicaciones relacionadas con una localizaci\u00f3n muy perif\u00e9rica de la punta del cat\u00e9ter (flebitis, extravasaci\u00f3n).<\/p>\n\n\n\n<p>Se trata de un cat\u00e9ter que ofrece una mayor durabilidad y as\u00ed se pueden reducir los pinchazos.<\/p>\n\n\n\n<p>Ofrece una t\u00e9cnica de inserci\u00f3n lo menos invasiva posible, lo que ayuda a prevenir las complicaciones tempranas: edema, hematoma, malfuncionamiento del cat\u00e9ter, etc.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/midline-que-es1b\/\" rel=\"attachment wp-att-18046\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es1b.png\" alt=\"\" class=\"wp-image-18046\" width=\"700\" height=\"700\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es1b.png 1000w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es1b-300x300.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es1b-150x150.png 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es1b-768x768.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es1b-70x70.png 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es1b-335x335.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es1b-360x360.png 360w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Para terapias no hiperosmolares y con pH entre 5 y 9, superiores a 6 d\u00edas, las gu\u00edas internacionales recomiendan el uso de la l\u00ednea media.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"colocacion-de-una-linea-media\">Colocaci\u00f3n de una l\u00ednea media<\/h2>\n\n\n\n<p>Una l\u00ednea media se inserta con t\u00e9cnica Seldinger: es conocida en las UCI por ser el m\u00e9todo de introducci\u00f3n de las v\u00edas centrales y de los cat\u00e9teres arteriales.<br>La t\u00e9cnica Seldinger puede ser pura, simplificada o modificada.<br>Para ello, se necesita:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>una aguja de punci\u00f3n fina, en general de 21G<\/li><li>una gu\u00eda de acero inoxidable o de nitinol (material antiacodamiento)<\/li><li>un dilatador que sirve \u00fanicamente para la dilataci\u00f3n o<\/li><li>un microintroductor que consta de una vaina pelable y de in dilatador interno.<\/li><\/ul>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/intro-seldinger\/\" rel=\"attachment wp-att-18047\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/intro-Seldinger.jpg\" alt=\"\" class=\"wp-image-18047\" width=\"700\" height=\"700\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/intro-Seldinger.jpg 1000w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/intro-Seldinger-300x300.jpg 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/intro-Seldinger-150x150.jpg 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/intro-Seldinger-768x768.jpg 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/intro-Seldinger-70x70.jpg 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/intro-Seldinger-335x335.jpg 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/intro-Seldinger-360x360.jpg 360w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En este video podemos ver la colocaci\u00f3n mediante la t\u00e9cnica Seldinger m\u00e1s sencilla: la Seldinger simplificada, para la que no se necesita dilatador. Especialmente indicada en pediatr\u00eda ya que es r\u00e1pida y muy poco invasiva<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.youtube.com\/watch?v=otS8gPwJkL4\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/09\/enlace-a-video-youtube.jpg\" alt=\"\" class=\"wp-image-28333\" width=\"700\" srcset=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/09\/enlace-a-video-youtube.jpg 908w, http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2021\/09\/enlace-a-video-youtube-480x287.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 908px, 100vw\" \/><\/a><\/figure><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La ventaja de cualquiera de las t\u00e9cnicas Seldinger es que la aguja sirve solo para localizar la vena. La gu\u00eda sirve para canalizar la vena y guiar el cat\u00e9ter. Se trata de la t\u00e9cnica \u201cover the wire\u201d = encima de la gu\u00eda. Al no tener el cat\u00e9ter junto a la aguja, no se necesita canalizar en el momento de la punci\u00f3n, significa que el gesto se hace en varias etapas y de esta forma es mucho menos invasivo.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/midline-que-es2\/\" rel=\"attachment wp-att-18048\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es2.png\" alt=\"\" class=\"wp-image-18048\" width=\"700\" height=\"700\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es2.png 1000w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es2-300x300.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es2-150x150.png 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es2-768x768.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es2-70x70.png 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es2-335x335.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es2-360x360.png 360w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Se usa una aguja de calibre peque\u00f1o para poder minimizar el trauma a los tejidos. Sin embargo, el uso del dilatador es necesario cuando el di\u00e1metro del cat\u00e9ter es superior al orificio que crea la aguja. Sirve para ensanchar el paso subcut\u00e1neo.<br>\u2022 La t\u00e9cnica Seldinger pura es la t\u00e9cnica con dilataci\u00f3n<\/p>\n\n\n\n<p>\u2022 La t\u00e9cnica Seldinger simplificada es la t\u00e9cnica sin dilataci\u00f3n<\/p>\n\n\n\n<p>\u2022 La t\u00e9cnica Seldinger modificada (o MicroSeldinger) es la t\u00e9cnica con introductor pelable, que lleva en su interior un dilatador que se deja. Entonces se quita la gu\u00eda y el dilatador interno. De esta forma, el introductor sirve de gu\u00eda para insertar el cat\u00e9ter.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ventaja-adicional-del-cateter-de-linea-media\">Ventaja adicional del cat\u00e9ter de l\u00ednea media<\/h2>\n\n\n\n<p>Si lo comparamos con el cat\u00e9ter corto, el cat\u00e9ter de l\u00ednea media se presenta con un prolongador integrado. Esto minimiza los riesgos de flebitis mec\u00e1nica o bacteriana as\u00ed como el riesgo de infecci\u00f3n por tener que manipular el cat\u00e9ter a distancia del punto de inserci\u00f3n.<\/p>\n\n\n\n<p>Cat\u00e9ter de l\u00ednea media<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"102\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Cat-de-linea-media-300x102.png\" alt=\"\" class=\"wp-image-5876\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Cat-de-linea-media-300x102.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Cat-de-linea-media.png 576w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"227\" height=\"222\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Cat\u00e9ter-corto.png\" alt=\"\" class=\"wp-image-5877\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Cat\u00e9ter-corto.png 227w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Cat\u00e9ter-corto-52x50.png 52w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Cat\u00e9ter-corto-66x66.png 66w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\">Cat\u00e9ter corto perif\u00e9rico&nbsp;<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"puncion-con-ecografia\">Punci\u00f3n con ecograf\u00eda<\/h2>\n\n\n\n<p>Cuando se trata de una l\u00ednea media es necesario usar un ec\u00f3grafo para poder visualizar las venas y proceder a la inserci\u00f3n, ya que los vasos de primera elecci\u00f3n son profundos (vena bas\u00edlica o vena cef\u00e1lica).<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"153\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Punci\u00f3n-1-300x153.png\" alt=\"\" class=\"wp-image-5882\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Punci\u00f3n-1-300x153.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Punci\u00f3n-1-768x391.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Punci\u00f3n-1.png 814w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"238\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Punci\u00f3n2-300x238.png\" alt=\"\" class=\"wp-image-5883\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Punci\u00f3n2-300x238.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/Punci\u00f3n2.png 621w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\"> 6<br><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La ecograf\u00eda es muy utilizada y recomendada para todo tipo de v\u00edas centrales: reservorios, PICCS, centrales; as\u00ed como para las l\u00edneas medias. Al hacer visible las venas y su recorrido, permite aumentar mucho la tasa de \u00e9xito en el primer intento (del 77% al 99%).<br>Adem\u00e1s, el ec\u00f3grafo permite medir el calibre de las venas, lo que da la ventaja de elegir el di\u00e1metro adecuado del cat\u00e9ter respecto a la vena elegida. Cualquier cat\u00e9ter tiene que ocupar solo 1\/3 de la luz de la vena.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nuestra-recomendacion\">Nuestra recomendaci\u00f3n<\/h2>\n\n\n\n<p>Respecto a la administraci\u00f3n de f\u00e1rmacos<strong> no irritantes por v\u00eda perif\u00e9rica<\/strong>, <strong>el cat\u00e9ter corto es \u00fatil para terapias de muy corta duraci\u00f3n<\/strong>. Para terapias <strong>prolongadas<\/strong>, la<strong> l\u00ednea media<\/strong> ofrece las siguientes ventajas las ventajas:<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><a href=\"http:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/midline-que-es3\/\" rel=\"attachment wp-att-18049\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es3.png\" alt=\"\" class=\"wp-image-18049\" width=\"700\" height=\"700\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es3.png 1000w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es3-300x300.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es3-150x150.png 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es3-768x768.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es3-70x70.png 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es3-335x335.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2019\/05\/midline-que-es3-360x360.png 360w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"bibliografia\">bibliograf\u00eda<\/h3>\n\n\n\n<ol class=\"wp-block-list\"><li>Jill Anderson et.al, <a href=\"https:\/\/cardiomed.com\/wp-content\/uploads\/sites\/7\/2018\/06\/Extended-Dwell-PIV-in-Paeds-JAVA-Sept-2016.pdf\">Comparison of Outcomes of Extended Dwell\/Midline Peripheral Intravenous Catheters and Peripherally Inserted Central Catheters in Children<\/a>, Journal of the Association for Vascular Access Volume 21, Issue 3, Pages 158-164 &#8211; September 2016<\/li><li>Giancarlo Scoppettuolo et.al, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC4742453\/\">Ultrasound-guided \u201cshort\u201d midline catheters for difficult venous access in the emergency department: a retrospective analysis<\/a>, International Journal of Emergency Medicine &#8211; 2016<\/li><li>Stokowski et.al, <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/19444022\/\">The use of ultrasound to improve practice and reduce complication rates in peripherally inserted central catheter insertions: final report of investigation<\/a>, J Infus Nurs. May-Jun;32(3):145-55 &#8211; 2009<\/li><li>Daniel Z. Adams et.al, <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/27397766\/\">The Midline Catheter: A Clinical Review<\/a>, J Emerg Med. 51(3):252-8 &#8211; 2016<\/li><li>Sarah Y. Qian et.al, <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/25041922\/\">The use of 8-cm 22G Seldinger catheters for intravenous access in children with cystic fibrosis<\/a>, J Vasc Access. ;15(5):415-7 &#8211; 2014<\/li><li><a href=\"https:\/\/www.cdc.gov\/infectioncontrol\/guidelines\/bsi\/recommendations.html\">CDC guidelines<\/a> &#8211; 2011<\/li><\/ol>\n\n\n\n<p><\/p>\n\n\n\n<p>Si quieres saber m\u00e1s acerca\u00a0 de las l\u00edneas medias, deja un comentario<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cat\u00e9ter corto es una v\u00eda de corta duraci\u00f3n que permite la perfusi\u00f3n de tratamientos con una duraci\u00f3n &lt; 7 d\u00edas. Para un tratamiento superior y por las limitaciones que supone es necesario considerar una alternativa que permita al profesional sanitario no irse a una v\u00eda central, recurso innecesario para una terpapia perif\u00e9rica. El cat\u00e9ter [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":47906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[116],"tags":[67,143,144,132,145],"class_list":["post-5880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-terapias-intravasculares","tag-cateter","tag-linea-media","tag-midline","tag-seldinger","tag-terapia-prolongada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es? - Campus Vygon Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Frente a las limitaciones del cat\u00e9ter corto, descubre el cat\u00e9ter midline, un recurso imprescindible para tratamientos intravenosos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es? - Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Frente a las limitaciones del cat\u00e9ter corto, descubre el cat\u00e9ter midline, un recurso imprescindible para tratamientos intravenosos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-02T10:43:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-28T08:27:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-Midline-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marie Pineau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie Pineau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/\"},\"author\":{\"name\":\"Marie Pineau\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/3115f9edfc217688bdca3dcb2a969787\"},\"headline\":\"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es?\",\"datePublished\":\"2019-05-02T10:43:19+00:00\",\"dateModified\":\"2025-09-28T08:27:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/\"},\"wordCount\":1307,\"commentCount\":27,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-Midline-scaled.jpeg\",\"keywords\":[\"cat\u00e9ter\",\"linea media\",\"midline\",\"Seldinger\",\"terapia prolongada\"],\"articleSection\":[\"Terapias Intravasculares\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/\",\"name\":\"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es? - Campus Vygon Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-Midline-scaled.jpeg\",\"datePublished\":\"2019-05-02T10:43:19+00:00\",\"dateModified\":\"2025-09-28T08:27:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/3115f9edfc217688bdca3dcb2a969787\"},\"description\":\"Frente a las limitaciones del cat\u00e9ter corto, descubre el cat\u00e9ter midline, un recurso imprescindible para tratamientos intravenosos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-Midline-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-Midline-scaled.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/cateter-linea-media-midline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/3115f9edfc217688bdca3dcb2a969787\",\"name\":\"Marie Pineau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/12\\\/mpineau-150x150.jpg\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/12\\\/mpineau-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/12\\\/mpineau-150x150.jpg\",\"caption\":\"Marie Pineau\"},\"description\":\"Soy responsable de contenidos de las unidades de negocio de Terapias Intravasculares y Obstetricia-Neonatolog\u00eda-Nutrici\u00f3n enteral en Vygon Espa\u00f1a \u2022 EXPERIENCIA He podido ejercer como enfermera durante varios a\u00f1os al principio de mi carrera, en m\u00faltiples \u00e1mbitos, entre otros como la neonatolog\u00eda, la pediatr\u00eda, la medicina interna y la cirug\u00eda. Desde mi llegada en Vygon en el a\u00f1o 2010, he podido desarrollar competencias en el terreno y adquirir conocimiento sobre productos, desarrollando una labor marketing y comercial. \u2022 PUEDO AYUDARTE EN\u2026 Resolver dudas sobre productos y sus aplicaciones ya que mi perfil combina a la vez marketing, comunicaci\u00f3n y pr\u00e1ctica cl\u00ednica Encontrar material digital sobre protocolos y t\u00e9cnicas as\u00ed como literatura existentes en terapia intravascular, tambi\u00e9n en neonatolog\u00eda, obstetricia y nutrici\u00f3n enteral.\",\"sameAs\":[\"https:\\\/\\\/www.vygon.es\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/marie-pineau\\\/\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/author\\\/mpineau\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es? - Campus Vygon Espa\u00f1a","description":"Frente a las limitaciones del cat\u00e9ter corto, descubre el cat\u00e9ter midline, un recurso imprescindible para tratamientos intravenosos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/","og_locale":"es_ES","og_type":"article","og_title":"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es? - Campus Vygon Espa\u00f1a","og_description":"Frente a las limitaciones del cat\u00e9ter corto, descubre el cat\u00e9ter midline, un recurso imprescindible para tratamientos intravenosos.","og_url":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/","og_site_name":"Campus Vygon Espa\u00f1a","article_published_time":"2019-05-02T10:43:19+00:00","article_modified_time":"2025-09-28T08:27:46+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-Midline-scaled.jpeg","type":"image\/jpeg"}],"author":"Marie Pineau","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Marie Pineau","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/"},"author":{"name":"Marie Pineau","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/3115f9edfc217688bdca3dcb2a969787"},"headline":"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es?","datePublished":"2019-05-02T10:43:19+00:00","dateModified":"2025-09-28T08:27:46+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/"},"wordCount":1307,"commentCount":27,"image":{"@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-Midline-scaled.jpeg","keywords":["cat\u00e9ter","linea media","midline","Seldinger","terapia prolongada"],"articleSection":["Terapias Intravasculares"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/","url":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/","name":"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es? - Campus Vygon Espa\u00f1a","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-Midline-scaled.jpeg","datePublished":"2019-05-02T10:43:19+00:00","dateModified":"2025-09-28T08:27:46+00:00","author":{"@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/3115f9edfc217688bdca3dcb2a969787"},"description":"Frente a las limitaciones del cat\u00e9ter corto, descubre el cat\u00e9ter midline, un recurso imprescindible para tratamientos intravenosos.","breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-Midline-scaled.jpeg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-Midline-scaled.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/cateter-linea-media-midline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"El cat\u00e9ter de l\u00ednea media o Midline \u00bfQu\u00e9 es?"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/3115f9edfc217688bdca3dcb2a969787","name":"Marie Pineau","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/12\/mpineau-150x150.jpg","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/12\/mpineau-150x150.jpg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/12\/mpineau-150x150.jpg","caption":"Marie Pineau"},"description":"Soy responsable de contenidos de las unidades de negocio de Terapias Intravasculares y Obstetricia-Neonatolog\u00eda-Nutrici\u00f3n enteral en Vygon Espa\u00f1a \u2022 EXPERIENCIA He podido ejercer como enfermera durante varios a\u00f1os al principio de mi carrera, en m\u00faltiples \u00e1mbitos, entre otros como la neonatolog\u00eda, la pediatr\u00eda, la medicina interna y la cirug\u00eda. Desde mi llegada en Vygon en el a\u00f1o 2010, he podido desarrollar competencias en el terreno y adquirir conocimiento sobre productos, desarrollando una labor marketing y comercial. \u2022 PUEDO AYUDARTE EN\u2026 Resolver dudas sobre productos y sus aplicaciones ya que mi perfil combina a la vez marketing, comunicaci\u00f3n y pr\u00e1ctica cl\u00ednica Encontrar material digital sobre protocolos y t\u00e9cnicas as\u00ed como literatura existentes en terapia intravascular, tambi\u00e9n en neonatolog\u00eda, obstetricia y nutrici\u00f3n enteral.","sameAs":["https:\/\/www.vygon.es\/","https:\/\/www.linkedin.com\/in\/marie-pineau\/"],"url":"https:\/\/campusvygon.com\/es\/author\/mpineau\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/5880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=5880"}],"version-history":[{"count":25,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/5880\/revisions"}],"predecessor-version":[{"id":34603,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/5880\/revisions\/34603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/47906"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=5880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/categories?post=5880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/tags?post=5880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}