{"id":7667,"date":"2020-05-15T13:03:00","date_gmt":"2020-05-15T11:03:00","guid":{"rendered":"http:\/\/campusvygon.com\/es\/?p=7667"},"modified":"2025-09-30T18:56:38","modified_gmt":"2025-09-30T16:56:38","slug":"las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/","title":{"rendered":"Las recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19"},"content":{"rendered":"<a href='#' class='small-button smallblue'>Descarga en pdf<\/a>\n<hr \/>\n<p>Las asociaciones y sociedades cient\u00edficas internacionales presentan cada cierto tiempo sus <a href=\"http:\/\/campusvygon.com\/es\/recomendaciones-sobre-rcp\/\" target=\"_blank\" rel=\"noopener noreferrer\">gu\u00edas y recomendaciones para RCP<\/a> actualizadas seg\u00fan la evidencia cient\u00edfica. Sin embargo, la crisis sanitaria que estamos viviendo les ha obligado a preparar unas <strong>gu\u00edas espec\u00edficas de RCP para hacer frente al COVID-19<\/strong>. Algunas de estas recomendaciones, que se centran en garantizar la seguridad de los profesionales sanitarios, puede que hayan llegado para quedarse.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"wVEUZO71D3\"><p><a href=\"https:\/\/campusvygon.com\/es\/bcard\/\">bcard<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;bcard&#8221; &#8212; Campus Vygon Espa\u00f1a\" src=\"https:\/\/campusvygon.com\/es\/bcard\/embed\/#?secret=a6yy21byeP#?secret=wVEUZO71D3\" data-secret=\"wVEUZO71D3\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Los expertos de la <a href=\"https:\/\/www.heart.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Heart Association<\/a> explican que los riesgos que la RCP en tiempos de COVID supone para los profesionales sanitarios son:<\/p>\n<ul>\n<li>La RCP implica la pr\u00e1ctica de varios <strong>procedimientos que generan aerosoles<\/strong> en el paciente. Estas part\u00edculas v\u00edricas quedan suspendidas en el aire durante aproximadamente una hora y pueden ser inhaladas por quienes se encuentren cerca. Estos son los procedimientos de riesgo:\n<ul>\n<li>las cardio compresiones<\/li>\n<li>la ventilaci\u00f3n de presi\u00f3n positiva<\/li>\n<li>la intubaci\u00f3n<\/li>\n<\/ul>\n<\/li>\n<li>Las t\u00e9cnicas de RCP requieren la <strong>participaci\u00f3n de varios intervinientes<\/strong>, todos ellos, en contacto o muy cerca del paciente.<\/li>\n<li>Adem\u00e1s, las RCP suelen contar con el <strong>factor de estr\u00e9s y tensi\u00f3n<\/strong> por la emergencia y las necesidades inmediatas del paciente que requiere reanimaci\u00f3n. Esto puede dar lugar a <strong>lapsos en las pr\u00e1cticas de control de infecciones<\/strong>.<\/li>\n<\/ul>\n<p>Vistos estos riesgos, vamos a repasar las especificaciones que la American Heart Association y el <a href=\"https:\/\/www.resus.org.uk\/\" target=\"_blank\" rel=\"noopener noreferrer\">Resuscitation Council UK<\/a> hacen para la reanimaci\u00f3n cardio pulmonar en tiempos de COVID:<\/p>\n<h3><strong>Recomendaciones de AHA sobre RCP en tiempos de COVID-19<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7695 aligncenter\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/1200px-American_Heart_Association_Logo.svg_-300x180.png\" alt=\"\" width=\"300\" height=\"180\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/1200px-American_Heart_Association_Logo.svg_-300x180.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/1200px-American_Heart_Association_Logo.svg_-1024x615.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/1200px-American_Heart_Association_Logo.svg_-768x461.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/1200px-American_Heart_Association_Logo.svg_-335x201.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/1200px-American_Heart_Association_Logo.svg_.png 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: left\">En la publicaci\u00f3n <em><a href=\"https:\/\/www.ahajournals.org\/doi\/10.1161\/CIRCULATIONAHA.120.047463\" target=\"_blank\" rel=\"noopener noreferrer\">Interim Guidance for Basic and Advanced Life Support in Adults, Children, and Neonates With Suspected or Confirmed COVID-19<\/a>, <\/em>publicada en colaboraci\u00f3n con la <a href=\"https:\/\/www.aap.org\/en-us\/Pages\/Default.aspx\" target=\"_blank\" rel=\"noopener noreferrer\">American Academy of Pediatrics<\/a>, la <a href=\"https:\/\/www.aarc.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Association for Respiratory Care<\/a>, el <a href=\"https:\/\/www.acep.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American College of Emergency Physicians<\/a>, <a href=\"https:\/\/socca.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">The Society of Critical Care Anesthesiologists<\/a>, y la <a href=\"https:\/\/www.asahq.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Society of Anesthesiologists<\/a> y con el apoyo de la <a href=\"https:\/\/www.aacn.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Association of Critical Care Nurses<\/a> y <a href=\"https:\/\/naemsp.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">National EMS Physicians<\/a>, AHA recopila las <strong>gu\u00edas principales para hacer frente a los retos que presenta la pandemia del Coronavirus en la ciencia de la resucitaci\u00f3n<\/strong>.<\/p>\n<p>Seg\u00fan AHA, en las \u00faltimas dos d\u00e9cadas ha habido una gran mejora en los \u00edndices de supervivencia a una parada cardiaca tanto intra como extrahospitalaria. Esto se debe al inicio r\u00e1pido (en pocos segundos o minutos) de las cardio compresiones de calidad y la desfibrilaci\u00f3n. Sin embargo, <strong>la situaci\u00f3n actual<\/strong> supone grandes retos y <strong>requiere modificaciones en los procedimientos y pr\u00e1cticas establecidas para garantizar la seguridad de los profesionales sanitarios<\/strong>. Estas son las gu\u00edas que propone la sociedad cient\u00edfica americana:<\/p>\n<ul>\n<li><strong>Limitar la exposici\u00f3n de los profesionales al virus<\/strong>\n<ul>\n<li>Colocaci\u00f3n del EPI adecuado antes de entrar en escena<\/li>\n<li>Limitar el personal <em>en la escena<\/em><\/li>\n<li>Considerar el uso de un dispositivo de cardio compresi\u00f3n mec\u00e1nica para adultos y adolescentes que cumplan con los criterios de peso y estatura.<\/li>\n<li>Comunicar a cualquier nuevo interviniente la situaci\u00f3n de riesgo ante COVID-19.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Priorizar las estrategias de oxigenaci\u00f3n y ventilaci\u00f3n con el m\u00ednimo riesgo de generar aerosoles<\/strong>\n<ul>\n<li>Utilizar un filtro HEPA para la ventilaci\u00f3n.<\/li>\n<li>Utilizar la t\u00e9cnica de intubaci\u00f3n con la mayor probabilidad de \u00e9xito en el primer intento.<\/li>\n<li>Intubar r\u00e1pido con un tubo con manguito, si es posible, y conectar a un ventilador mec\u00e1nico, cuando sea posible.<\/li>\n<li>Detener las compresiones tor\u00e1cicas para intubar<\/li>\n<li>Considerar el uso de la videolaringoscopia, si est\u00e1 disponible.<\/li>\n<li>Para los adultos, considerar la oxigenaci\u00f3n pasiva con una m\u00e1scarilla facial no respiratoria como alternativa al dispositivo bal\u00f3n-m\u00e1scara.<\/li>\n<li>Si la intubaci\u00f3n se retrasa, considere el dispositivo supragl\u00f3tico.<\/li>\n<li>Minimizar las desconexiones de los circuitos cerrados.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Valorar la conveniencia de la reanimaci\u00f3n<\/strong>\n<ul>\n<li>Abordar los objetivos de la atenci\u00f3n.<\/li>\n<li>Adoptar pol\u00edticas para orientar la determinaci\u00f3n, teniendo en cuenta los factores de riesgo del paciente para la supervivencia.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3><strong>Recomendaciones del European Resuscitation Council (ERC) sobre RCP en tiempos de COVID-19<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8143 aligncenter\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/logo-300x89.png\" alt=\"\" width=\"300\" height=\"89\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/logo-300x89.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/logo-335x99.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/logo-700x208.png 700w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/logo.png 702w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Las recomendaciones del <a href=\"https:\/\/www.erc.edu\/\" target=\"_blank\" rel=\"noopener noreferrer\">European Resuscitation Council (ERC)<\/a> van en la misma l\u00ednea que las de sus hom\u00f3logos americanos: garantizar la seguridad de los profesionales sanitarios. Las <a href=\"\/Users\/aperez\/Desktop\/ERC_covid19_pages.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">gu\u00edas espec\u00edficas para RCP en tiempos de COVID-19 del ERC<\/a> dicen, en el caso del <strong>Soporte Vital B\u00e1sico (SVB)<\/strong>:<\/p>\n<ul>\n<li>Los equipos que atienden a los pacientes con paro card\u00edaco (tanto en el hospital como fuera de \u00e9l) deber\u00edan estar compuestos \u00fanicamente por trabajadores sanitarios con acceso y capacitaci\u00f3n en el uso de los equipos de protecci\u00f3n personal (EPI).<\/li>\n<li>Es poco probable que aplicaci\u00f3n de una descarga de un desfibrilador genere aerosoles.<\/li>\n<li>Se debe reconocer el paro card\u00edaco buscando la ausencia de signos de vida y la ausencia de respiraci\u00f3n normal.<\/li>\n<li>Los profesionales de la salud deben utilizar siempre el EPI de protecci\u00f3n de la v\u00eda a\u00e9rea para los procedimientos con aerosoles como las compresiones tor\u00e1cicas, las intervenciones en las v\u00edas respiratorias y de ventilaci\u00f3n) durante la reanimaci\u00f3n.<\/li>\n<li>Realizar compresiones tor\u00e1cicas y ventilaci\u00f3n con una bal\u00f3n-m\u00e1scara y ox\u00edgeno a 30:2, deteniendo las compresiones tor\u00e1cicas durante las ventilaciones para minimizar el riesgo de aerosolizaci\u00f3n. Los <strong>equipos de SVB menos formados en la ventilaci\u00f3n bal\u00f3n-m\u00e1scara no deben proporcionar ventilaci\u00f3n de bal\u00f3n-m\u00e1scara debido al riesgo de generaci\u00f3n de aerosoles<\/strong>. Estos los equipos <strong>deben colocar una mascarilla de ox\u00edgeno en la cara del paciente, dar ox\u00edgeno y proporcionar RCP s\u00f3lo por compresi\u00f3n<\/strong>.<\/li>\n<li>Usar un filtro de aire de part\u00edculas de alta eficiencia (HEPA) o un intercambiador de calor y humedad (HME) entre el bal\u00f3n autoinflable y la mascarilla para minimizar el riesgo de propagaci\u00f3n del virus.<\/li>\n<li>Usar las dos manos para sostener la mascarilla y asegurar un buen sellado para la ventilaci\u00f3n del bal\u00f3n-m\u00e1scara. Esto requiere un segundo rescatador (la persona que realiza las compresiones puede apretar el bal\u00f3n cuando se haga la pausa, despu\u00e9s de cada 30 compresiones).<\/li>\n<li>Aplique un desfibrilador y siga las instrucciones que est\u00e9n disponibles.<\/li>\n<\/ul>\n<p>En el caso del <strong>Soporte Vital Avanzado (SVA)<\/strong>, tanto intra como extra hospitalaria, las gu\u00edas recomiendan:<\/p>\n<ul>\n<li>En el caso de los pacientes para los que la reanimaci\u00f3n ser\u00eda inapropiada, las decisiones deben ser tomadas y comunicadas. Los pacientes con insuficiencia respiratoria grave por COVID-19 no aptos para la intubaci\u00f3n endotraqueal y la ventilaci\u00f3n mec\u00e1nica tienen muy pocas probabilidades de sobrevivir al intento de resucitaci\u00f3n tras un paro card\u00edaco. Para esos pacientes, es probable que sea apropiado tomar la decisi\u00f3n de no intentar la reanimaci\u00f3n cardiopulmonar.<\/li>\n<li>Se debe disponer de equipo de protecci\u00f3n individual (<strong>EPI<\/strong>) para proteger al personal durante los intentos de reanimaci\u00f3n. Se reconoce que esto puede causar un <strong>breve retraso en el inicio de las compresiones tor\u00e1cicas, pero la seguridad del personal es primordial<\/strong>.<\/li>\n<li>Las compresiones tor\u00e1cicas pueden generar aerosoles, as\u00ed como las intervenciones en la v\u00eda respiratoria. El personal sanitario debe, por lo tanto, ponerse equipos de protecci\u00f3n individual espec\u00edficos antes de iniciar las compresiones tor\u00e1cicas y\/o la intervenci\u00f3n en la v\u00eda respiratoria:\n<ul>\n<li>como m\u00ednimo una mascarilla FFP3 (FFP2 o N95 si no se dispone de FFP3),<\/li>\n<li>protecci\u00f3n para los ojos y la cara,<\/li>\n<li>bata de manga larga<\/li>\n<li>y guantes.<\/li>\n<\/ul>\n<\/li>\n<li>Asegurarse de que haya un filtro de alta eficiencia (HEPA) entre el bal\u00f3n autoinflable y la v\u00eda respiratoria (mascarilla, dispositivo supragl\u00f3tico, tubo endotraqueal) para filtrar las respiraciones espiradas.<\/li>\n<li>La aplicaci\u00f3n de una descarga de un DEA\/desfibrilador no es probable que sea un procedimiento que genere aerosoles y puede realizarse con el proveedor de atenci\u00f3n m\u00e9dica usando una m\u00e1scara quir\u00fargica resistente a los fluidos, protecci\u00f3n ocular, corta delantal con mangas y guantes.<\/li>\n<li>Restringir el n\u00famero de personal en la habitaci\u00f3n o al lado de la cama. Asignar una persona para controlar los accesos a la sala. Todo el personal que no vaya a intervenir debe mantener su distancia del paciente y permanecer protegido.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Recomendaciones del Resuscitation Council UK sobre RCP en tiempos de COVID-19<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7694 aligncenter\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/descarga-300x150.png\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/descarga-300x150.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/descarga-335x168.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/descarga.png 360w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>El Resustitation Council UK, en su <a href=\"https:\/\/www.resus.org.uk\/_resources\/assets\/attachment\/full\/0\/36100.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Guidance for the resuscitation of COVID-19 patients in hospital<\/em><\/a> hace unas recomendaciones centradas en la RCP intrahospitalaria, cuyo principal objetivo tambi\u00e9n es limitar la propagaci\u00f3n del virus y garantizar la seguridad de los profesionales. Las recomendaciones son:<\/p>\n<ul>\n<li>Colocaci\u00f3n del <strong>EPI adecuado<\/strong> antes de entrar en escena. Aunque esto retrase levemente el inicio de las cardio compresiones, hay que garantizar la seguridad del profesional.<\/li>\n<li>Confirmar la parada cardiaca con la ausencia de respiraci\u00f3n y el control del pulso en la car\u00f3tida. <strong>No acercar el rostro al paciente<\/strong> para comprobar la ausencia de respiraci\u00f3n e informar a todos los intervinientes del riesgo de COVID-19.<\/li>\n<li>Si cuenta con un desfibrilador, <strong>desfibrilar cuanto antes<\/strong>. Una r\u00e1pida restauraci\u00f3n de la circulaci\u00f3n puede limitar la necesidad de otras t\u00e9cnicas de resucitaci\u00f3n. Hay que seguir las gu\u00edas locales sobre la <strong>limpieza del material<\/strong> que haya entrado en contacto con el paciente con riesgo de COVID-19.<\/li>\n<li>Una vez colocado el EPI, comience la RCP s\u00f3lo con compresi\u00f3n y monitorice el ritmo del paro card\u00edaco del paciente lo antes posible.\n<ul>\n<li><strong>No haga ventilaci\u00f3n boca a boca<\/strong>.<\/li>\n<li>Si el paciente ya est\u00e1 recibiendo terapia de ox\u00edgeno suplementario con una <strong>mascarilla facial<\/strong>, d\u00e9jela en la cara del paciente durante las compresiones tor\u00e1cicas, ya que esto puede <strong>limitar la propagaci\u00f3n de aerosoles<\/strong>. Si no est\u00e1 in situ, pero se puede conseguir f\u00e1cilmente una, poner una simple m\u00e1scara de ox\u00edgeno en la cara del paciente.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Restringir el n\u00famero de personal en la habitaci\u00f3n<\/strong>. Asigne una persona para impedir el acceso a la habitaci\u00f3n.<\/li>\n<li>Las <strong>intervenciones en las v\u00edas respiratorias<\/strong> (por ejemplo, la inserci\u00f3n de v\u00edas respiratorias supragl\u00f3ticas (SGA) o la intubaci\u00f3n traqueal) deben ser <strong>realizadas por personal experimentado<\/strong>. La intubaci\u00f3n endotraqueal o la inserci\u00f3n de SGA s\u00f3lo debe ser intentada por personas que tengan experiencia y sean competentes en este procedimiento.<\/li>\n<li><strong>Identificar y tratar cualquier causa reversible<\/strong> (por ejemplo, hipoxemia grave) antes de considerar la posibilidad de detener la reanimaci\u00f3n cardiopulmonar. Se debe emprender una<strong> planificaci\u00f3n<\/strong> temprana de la fase posterior a la reanimaci\u00f3n. Ponerse en contacto con UCI forma parte de la planificaci\u00f3n.<\/li>\n<li>Tras la reanimaci\u00f3n, <strong>tirar o limpiar todo el material utilizado durante la RCP<\/strong> siguiendo las recomendaciones del fabricante y las gu\u00edas locales. Hay que ser especialmente cuidadoso con el material que ha estado en contacto con la v\u00eda a\u00e9rea del paciente.<\/li>\n<li>Retirar el EPI siguiendo las gu\u00edas para evitar posibles contaminaciones y limpiar las manos.<\/li>\n<li>El informe posterior a la reanimaci\u00f3n es importante y debe ser planificado.<\/li>\n<\/ul>\n<h3><strong>Recomendaciones del Consell Catal\u00e0 de Ressucitaci\u00f3 sobre RCP en tiempos de COVID-19<\/strong><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7728 aligncenter\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/ccr-300x125.jpg\" alt=\"\" width=\"300\" height=\"125\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/ccr-300x125.jpg 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/ccr-335x140.jpg 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/ccr.jpg 348w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>En el documento\u00a0<a href=\"https:\/\/www.semg.es\/images\/2020\/Coronavirus\/parada_cardiaca_covid19.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Recomendaciones ante una parada card\u00edaca\u00a0durante la pandemia de COVID-19<\/em><\/a>, el <a href=\"https:\/\/ccr.cat\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consell Catal\u00e0 de Ressucitaci\u00f3<\/a> recomienda:<\/p>\n<ul>\n<li><strong>No realizar ventilaci\u00f3n boca a boca ni ventilaci\u00f3n bal\u00f3n m\u00e1scara<\/strong>.<\/li>\n<li>Cualquier paciente en paro card\u00edaco atendido por un equipo sanitario puede estar infectado por COVID-19. Hay que trabajar siempre con todas las medidas de protecci\u00f3n ante el virus.<\/li>\n<li>Evitar iniciar la resucitaci\u00f3n sin usar un equipo de proteccci\u00f3n b\u00e1sico.<\/li>\n<li>Evitar el acceso a la v\u00eda a\u00e9rea sin un equipo de protecci\u00f3n total.<\/li>\n<li>Tener especial cuidado en la descontaminaci\u00f3n y al desvertirse.<\/li>\n<li>Briefing previo para asignar funciones y tareas.<\/li>\n<li>Ensayar y simular todos los procedimientos para reducir el riesgo de infecci\u00f3n.<\/li>\n<\/ul>\n<p><strong>Conclusiones de las gu\u00edas de RCP adaptadas al COVID-19<\/strong><\/p>\n<p>[infobox title=&#8217;PUNTOS CLAVE DE LAS RECOMENDACIONES SOBRE RCP EN TIEMPOS DE COVID-19&#8242;]Garantizar la seguridad del profesional sanitario es primordial en estos tiempos, por lo que el Resuscitation Council UK y la AHA recomiendan:<\/p>\n<ul>\n<li><strong>\u00a0limitar el n\u00famero de intervinientes <\/strong>en una RCP.<\/li>\n<li>garantizar su seguridad <strong>limitando los aerosoles en la ventilaci\u00f3n del paciente.<\/strong><\/li>\n<li><strong>utilizar material desechable <\/strong>para evitar contagios.<\/li>\n<\/ul>\n<p>[\/infobox]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7913 size-large\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVB-en-tiempos-de-Covid-19-v4-724x1024.jpg\" alt=\"\" width=\"724\" height=\"1024\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVB-en-tiempos-de-Covid-19-v4-724x1024.jpg 724w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVB-en-tiempos-de-Covid-19-v4-212x300.jpg 212w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVB-en-tiempos-de-Covid-19-v4-768x1086.jpg 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVB-en-tiempos-de-Covid-19-v4-1086x1536.jpg 1086w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVB-en-tiempos-de-Covid-19-v4-1448x2048.jpg 1448w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVB-en-tiempos-de-Covid-19-v4-237x335.jpg 237w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVB-en-tiempos-de-Covid-19-v4-scaled.jpg 1810w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7914 size-large\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVA-724x1024.jpg\" alt=\"\" width=\"724\" height=\"1024\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVA-724x1024.jpg 724w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVA-212x300.jpg 212w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVA-768x1086.jpg 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVA-1086x1536.jpg 1086w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVA-1448x2048.jpg 1448w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVA-237x335.jpg 237w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/04\/SVA-scaled.jpg 1810w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/p>\n<p><iframe loading=\"lazy\" title=\"C\u00f3mo Montar una B-Card en Tiempos de COVID-19\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/ncuE_i3DHsI?list=PLudknT6ICYd1-UZkgjbWd7k-KQjUQhW6U\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>[infobox title=&#8217;BIBLIOGRAF\u00cdA&#8217;]<\/p>\n<ul>\n<li><a href=\"https:\/\/www.heart.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Heart Association<\/a><\/li>\n<li>\n<p class=\"citation__title\">Dana P. Edelson et al. <a href=\"https:\/\/www.ahajournals.org\/doi\/10.1161\/CIRCULATIONAHA.120.047463\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Interim Guidance for Basic and Advanced Life Support in Adults, Children, and Neonates With Suspected or Confirmed COVID-19<\/em><\/a>. From the Emergency Cardiovascular Care Committee and Get With The Guidelines-Resuscitation Adult and Pediatric Task Forces of the American Heart Association. <span class=\"epub-section__item\"><span class=\"epub-section__state\">Originally published <\/span><span class=\"epub-section__date\">9 Apr 2020. <\/span><\/span><span class=\"epub-section__item\">Circulation. 2020;141:e933\u2013e943.<\/span><\/p>\n<\/li>\n<li><a href=\"https:\/\/www.aap.org\/en-us\/Pages\/Default.aspx\" target=\"_blank\" rel=\"noopener noreferrer\">American Academy of Pediatrics<\/a><\/li>\n<li><a href=\"https:\/\/www.aarc.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Association for Respiratory Care<\/a><\/li>\n<li><a href=\"https:\/\/www.acep.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American College of Emergency Physicians<\/a><\/li>\n<li><a href=\"https:\/\/socca.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Society of Critial Care Anesthesiologists<\/a><\/li>\n<li><a href=\"https:\/\/www.asahq.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Society of Anesthesiologists\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/www.aacn.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Association of Critical Care Nurses<\/a><\/li>\n<li><a href=\"https:\/\/naemsp.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">National Association of\u00a0EMS\u00a0Physicians<\/a><\/li>\n<li><a href=\"https:\/\/www.erc.edu\/\" target=\"_blank\" rel=\"noopener noreferrer\">European Resuscitation Council<\/a><\/li>\n<li><a href=\"https:\/\/www.resus.org.uk\/covid-19-resources\" target=\"_blank\" rel=\"noopener noreferrer\">Resuscitation Council UK. Guidance for COVID-19.<\/a><\/li>\n<li><a href=\"https:\/\/www.semg.es\/images\/2020\/Coronavirus\/parada_cardiaca_covid19.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Consell Catal\u00e1 de Ressucitaci\u00f3. Recomendaciones<em> ante una parada cardiaca durante la pandemia de COVID-19.<\/em><\/a><\/li>\n<li><a href=\"https:\/\/ccr.cat\/\" target=\"_blank\" rel=\"noopener noreferrer\">Consell Catal\u00e1 de Ressucitaci\u00f3<\/a><\/li>\n<\/ul>\n<p>[\/infobox]<\/p>\n<p>Tambi\u00e9n os recordamos que, en l\u00ednea con las iniciativas de formaci\u00f3n y concienciaci\u00f3n del 16 de octubre, d\u00eda mundial de la RCP, publicamos el ebook <em>La oxigenaci\u00f3n pasiva en RCP \u2013 Un nuevo paradigma para una nueva normalidad, <\/em>una recopilaci\u00f3n de contenidos y materiales formativos para RCP en el que han colaborado grandes profesionales como el propio dr. Garrote o el ya fallecido dr. Boussignac. <a href=\"http:\/\/campusvygon.com\/es\/ebook-oxigenacion-pasiva-en-rcp\/\" target=\"_blank\" rel=\"noopener noreferrer\">Pod\u00e9is descargarlo de forma gratuita aqu\u00ed<\/a>.<\/p>\n<p><a href=\"http:\/\/campusvygon.com\/es\/ebook-oxigenacion-pasiva-en-rcp\/\" target=\"_blank\" rel=\"attachment noopener wp-att-13214 noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-13214\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/10\/twitter.png\" alt=\"\" width=\"1024\" height=\"512\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/10\/twitter.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/10\/twitter-300x150.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/10\/twitter-768x384.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/10\/twitter-335x168.png 335w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: left\"><strong>[infobox title=&#8217;Tambi\u00e9n te puede interesar&#8217;]<\/strong><\/p>\n<ul style=\"text-align: left\">\n<li><strong><a href=\"http:\/\/campusvygon.com\/es\/ebook-oxigenacion-pasiva-en-rcp\/\" target=\"_blank\" rel=\"noopener noreferrer\">EBOOK: <em>La oxigenaci\u00f3n pasiva en RCP \u2013 Un nuevo paradigma para una nueva normalidad<\/em><\/a><\/strong><\/li>\n<li style=\"text-align: left\"><strong><a class=\"vw-post-box__link\" href=\"http:\/\/campusvygon.com\/es\/protocolo-de-rcp-en-tiempos-de-covid-19\/\" rel=\"bookmark\">PROTOCOLO DE RCP EN TIEMPOS DE COVID-19<\/a><\/strong><\/li>\n<li><strong><a href=\"http:\/\/campusvygon.com\/es\/bcard\/\" target=\"_blank\" rel=\"noopener noreferrer\">ACCEDE A TODA LA INFORMACI\u00d3N SOBRE B-CARD<\/a><\/strong><\/li>\n<li><strong><a href=\"http:\/\/campusvygon.com\/es\/dispositivos-ventilacion-vs-oxigenacion-rcp\/\" target=\"_blank\" rel=\"noopener noreferrer\">COMPARATIVA ENTRE DISPOSITIVOS PARA VENTILACI\u00d3N VS DISPOSITIVOS PARA OXIGENACI\u00d3N PASIVA EN RCP<\/a><\/strong><\/li>\n<li><strong><a class=\"vw-post-box__link\" href=\"http:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/\" rel=\"bookmark\">LAS RECOMENDACIONES DE LAS SOCIEDADES CIENT\u00cdFICAS SOBRE RCP EN TIEMPOS DE COVID-19<\/a><\/strong><\/li>\n<li><strong><a class=\"vw-post-box__link\" href=\"http:\/\/campusvygon.com\/es\/oxigenacion-pasiva-rcp-covid\/\" rel=\"bookmark\">8 VENTAJAS DE LA OXIGENACI\u00d3N PASIVA EN RCP EN TIEMPOS DE COVID-19<\/a><\/strong><\/li>\n<li><strong><a class=\"vw-post-box__link\" href=\"http:\/\/campusvygon.com\/es\/riesgos-ventilacion-rcp\/\" rel=\"bookmark\">EFECTOS ADVERSOS DE LA VENTILACI\u00d3N EN RCP Y UNA ALTERNATIVA: EL FLUJO CONTINUO DE OX\u00cdGENO<\/a><\/strong><\/li>\n<li><strong><a class=\"vw-post-box__link\" href=\"http:\/\/campusvygon.com\/es\/entrevista-dr-garrote-nuevo-cambio-de-paradigma-por-covid\/\" rel=\"bookmark\">ENTREVISTA AL DOCTOR JOS\u00c9 IGNACIO GARROTE SOBRE EL NUEVO CAMBIO DE PARADIGMA EN LA RCP POR EL COVID-19<\/a><\/strong><\/li>\n<li><strong><a class=\"vw-post-box__link\" href=\"http:\/\/campusvygon.com\/es\/entrevista-dr-garrote-nuevo-cambio-de-paradigma-por-covid-publico\/\" rel=\"bookmark\">ENTREVISTA: EL DOCTOR JOS\u00c9 IGNACIO GARROTE RESPONDE A LAS PREGUNTAS DEL P\u00daBLICO SOBRE EL NUEVO CAMBIO DE PARADIGMA EN LA RCP POR EL COVID-19<\/a><\/strong><\/li>\n<li><strong><a class=\"vw-post-box__link\" href=\"http:\/\/campusvygon.com\/es\/recomendaciones-sobre-rcp\/\" rel=\"bookmark\">\u00daLTIMAS RECOMENDACIONES SOBRE RCP DE ILCOR, AHA Y ERC<\/a><\/strong><\/li>\n<li><strong><a class=\"vw-post-box__link\" href=\"http:\/\/campusvygon.com\/es\/el-papel-de-la-bujia-para-garantizar-una-intubacion-segura-en-tiempos-de-covid-19\/\" rel=\"bookmark\">EL PAPEL DE LAS BUJ\u00cdAS PARA GARANTIZAR UNA INTUBACI\u00d3N SEGURA EN TIEMPOS DE COVID-19<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: left\"><strong>[\/infobox]<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las asociaciones y sociedades cient\u00edficas internacionales presentan cada cierto tiempo sus gu\u00edas y recomendaciones para RCP actualizadas seg\u00fan la evidencia cient\u00edfica. Sin embargo, la crisis sanitaria que estamos viviendo les ha obligado a preparar unas gu\u00edas espec\u00edficas de RCP para hacer frente al COVID-19. Algunas de estas recomendaciones, que se centran en garantizar la seguridad [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":48254,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[379,258],"tags":[],"class_list":["post-7667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-b-card","category-emergencias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19<\/title>\n<meta name=\"description\" content=\"Recomendaciones de las principales sociedades cient\u00edficas, la American Heart Asociation y el Resuscitation Council UK sobre RCP en tiempos de COVID-19\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19\" \/>\n<meta property=\"og:description\" content=\"Recomendaciones de las principales sociedades cient\u00edficas, la American Heart Asociation y el Resuscitation Council UK sobre RCP en tiempos de COVID-19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-15T11:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T16:56:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sociedades-cientificas-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"James Webb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"James Webb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/\"},\"author\":{\"name\":\"James Webb\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/e736a5547871c4f8ffc13b4b35021488\"},\"headline\":\"Las recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19\",\"datePublished\":\"2020-05-15T11:03:00+00:00\",\"dateModified\":\"2025-09-30T16:56:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/\"},\"wordCount\":2449,\"commentCount\":12,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-sociedades-cientificas-scaled.jpeg\",\"articleSection\":[\"B-Card\",\"Urgencias y Emergencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/\",\"name\":\"Recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-sociedades-cientificas-scaled.jpeg\",\"datePublished\":\"2020-05-15T11:03:00+00:00\",\"dateModified\":\"2025-09-30T16:56:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/e736a5547871c4f8ffc13b4b35021488\"},\"description\":\"Recomendaciones de las principales sociedades cient\u00edficas, la American Heart Asociation y el Resuscitation Council UK sobre RCP en tiempos de COVID-19\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-sociedades-cientificas-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portada-sociedades-cientificas-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"Selective focus is first aid bag. Team paramedic firs aid accident on road. Ambulance emergency service. First aid procedure.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/e736a5547871c4f8ffc13b4b35021488\",\"name\":\"James Webb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/plugins\\\/wp-user-avatar\\\/deprecated\\\/wp-user-avatar\\\/images\\\/wpua-96x96.png\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/plugins\\\/wp-user-avatar\\\/deprecated\\\/wp-user-avatar\\\/images\\\/wpua-96x96.png\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/plugins\\\/wp-user-avatar\\\/deprecated\\\/wp-user-avatar\\\/images\\\/wpua-96x96.png\",\"caption\":\"James Webb\"},\"description\":\"Soy responsable de las Unidades de negocio Anestesia y Emergencias y Cuidados Intensivos. EXPERIENCIA Soy bioqu\u00edmico y genetista molecular de formaci\u00f3n, y empec\u00e9 mi carrera profesional trabajando en Hospitales en el Reino Unido liderando un grupo de investigaci\u00f3n en las enfermedades raras. Llevo 20 a\u00f1os centrado en la en la gesti\u00f3n de compa\u00f1\u00edas en el sector de salud, complementando mi formaci\u00f3n cient\u00edfica con un MBA Ejecutivo, especializ\u00e1ndome en el desarrollo y gesti\u00f3n de compa\u00f1\u00edas startup. He trabajado en compa\u00f1\u00edas de biotecnolog\u00eda, servicios de diagn\u00f3stico e investigaci\u00f3n y dispositivos m\u00e9dicos antes de entrar en Vygon. PUEDO AYUDARTE EN\u2026 Mi trabajo se basa en una apuesta clara de Vygon para proporcionar los mejores servicios, herramientas y formaci\u00f3n a los profesionales de salud para atender a sus pacientes en los \u00e1mbitos de Anestesia, Urgencias, Emergencias o Cuidados Intensivos.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jameswebb1971\\\/?originalSubdomain=es\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jameswebb1971\\\/\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/author\\\/james-webb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19","description":"Recomendaciones de las principales sociedades cient\u00edficas, la American Heart Asociation y el Resuscitation Council UK sobre RCP en tiempos de COVID-19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19","og_description":"Recomendaciones de las principales sociedades cient\u00edficas, la American Heart Asociation y el Resuscitation Council UK sobre RCP en tiempos de COVID-19","og_url":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/","og_site_name":"Campus Vygon Espa\u00f1a","article_published_time":"2020-05-15T11:03:00+00:00","article_modified_time":"2025-09-30T16:56:38+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sociedades-cientificas-scaled.jpeg","type":"image\/jpeg"}],"author":"James Webb","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"James Webb","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/"},"author":{"name":"James Webb","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/e736a5547871c4f8ffc13b4b35021488"},"headline":"Las recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19","datePublished":"2020-05-15T11:03:00+00:00","dateModified":"2025-09-30T16:56:38+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/"},"wordCount":2449,"commentCount":12,"image":{"@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sociedades-cientificas-scaled.jpeg","articleSection":["B-Card","Urgencias y Emergencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/","url":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/","name":"Recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sociedades-cientificas-scaled.jpeg","datePublished":"2020-05-15T11:03:00+00:00","dateModified":"2025-09-30T16:56:38+00:00","author":{"@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/e736a5547871c4f8ffc13b4b35021488"},"description":"Recomendaciones de las principales sociedades cient\u00edficas, la American Heart Asociation y el Resuscitation Council UK sobre RCP en tiempos de COVID-19","breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sociedades-cientificas-scaled.jpeg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portada-sociedades-cientificas-scaled.jpeg","width":2560,"height":1707,"caption":"Selective focus is first aid bag. Team paramedic firs aid accident on road. Ambulance emergency service. First aid procedure."},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/las-recomendaciones-de-las-sociedades-cientificas-sobre-rcp-en-tiempos-de-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las recomendaciones de las sociedades cient\u00edficas sobre RCP en tiempos de COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/e736a5547871c4f8ffc13b4b35021488","name":"James Webb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png","url":"https:\/\/campusvygon.com\/es\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png","caption":"James Webb"},"description":"Soy responsable de las Unidades de negocio Anestesia y Emergencias y Cuidados Intensivos. EXPERIENCIA Soy bioqu\u00edmico y genetista molecular de formaci\u00f3n, y empec\u00e9 mi carrera profesional trabajando en Hospitales en el Reino Unido liderando un grupo de investigaci\u00f3n en las enfermedades raras. Llevo 20 a\u00f1os centrado en la en la gesti\u00f3n de compa\u00f1\u00edas en el sector de salud, complementando mi formaci\u00f3n cient\u00edfica con un MBA Ejecutivo, especializ\u00e1ndome en el desarrollo y gesti\u00f3n de compa\u00f1\u00edas startup. He trabajado en compa\u00f1\u00edas de biotecnolog\u00eda, servicios de diagn\u00f3stico e investigaci\u00f3n y dispositivos m\u00e9dicos antes de entrar en Vygon. PUEDO AYUDARTE EN\u2026 Mi trabajo se basa en una apuesta clara de Vygon para proporcionar los mejores servicios, herramientas y formaci\u00f3n a los profesionales de salud para atender a sus pacientes en los \u00e1mbitos de Anestesia, Urgencias, Emergencias o Cuidados Intensivos.","sameAs":["https:\/\/www.linkedin.com\/in\/jameswebb1971\/?originalSubdomain=es","https:\/\/www.linkedin.com\/in\/jameswebb1971\/"],"url":"https:\/\/campusvygon.com\/es\/author\/james-webb\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/7667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=7667"}],"version-history":[{"count":11,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/7667\/revisions"}],"predecessor-version":[{"id":34623,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/7667\/revisions\/34623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/48254"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=7667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/categories?post=7667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/tags?post=7667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}