{"id":9540,"date":"2020-07-02T12:13:28","date_gmt":"2020-07-02T10:13:28","guid":{"rendered":"http:\/\/campusvygon.com\/es\/?p=9540"},"modified":"2025-09-29T11:15:15","modified_gmt":"2025-09-29T09:15:15","slug":"asfixia-perinatal","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/","title":{"rendered":"Evitar y manejar la asfixia perinatal"},"content":{"rendered":"<p>La asfixia perinatal, desde las primeras observaciones en 1861 sobre la posible relaci\u00f3n entre acontecimientos adversos durante el parto y el desarrollo de deficiencias intelectuales en los reci\u00e9n nacidos, se ha convertido en una prioridad para los profesionales sanitarios (1).<\/p>\n<p>Se trata de un s\u00edndrome por el que se produce<strong> la suspensi\u00f3n o disminuci\u00f3n del intercambio gaseoso a nivel placentario o pulmonar<\/strong>, que resulta en hipoxemia, hipercapnia e hipoxia tisular con acidosis metab\u00f3lica (2). Adem\u00e1s, puede ir asociado, a una isquemia y acumulaci\u00f3n de <strong>productos del catabolismo celular (2,3).<\/strong><\/p>\n<p><a href=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9543\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal.png\" alt=\"\u00bfSab\u00edas qu\u00e9... Asfixia perinatal?\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal.png 1080w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal-300x300.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal-1024x1024.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal-150x150.png 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal-768x768.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal-70x70.png 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal-335x335.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Asfixia-perinatal-360x360.png 360w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/a><\/p>\n<p><strong>La asfixia afecta todos los \u00f3rganos y sistemas gradualmente seg\u00fan su intensidad y duraci\u00f3n<\/strong> (2). Sin embargo, aunque el diagn\u00f3stico de la asfixia perinatal -llamada as\u00ed porque puede darse antes del nacimiento, durante el embarazo, el trabajo de parto y el parto- requiere la constataci\u00f3n de alteraciones gasom\u00e9tricas, \u00e9stas no conllevan necesariamente repercusi\u00f3n org\u00e1nica.<\/p>\n<p>Durante el parto pueden darse de forma transitoria momentos de hipoxemia e hipercapnia, sin repercusi\u00f3n patol\u00f3gica para el feto. Por esta raz\u00f3n, aunque esta definici\u00f3n de asfixia es adecuada patog\u00e9nicamente, no es operativa en la pr\u00e1ctica cl\u00ednica (1,2).<\/p>\n<p>La Academia Americana de Pediatr\u00eda (AAP) y el Colegio Americano de Obstetras y Ginec\u00f3logos, con el fin de resolver este problema de terminolog\u00eda, establecieron que, \u00fanicamente, <strong>se puede hablar de asfixia perinatal cuando se cumplan estos cuatro requisitos<\/strong> (3):<\/p>\n<ul>\n<li><strong>Acidosis metab\u00f3lica o mixta con un pH de cord\u00f3n menor de 7 <\/strong><\/li>\n<li><strong>APGAR entre 0 y 3<\/strong> a los 5 minutos<\/li>\n<li>Presencia de<strong> manifestaciones neurol\u00f3gicas en el per\u00edodo neonatal inmediato, derivadas de la hipoxia o de la isquemia<\/strong>, como convulsiones, hipoton\u00eda, como manifestaciones de encefalopat\u00eda hip\u00f3xico-isqu\u00e9mica<\/li>\n<li><strong>Evidencias de compromiso multiorg\u00e1nico<\/strong><\/li>\n<\/ul>\n<h4>Compromiso multisist\u00e9mico<\/h4>\n<p><a href=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9545 size-large\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia-1024x1024.png\" alt=\"Severidad de asfixia perinatal\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia-1024x1024.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia-300x300.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia-150x150.png 150w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia-768x768.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia-70x70.png 70w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia-335x335.png 335w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia-360x360.png 360w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Severidad-en-asfixia.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a>Actualmente, entre el 0,2 y el 0,4% de los reci\u00e9n nacidos se ven afectados por la p\u00e9rdida de bienestar fetal (2). Esta p\u00e9rdida puede comprometer la totalidad del organismo del reci\u00e9n nacido, produciendo fallos multisist\u00e9micos en estos peque\u00f1os pacientes (4).<\/p>\n<p>Este hecho provoca complicaciones a corto y largo plazo como: par\u00e1lisis cerebral, epilepsia, trastornos motores y de aprendizaje, retraso en el habla, deficiencias auditivas y visuales, problemas de alimentaci\u00f3n, problemas ortop\u00e9dicos\u2026 (4)<\/p>\n<p><strong>El sistema nervioso central es el m\u00e1s vulnerable debido a su limitada capacidad de recuperaci\u00f3n, con consecuencias celulares irreversibles y secuelas asociadas<\/strong>. La manifestaci\u00f3n cl\u00ednica m\u00e1s caracter\u00edstica es la encefalopat\u00eda hip\u00f3xica isqu\u00e9mica. Las consecuencias en este sistema, dependiendo del grado de gravedad de la encefalopat\u00eda, puede vincularse a una tasa de 50% de mortalidad en el periodo neonatal o, bien, a un 95% de secuelas graves, como retraso mental, en los RN que sobreviven (2,5).<\/p>\n<p>Sin embargo, la p\u00e9rdida de bienestar fetal compromete otros sistemas como el <strong>cardiovascular<\/strong>, por isquemia mioc\u00e1rdica; <strong>respiratorio<\/strong>, debido a la depresi\u00f3n de los centros respiratorios y al aumento del riego de aspiraci\u00f3n meconial; <strong>urinario<\/strong>, por la disminuci\u00f3n de la perfusi\u00f3n renal; <strong>digestivo<\/strong>, con una disminuci\u00f3n del tr\u00e1nsito intestinal y el desarrollo de \u00falceras de estr\u00e9s y necrosis intestinal; <strong>hematol\u00f3gico<\/strong>, por mayor consumo de plaquetas como consecuencia del inicio de coagulaci\u00f3n intraventricular; y <strong>metab\u00f3lico<\/strong>, que deriva en hipoglucemia e hipocalcemia (2,5).<\/p>\n<h4>Control de la Asfixia Perinatal<\/h4>\n<p>La gran mayor\u00eda de las causas de hipoxia perinatal son de origen intrauterino. Aproximadamente 5% ocurren antes del inicio del trabajo de parto, <strong>85% durante el parto o la expulsi\u00f3n<\/strong> y 10% restante durante el periodo neonatal (2). Por ese motivo, para evitar la p\u00e9rdida de bienestar fetal, es necesario establecer <strong>estrategias de detecci\u00f3n precoz que determinen cuando el feto est\u00e1 en riesgo. <\/strong><\/p>\n<p><strong>La monitorizaci\u00f3n del intraparto es una pr\u00e1ctica habitual, en la actualidad, en los hospitales para el control del bienestar fetal. <\/strong>Durante a\u00f1os, se emple\u00f3 \u00fanicamente la auscultaci\u00f3n fetal mediante el estetoscopio teniendo en cuenta que es una m\u00e9todo no objetivable y no reproducible con el que registrar la frecuencia card\u00edaca fetal durante la mayor\u00eda del tiempo del trabajo de parto (6).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-9600 aligncenter\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1.png\" alt=\"Causas Asfixia Perinatal\" width=\"8910\" height=\"6300\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1.png 8910w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1-300x212.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1-1024x724.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1-768x543.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1-1536x1086.png 1536w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1-2048x1448.png 2048w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1-400x284.png 400w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1-1080x764.png 1080w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Causas-Asfixia-Perinatal-1-335x237.png 335w\" sizes=\"(max-width: 8910px) 100vw, 8910px\" \/><\/p>\n<p>No obstante, <strong>el desarrollo de la tecnolog\u00eda ha permitido el desarrollo de nuevas pr\u00e1cticas para dicha monitorizaci\u00f3n.<\/strong> A finales de los a\u00f1os 60 parecieron los primeros monitores que permit\u00edan el registro de la FCF y las contracciones uterinas denominados monitores cardiotocogr\u00e1ficos. Su uso tuvo una r\u00e1pida y ampl\u00eda aceptaci\u00f3n. Sin embargo, y a pesar de que hoy en d\u00eda se sigue utilizando en la vigilancia de fetos hipox\u00e9micos ha causado un amplio debate (6,7).<\/p>\n<p><strong>Varios estudios parecen indicar que la alta sensibilidad del cardiotocograma proporciona un \u00edndice muy alto de falsos positivos y provoca un n\u00famero muy elevado de intervenciones innecesaria<\/strong> al indicar err\u00f3neamente que el feto est\u00e1 en peligro. Adem\u00e1s, como consecuencia, <a href=\"http:\/\/campusvygon.com\/es\/manacor-cesareas\/\">al aumentar el n\u00famero de ces\u00e1reas<\/a> no necesarias se <strong>incrementa el riesgo de morbilidad y mortalidad materna y perinatal<\/strong> (7).<\/p>\n<h4><strong>Microtoma fetal, \u201cGold standard\u201d<\/strong><\/h4>\n<p>Esta prueba consiste en la extracci\u00f3n de sangre de calota fetal para el estudio de la gasometr\u00eda. Es importante que haya una dilataci\u00f3n cervical de 3-4&nbsp;cm y que la membrana amni\u00f3tica est\u00e9 rota para poder realizarlo.<\/p>\n<p>La t\u00e9cnica consiste en exponer la presentaci\u00f3n fetal mediante un amnioscopio. Tras provocar una vasodilataci\u00f3n capilar reactiva aplicando cloruro de etilo, se realiza con una lanceta una peque\u00f1a incisi\u00f3n en el cuero cabelludo; posteriormente se aspira con un tubo capilar la sangre que fluye, evitando el contacto con aire (8).<\/p>\n<p><iframe loading=\"lazy\" title=\"Tutorial de uso Fetal Scalp\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/gyMdgZ6DHTc?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Los resultados obtenidos en esta prueba ayudar\u00e1n a los profesionales sanitarios a determinar la existencia de sufrimiento fetal y a decidir la mejor actuaci\u00f3n para asegurar el bienestar del paciente (8,9,10):<\/p>\n<ul>\n<li>pH &gt; 7,25: El beb\u00e9 est\u00e1 sano y se prosigue con el parto<\/li>\n<li>pH entre 7,20 -7,24: El feto se encuentra en un estado de preacid\u00f3sis y se debe de repetir la muestra 15 minutos m\u00e1s tarde. La prueba puede haberse realizado en un momento de muchas contracciones o hiperdinam\u00eda y los resultados se encuentran alterados.<\/li>\n<li>pH &lt; 7,20: Se practica una extracci\u00f3n fetal urgente<\/li>\n<\/ul>\n<p>Las complicaciones de la t\u00e9cnica son extremadamente raras (8) y su incorporaci\u00f3n en la pr\u00e1ctica cl\u00ednica ha ayudado a reducir la tasa de ces\u00e1reas. <strong>Se considera la \u00fanica prueba 100% en la determinaci\u00f3n del bienestar fetal<\/strong> (10).<\/p>\n<h4>Atenci\u00f3n al Reci\u00e9n Nacido con Asfixia<\/h4>\n<p>A pesar de que la anticipaci\u00f3n y monitoreo son fundamentales para el control del bienestar fetal, es imprescindible conocer c\u00f3mo manejar a un Reci\u00e9n Nacido que presenta s\u00edntomas de asfixia perinatal (cianosis y par\u00f3n respiratorio deficiente).<\/p>\n<p>Este proceso pasa por mantener la funci\u00f3n cardiorespitaria en rangos normales, mediante 02 o ventilaci\u00f3n mec\u00e1nica; mantener la presi\u00f3n arterial a trav\u00e9s de la infusi\u00f3n de f\u00e1rmacos vasoactivos para favorecer la perfusi\u00f3n cerebral, corregir la acidosis metab\u00f3lica e hipoglucemia; y rectificar la hipovolemia y\/o anemia.<\/p>\n<p><a href=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-9549\" src=\"http:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia.png\" alt=\"Manejo de la Asfixia Perinatal\" width=\"2138\" height=\"1512\" srcset=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia.png 2138w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia-300x212.png 300w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia-1024x724.png 1024w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia-768x543.png 768w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia-1536x1086.png 1536w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia-2048x1448.png 2048w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia-400x284.png 400w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia-1080x764.png 1080w, https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/07\/Manejo-de-la-asfixia-335x237.png 335w\" sizes=\"(max-width: 2138px) 100vw, 2138px\" \/>\u200b<\/a><\/p>\n<p>[accordion title=&#8217;Bibliograf\u00eda&#8217;]<\/p>\n<ol>\n<li>Mart\u00ednez Biarge, M., 2008. <em>Morbilidad Perinatal Y Neurol\u00f3gtica Asociada A Los Eventos Centineras<\/em>. [PDF] Universidad aut\u00f3noma de madrid, pp.1-4. Disponible en: <a href=\"https:\/\/repositorio.uam.es\/bitstream\/handle\/10486\/6183\/37603_mart\u00ednez_biarge_miriam.pdf\">https:\/\/repositorio.uam.es\/bitstream\/handle\/10486\/6183\/37603_mart\u00ednez_biarge_miriam.pdf<\/a> [Acceso 20 Junio 2020].<\/li>\n<li>Guti\u00e9rrez, J., Angulo, E., Garc\u00eda, H., Garc\u00eda, E., Padilla, H., P\u00e9rez, D., Plasencia, A., Vargas, R., Yanowsky, G. and Zepeda, L., 2019. <em>Manual De Neonatolog\u00eda<\/em>. 2nd ed. [PDF] Guadalajara: Universidad de Guadalajara, pp.38-54. Disponible en: <a href=\"http:\/\/www.cucs.udg.mx\/revistas\/libros\/ManualNeonatonologia.pdf\">http:\/\/www.cucs.udg.mx\/revistas\/libros\/ManualNeonatonologia.pdf<\/a> [Acceso 22 Junio 2020].<\/li>\n<li>Cifuentes, J., 2003. <em>Asfixia Perinatal<\/em>. [online] MEDwave. Available at: <a href=\"https:\/\/www.medwave.cl\/link.cgi\/Medwave\/PuestaDia\/APS\/1954\">https:\/\/www.medwave.cl\/link.cgi\/Medwave\/PuestaDia\/APS\/1954<\/a> [Acceso 22 Junio 2020].<\/li>\n<li><em>Efectos A Largo Plazo De La Asfixia Al Nacer Y La Encefalopat\u00eda Hip\u00f3xico-Isqu\u00e9mica<\/em>. [online] Disponible en: <a href=\"https:\/\/www.abclawcenters.com\/blog\/2018\/10\/30\/efectos-a-largo-plazo-de-la-asfixia-al-nacer-y-la-encefalopatia-hipoxico-isquemica\/\">https:\/\/www.abclawcenters.com\/blog\/2018\/10\/30\/efectos-a-largo-plazo-de-la-asfixia-al-nacer-y-la-encefalopatia-hipoxico-isquemica\/<\/a> [Acceso 21 Junio 2020].<\/li>\n<li>Krauel, J., n.d. <em>Asfixia Intrauterina<\/em>. [PDF] pp.415-431. Disponible en: <a href=\"http:\/\/webs.academia.cat\/revistes_elect\/view_document.php?tpd=2&amp;i=2782\">http:\/\/webs.academia.cat\/revistes_elect\/view_document.php?tpd=2&amp;i=2782<\/a>&gt; [Acceso 23 Junio 2020].<\/li>\n<li>Calveiro, M., 2017. <em>Frecuencia De Registros Cardiotocogr\u00e1ficos Sugerentes De P\u00e9rdida De Bienestar Fetal Y Su Relaci\u00f3n Con Los Resultados Perinatales En Un Hospital De Tercer Nivel<\/em>. [PDF] Madrid, pp.29-36. Disponible: &lt;<a href=\"https:\/\/eprints.ucm.es\/46300\/1\/T39554.pdf\">https:\/\/eprints.ucm.es\/46300\/1\/T39554.pdf<\/a>&gt; [Acceso 22 Junio 2020].<\/li>\n<li>Marcos, I., 2000. <em>De Las Manos A La Cardiotocograf\u00eda<\/em>. [PDF] Disponible: &lt;<a href=\"https:\/\/aesmatronas.com\/wp-content\/uploads\/sites\/7\/2017\/12\/10_DE_LAS_MANOS.pdf\">https:\/\/aesmatronas.com\/wp-content\/uploads\/sites\/7\/2017\/12\/10_DE_LAS_MANOS.pdf<\/a>&gt; [Acceso 21 de Junio 2020].<\/li>\n<li>Bik, M., 2020. <em>Monotorizaci\u00f3n Fetal Intraparto: Algoritmo De Actuaci\u00f3n. Ph Calota<\/em>. [PDF] Editorial M\u00e9dica Panamericana, pp.10-13. Disponible en: &lt;<a href=\"https:\/\/aula.campuspanamericana.com\/_Cursos\/Curso01207\/Temario\/M1T6\/M1_T6_Texto.pdf\">https:\/\/aula.campuspanamericana.com\/_Cursos\/Curso01207\/Temario\/M1T6\/M1_T6_Texto.pdf<\/a>&gt; [Acceso 22 Junio 2020].<\/li>\n<li>2020. <em>Toma De Ph de Calota fetal: Significado y Actuaci\u00f3n <\/em>[online] Disponible en: <a href=\"http:\/\/saludmujerclinico.es\/toma-de-ph-de-calota-fetal-significado-y-actuacion\/\">http:\/\/saludmujerclinico.es\/toma-de-ph-de-calota-fetal-significado-y-actuacion\/<\/a> [Acceso 18 Junio2020].<\/li>\n<\/ol>\n<p>[\/accordion]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La asfixia perinatal, desde las primeras observaciones en 1861 sobre la posible relaci\u00f3n entre acontecimientos adversos durante el parto y el desarrollo de deficiencias intelectuales en los reci\u00e9n nacidos, se ha convertido en una prioridad para los profesionales sanitarios (1). Se trata de un s\u00edndrome por el que se produce la suspensi\u00f3n o disminuci\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":48009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[286],"tags":[277,371,275],"class_list":["post-9540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neonatologia","tag-asfixia-fetal","tag-asfixia-perinatal","tag-microtoma"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evitar y manejar la asfixia perinatal<\/title>\n<meta name=\"description\" content=\"Controlar la asfixia perinatal es una prioridad para los profesionales sanitarios. Descubre c\u00f3mo evitar la p\u00e9rdida de bienestar fetal en este art\u00edculo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evitar y manejar la asfixia perinatal\" \/>\n<meta property=\"og:description\" content=\"Controlar la asfixia perinatal es una prioridad para los profesionales sanitarios. Descubre c\u00f3mo evitar la p\u00e9rdida de bienestar fetal en este art\u00edculo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-02T10:13:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-29T09:15:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portda-asfixia-perinatal-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Cabrera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Cabrera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/\"},\"author\":{\"name\":\"Jorge Cabrera\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/c2351d5dbfb3c87d31141cbb6bbdd081\"},\"headline\":\"Evitar y manejar la asfixia perinatal\",\"datePublished\":\"2020-07-02T10:13:28+00:00\",\"dateModified\":\"2025-09-29T09:15:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/\"},\"wordCount\":1471,\"commentCount\":4,\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portda-asfixia-perinatal-scaled.jpeg\",\"keywords\":[\"asfixia fetal\",\"asfixia perinatal\",\"microtoma\"],\"articleSection\":[\"Neonatolog\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/\",\"name\":\"Evitar y manejar la asfixia perinatal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portda-asfixia-perinatal-scaled.jpeg\",\"datePublished\":\"2020-07-02T10:13:28+00:00\",\"dateModified\":\"2025-09-29T09:15:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/c2351d5dbfb3c87d31141cbb6bbdd081\"},\"description\":\"Controlar la asfixia perinatal es una prioridad para los profesionales sanitarios. Descubre c\u00f3mo evitar la p\u00e9rdida de bienestar fetal en este art\u00edculo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portda-asfixia-perinatal-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/09\\\/Portda-asfixia-perinatal-scaled.jpeg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/asfixia-perinatal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evitar y manejar la asfixia perinatal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#\\\/schema\\\/person\\\/c2351d5dbfb3c87d31141cbb6bbdd081\",\"name\":\"Jorge Cabrera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/jorge-carera-foto.jpg\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/jorge-carera-foto.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/03\\\/jorge-carera-foto.jpg\",\"caption\":\"Jorge Cabrera\"},\"description\":\"Soy comercial especialista en terapias intravenosa y neonatolog\u00eda \u2022 EXPERIENCIA Soy farmac\u00e9utico, especialista en Bioqu\u00edmica, he ejercido como tal tanto en oficinas de farmacia, hospitales y cl\u00ednicas privadas. Pero pronto descubr\u00ed el mundo comercial y el servicio a clientes m\u00e9dicos y sanitarios en general, donde me siento realizado. \u2022 PUEDO AYUDARTE EN... Mi trabajo se basa en conocer las necesidades de mis clientes en el \u00e1mbito sanitario, y aportarles mejoras en sus t\u00e9cnicas diarias con el mejor material del mercado.\",\"sameAs\":[\"http:\\\/\\\/www.vygon.es\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jorge-cabrera-perez-33050097\\\/\"],\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/author\\\/jcabrera\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evitar y manejar la asfixia perinatal","description":"Controlar la asfixia perinatal es una prioridad para los profesionales sanitarios. Descubre c\u00f3mo evitar la p\u00e9rdida de bienestar fetal en este art\u00edculo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/","og_locale":"es_ES","og_type":"article","og_title":"Evitar y manejar la asfixia perinatal","og_description":"Controlar la asfixia perinatal es una prioridad para los profesionales sanitarios. Descubre c\u00f3mo evitar la p\u00e9rdida de bienestar fetal en este art\u00edculo.","og_url":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/","og_site_name":"Campus Vygon Espa\u00f1a","article_published_time":"2020-07-02T10:13:28+00:00","article_modified_time":"2025-09-29T09:15:15+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portda-asfixia-perinatal-scaled.jpeg","type":"image\/jpeg"}],"author":"Jorge Cabrera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Cabrera","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/"},"author":{"name":"Jorge Cabrera","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/c2351d5dbfb3c87d31141cbb6bbdd081"},"headline":"Evitar y manejar la asfixia perinatal","datePublished":"2020-07-02T10:13:28+00:00","dateModified":"2025-09-29T09:15:15+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/"},"wordCount":1471,"commentCount":4,"image":{"@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portda-asfixia-perinatal-scaled.jpeg","keywords":["asfixia fetal","asfixia perinatal","microtoma"],"articleSection":["Neonatolog\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/campusvygon.com\/es\/asfixia-perinatal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/","url":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/","name":"Evitar y manejar la asfixia perinatal","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portda-asfixia-perinatal-scaled.jpeg","datePublished":"2020-07-02T10:13:28+00:00","dateModified":"2025-09-29T09:15:15+00:00","author":{"@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/c2351d5dbfb3c87d31141cbb6bbdd081"},"description":"Controlar la asfixia perinatal es una prioridad para los profesionales sanitarios. Descubre c\u00f3mo evitar la p\u00e9rdida de bienestar fetal en este art\u00edculo.","breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/asfixia-perinatal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portda-asfixia-perinatal-scaled.jpeg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/09\/Portda-asfixia-perinatal-scaled.jpeg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/asfixia-perinatal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"Evitar y manejar la asfixia perinatal"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/campusvygon.com\/es\/#\/schema\/person\/c2351d5dbfb3c87d31141cbb6bbdd081","name":"Jorge Cabrera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/03\/jorge-carera-foto.jpg","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/03\/jorge-carera-foto.jpg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2024\/03\/jorge-carera-foto.jpg","caption":"Jorge Cabrera"},"description":"Soy comercial especialista en terapias intravenosa y neonatolog\u00eda \u2022 EXPERIENCIA Soy farmac\u00e9utico, especialista en Bioqu\u00edmica, he ejercido como tal tanto en oficinas de farmacia, hospitales y cl\u00ednicas privadas. Pero pronto descubr\u00ed el mundo comercial y el servicio a clientes m\u00e9dicos y sanitarios en general, donde me siento realizado. \u2022 PUEDO AYUDARTE EN... Mi trabajo se basa en conocer las necesidades de mis clientes en el \u00e1mbito sanitario, y aportarles mejoras en sus t\u00e9cnicas diarias con el mejor material del mercado.","sameAs":["http:\/\/www.vygon.es","https:\/\/www.linkedin.com\/in\/jorge-cabrera-perez-33050097\/"],"url":"https:\/\/campusvygon.com\/es\/author\/jcabrera\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/9540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=9540"}],"version-history":[{"count":10,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/9540\/revisions"}],"predecessor-version":[{"id":33055,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/posts\/9540\/revisions\/33055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/48009"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=9540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/categories?post=9540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/tags?post=9540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}