{"id":11567,"date":"2020-08-07T13:00:29","date_gmt":"2020-08-07T11:00:29","guid":{"rendered":"http:\/\/campusvygon.com\/es\/?post_type=project&#038;p=11567"},"modified":"2022-05-09T10:12:40","modified_gmt":"2022-05-09T08:12:40","slug":"gauges-vs-french","status":"publish","type":"project","link":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/","title":{"rendered":"Gauges vs French"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb][et_pb_row _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/08\/Gauges-vs-French.jpg\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb title_text=\u00bbGauges-vs-French\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_button button_url=\u00bbhttps:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/08\/Gauges-vs-French.pdf\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbDescarga: Gauges vs French\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#FFFFFF\u00bb button_bg_color=\u00bb#3f3f3f\u00bb button_font=\u00bb|300|||||||\u00bb button_use_icon=\u00bboff\u00bb custom_padding=\u00bb15px|15px|15px|15px|true|true\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb theme_builder_area=\u00bbpost_content\u00bb button_bg_color__hover=\u00bb#3f3f3f\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":11569,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[390],"project_tag":[],"class_list":["post-11567","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-anestesia-y-cuidados-intensivos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gauges vs French - Campus Vygon Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gauges vs French - Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T08:12:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/08\/Gauges-vs-French.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"735\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/gauges-vs-french\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/gauges-vs-french\\\/\",\"name\":\"Gauges vs French - Campus Vygon Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/gauges-vs-french\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/gauges-vs-french\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/08\\\/Gauges-vs-French.jpg\",\"datePublished\":\"2020-08-07T11:00:29+00:00\",\"dateModified\":\"2022-05-09T08:12:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/gauges-vs-french\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/gauges-vs-french\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/gauges-vs-french\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/08\\\/Gauges-vs-French.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/08\\\/Gauges-vs-French.jpg\",\"width\":735,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/gauges-vs-french\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gauges vs French\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gauges vs French - Campus Vygon Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/","og_locale":"es_ES","og_type":"article","og_title":"Gauges vs French - Campus Vygon Espa\u00f1a","og_url":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/","og_site_name":"Campus Vygon Espa\u00f1a","article_modified_time":"2022-05-09T08:12:40+00:00","og_image":[{"width":735,"height":520,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/08\/Gauges-vs-French.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/","url":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/","name":"Gauges vs French - Campus Vygon Espa\u00f1a","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/08\/Gauges-vs-French.jpg","datePublished":"2020-08-07T11:00:29+00:00","dateModified":"2022-05-09T08:12:40+00:00","breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/08\/Gauges-vs-French.jpg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2020\/08\/Gauges-vs-French.jpg","width":735,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/project\/gauges-vs-french\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/campusvygon.com\/es\/project\/"},{"@type":"ListItem","position":3,"name":"Gauges vs French"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project\/11567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=11567"}],"version-history":[{"count":3,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project\/11567\/revisions"}],"predecessor-version":[{"id":33386,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project\/11567\/revisions\/33386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/11569"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=11567"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project_category?post=11567"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project_tag?post=11567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}