{"id":46551,"date":"2025-07-22T12:36:36","date_gmt":"2025-07-22T10:36:36","guid":{"rendered":"https:\/\/campusvygon.com\/es\/?post_type=project&#038;p=46551"},"modified":"2025-07-22T12:38:12","modified_gmt":"2025-07-22T10:38:12","slug":"beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal","status":"publish","type":"project","link":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/","title":{"rendered":"Beneficios de las sondas de alto flujo en el paciente neonatal"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; theme_builder_area=\u00bbpost_content\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb da_is_popup=\u00bboff\u00bb da_exit_intent=\u00bboff\u00bb da_has_close=\u00bbon\u00bb da_alt_close=\u00bboff\u00bb da_dark_close=\u00bboff\u00bb da_not_modal=\u00bbon\u00bb da_is_singular=\u00bboff\u00bb da_with_loader=\u00bboff\u00bb da_has_shadow=\u00bbon\u00bb da_disable_devices=\u00bboff|off|off\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/07\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb title_text=\u00bbCampus Vygon_Sondas de alto flujo\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243; url=\u00bbhttps:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/07\/Infografia_CampusVygon.-Sondas-de-alto-flujo.pdf\u00bb url_new_window=\u00bbon\u00bb align=\u00bbcenter\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb type=\u00bb4_4&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_button button_text=\u00bbDescarga la infograf\u00eda\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb button_url=\u00bbhttps:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/07\/Infografia_CampusVygon.-Sondas-de-alto-flujo.pdf\u00bb url_new_window=\u00bbon\u00bb button_alignment=\u00bbcenter\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":137,"featured_media":46549,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[391,389],"project_tag":[],"class_list":["post-46551","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-neonatologia","project_category-nutricion-enteral"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beneficios de las sondas de alto flujo en el paciente neonatal - Campus Vygon Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beneficios de las sondas de alto flujo en el paciente neonatal - Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T10:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/07\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\\\/\",\"name\":\"Beneficios de las sondas de alto flujo en el paciente neonatal - Campus Vygon Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg\",\"datePublished\":\"2025-07-22T10:36:36+00:00\",\"dateModified\":\"2025-07-22T10:38:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/07\\\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg\",\"width\":2560,\"height\":1810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/project\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beneficios de las sondas de alto flujo en el paciente neonatal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/\",\"name\":\"Campus Vygon Espa\u00f1a\",\"description\":\"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beneficios de las sondas de alto flujo en el paciente neonatal - Campus Vygon Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/","og_locale":"es_ES","og_type":"article","og_title":"Beneficios de las sondas de alto flujo en el paciente neonatal - Campus Vygon Espa\u00f1a","og_url":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/","og_site_name":"Campus Vygon Espa\u00f1a","article_modified_time":"2025-07-22T10:38:12+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/07\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/","url":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/","name":"Beneficios de las sondas de alto flujo en el paciente neonatal - Campus Vygon Espa\u00f1a","isPartOf":{"@id":"https:\/\/campusvygon.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/07\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg","datePublished":"2025-07-22T10:36:36+00:00","dateModified":"2025-07-22T10:38:12+00:00","breadcrumb":{"@id":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/#primaryimage","url":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/07\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg","contentUrl":"https:\/\/campusvygon.com\/es\/wp-content\/uploads\/sites\/7\/2025\/07\/Campus-Vygon_Sondas-de-alto-flujo-scaled.jpg","width":2560,"height":1810},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/es\/project\/beneficios-de-las-sondas-de-alto-flujo-en-el-paciente-neonatal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/campusvygon.com\/es\/project\/"},{"@type":"ListItem","position":3,"name":"Beneficios de las sondas de alto flujo en el paciente neonatal"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/es\/#website","url":"https:\/\/campusvygon.com\/es\/","name":"Campus Vygon Espa\u00f1a","description":"Un espacio para aprender sobre procedimientos y t\u00e9cnicas sanitarias de la mano de profesionales de referencia.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project\/46551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/comments?post=46551"}],"version-history":[{"count":2,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project\/46551\/revisions"}],"predecessor-version":[{"id":46553,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project\/46551\/revisions\/46553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media\/46549"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/media?parent=46551"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project_category?post=46551"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/es\/wp-json\/wp\/v2\/project_tag?post=46551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}