{"id":36228,"date":"2023-06-07T16:17:22","date_gmt":"2023-06-07T14:17:22","guid":{"rendered":"https:\/\/campusvygon.com\/it\/?p=36228"},"modified":"2024-02-16T14:10:32","modified_gmt":"2024-02-16T13:10:32","slug":"importanza-dellaccesso-arterioso-in-terapia-intensiva","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/","title":{"rendered":"Importanza dell\u2019accesso arterioso in terapia intensiva"},"content":{"rendered":"\n<p>Il posizionamento del catetere arterioso periferico \u00e8 ad oggi una delle procedure pi\u00f9 utilizzate nei reparti di terapia intensiva e sale operatorie. Solitamente posizionato in <strong>arteria radiale <\/strong>con tecnica blind, spesse volte diventa sia per l\u2019operatore che per il paziente pi\u00f9 un problema che una risorsa. <\/p>\n\n\n\n<p>Se ben posizionato e funzionante (accuratezza nella lettura della forma d\u2019onda con segnale stabile anche dopo il flush senza necessit\u00e0 di alcuna mobilizzazione o stabilizzazione dell\u2019arto), invece, <strong>aiuta ad ottimizzare il carico di lavoro<\/strong> di medici ed infermieri, <strong>facilita i prelievi di sangue<\/strong> e <strong>fornisce un accurato e continuo monitoraggio emodinamico.<\/strong><\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Come ottimizzare il segnale pressorio attraverso un corretto accesso arterioso<\/h2>\n\n\n\n<p>Adottare un approccio proattivo al posizionamento di un accesso arterioso andr\u00e0 a ridurre i fenomeni di risonanza e smorzamento che potrebbero condizionare le scelte terapeutiche fatte sul principio del <strong>Gold Directed Therapy<\/strong> [1].<\/p>\n\n\n\n<p>Come suggeriscono anche le linee guida SIAARTI sulla \u2018gestione emodinamica perioperatoria del paziente adulto in chirurgia non cardiaca\u2019, la somministrazione di fluidi e vasopressori dovrebbero essere basati sui valori di <strong>indice cardiaco <\/strong>(CI), <strong>variazione dello stroke volume<\/strong> (SVV), <strong>variazione della pressione di picco<\/strong> (PPV), <strong>apporto di O2<\/strong> (DO2), <strong>resistenze vascolari periferiche<\/strong> (SVR).. e non solamente dai tradizionali segni vitali [2]. <\/p>\n\n\n\n<p>Mentre fino a qualche anno fa queste informazioni erano di difficile rilevazione in quanto richiedevano devices molto pi\u00f9 invasivi, ad oggi esistono tecnologie all\u2019avanguardia e meno invasive che si basano sull\u2019analisi della forma dell\u2019onda di pressione arteriosa: <strong>pulse contour method<\/strong>.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2022\/09\/PRAM-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2022\/09\/PRAM-1024x1024.jpg\" alt=\"\" class=\"wp-image-34724\" style=\"width:624px;height:624px\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2022\/09\/PRAM-980x980.jpg 980w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2022\/09\/PRAM-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Si fa presto quindi a capire quanto sia importante se non fondamentale avere una forma d\u2019onda pi\u00f9 \u2018pulita\u2019 e realistica possibile.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Arteria radiale: come eseguire un corretto&nbsp; posizionamento<\/h2>\n\n\n\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#7ba180\">Anatomia dell&#8217;arteria radiale<\/h4>\n\n\n\n<p>L\u2019arteria radiale pu\u00f2 avere a volte anomalie anatomiche, essere tortuosa, collassabile e mobile, tutto ci\u00f2 pu\u00f2 influire sul <strong>tasso di insuccesso solitamente &lt;10%<\/strong> ma che pu\u00f2 raggiungere anche il 50% in pz in stato di shock. Ripetute punture oltre a far perdere del tempo, possono essere causa di discomfort per il paziente, aumentare il rischio di ematomi e causare spasmi all\u2019arteria, rendendo ancora pi\u00f9 difficile il suo incannulamento. <\/p>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-background\" style=\"background-color:#7ba180\">L\u2019utilizzo dell\u2019eco riduce del 32% l\u2019insuccesso dell\u2019incannulazione al primo tentativo e del 61% la formazione di ematoma [3].<\/p>\n\n\n\n<div style=\"height:65px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image.png\"><img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"681\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image.png\" alt=\"\" class=\"wp-image-36230\" style=\"width:640px;height:483px\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image.png 902w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-480x362.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 902px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:65px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#7ba180\">Eco-guida e AIM method<\/h4>\n\n\n\n<p>L\u2019utilizzo della <strong>guida ecografica<\/strong> per la cateterizzazione dell\u2019arteria radiale, oltre a preservare la salute del vaso, pu\u00f2 supportarci anche nella scelta della zona da pungere. A questo scopo <strong>l\u2019AIM<\/strong> (arterial insertion method) pu\u00f2 fare al caso nostro promuovendo un approccio sistematico che prevede l\u2019utilizzo di un ecografo per valutare l\u2019arteria radiale ad una distanza di circa 4cm dal polso, nella zona conosciuta come \u2018Chi\u2019 (Cheok) in cui l\u2019arteria \u00e8 pi\u00f9 grande, profonda e distante dall\u2019articolazione [4]. <\/p>\n\n\n\n<p>Questa zona essendo lontana dall\u2019articolazione \u00e8 meno influenzata dal movimento ed offre maggior spazio per il fissaggio, il che ci garantisce maggior stabilit\u00e0 dell\u2019accesso con conseguente riduzione di complicanze meccaniche ed infettive, preservando la performance del catetere e di conseguenza la sua vita [4-5].<\/p>\n\n\n\n<div style=\"height:58px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Eco-guida-e-AIM-method-27-1024x311.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"311\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Eco-guida-e-AIM-method-27-1024x311.jpg\" alt=\"\" class=\"wp-image-36241\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Eco-guida-e-AIM-method-27-980x297.jpg 980w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Eco-guida-e-AIM-method-27-480x146.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"569\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Eco-guida-e-AIM-method-28-1-1024x569.jpg\" alt=\"\" class=\"wp-image-36243\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Eco-guida-e-AIM-method-28-1-980x544.jpg 980w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Eco-guida-e-AIM-method-28-1-480x266.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<div style=\"height:58px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-color\" style=\"color:#7ba180\">Test di Allen<\/h4>\n\n\n\n<p>Prima del posizionamento della cannula arteriosa periferica radiale \u00e8 importante valutare il circolo collaterale. Il metodo pi\u00f9 utilizzato \u00e8 il <strong>Test di Allen<\/strong> che nonostante i suoi limiti (soggettivo, range di riperfusione elevato (5-15sec), non applicabile in pz non collaboranti), risulta comparabile al Barbeau test ed al controllo con gli ultrasuoni. <\/p>\n\n\n\n<p>Sta quindi all\u2019operatore la scelta su quale utilizzare ma \u00e8 consigliabile, in caso di Allen dubbio, il controllo con eco color doppler [6]<\/p>\n\n\n\n<div style=\"height:58px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"991\" height=\"742\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-1.png\" alt=\"\" class=\"wp-image-36232\" style=\"width:518px;height:388px\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-1.png 991w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-1-980x734.png 980w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-1-480x359.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 991px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Come scegliere il corretto device arterioso<\/h2>\n\n\n\n<p>Oltre alle valutazioni relative all&#8217;anatomia dell&#8217;arteria radiale ed a quale sia il migliore approccio, \u00e8 fondamentale tenere in considerazione anche alcuni aspetti legati alla scelta del dispositivo da utilizzare.<\/p>\n\n\n\n<p>Infatti, materiale, calibro e lunghezza sono altri fattori che influenzano la durata e la performance del sistema di lettura.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">\u00b7<strong> Materiale<\/strong><\/h4>\n\n\n\n<p>Un materiale troppo termosensibile (poliuretano PUR) tender\u00e0 a modificare la propria struttura, troppo rigido (teflon PTFE) tender\u00e0 a rompersi. <strong>Il polietilene <\/strong>(PE) potrebbe essere l\u2019ideale per il monitoraggio emodinamico in quanto essendo un materiale intermedio per le sue propriet\u00e0 di durezza e memoria permette di mantenere nel tempo una buona trasmissione dell\u2019onda pressoria arteriosa.<\/p>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00b7 Lunghezza e calibro<\/strong><\/h4>\n\n\n\n<p>In base alla formula del coefficiente di assorbimento, un catetere troppo lungo contribuir\u00e0 a smorzare la forma d\u2019onda mentre un catetere troppo corto tender\u00e0 a dislocarsi pi\u00f9 facilmente. <\/p>\n\n\n\n<p>Stessa cosa riguardo il calibro, <strong>pi\u00f9 grande \u00e8 meglio<\/strong>, ma troppo occluder\u00e0 il flusso arterioso con conseguente trombosi ed ipoperfusione dell&#8217;arto [7]<strong>.<\/strong><\/p>\n\n\n\n<p><strong>Il giusto compromesso risulta essere una lunghezza tale da garantire il 65% del catetere all\u2019interno del vaso [8] e un calibro tale da non occludere pi\u00f9 del 45% del lume del vaso [9-10].<\/strong><\/p>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Lunghezza-e-calibro-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"449\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Lunghezza-e-calibro-1024x449.jpg\" alt=\"\" class=\"wp-image-36281\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Lunghezza-e-calibro-980x430.jpg 980w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Lunghezza-e-calibro-480x210.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00b7 Tecnica di inserzione<\/strong><\/h4>\n\n\n\n<p>Per quanto riguarda la tecnica di inserzione, nonostante vari autori indicano di mantenere un <strong>angolo tra 45\u00b0 e 30\u00b0<\/strong> \u00e8 consigliabile, solitamente con <strong>l\u2019aiuto di una guida ecografica con puntura in plane asse lungo<\/strong>, adottare un\u2019angolazione minore (tra 15\u00b0 e 30\u00b0) cos\u00ec da aumentare il tratto sottocutaneo prima dell\u2019ingresso nel vaso, tale da rendere il catetere pi\u00f9 stabile con conseguente riduzione di complicanze meccaniche ed infettive [11]. Da evitare comunque l\u2019inserzione del catetere con un <strong>angolo &gt;45\u00b0 <\/strong>in quanto si aumenterebbe il rischio di kinking con conseguente riduzione di accuratezza nel monitoraggio emodinamico.<\/p>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/02\/foto-relazione-ago-vena.png\"><img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"396\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/02\/foto-relazione-ago-vena.png\" alt=\"\" class=\"wp-image-36727\" style=\"aspect-ratio:1.3333333333333333;width:596px;height:auto\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/02\/foto-relazione-ago-vena.png 492w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/02\/foto-relazione-ago-vena-480x386.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 492px, 100vw\" \/><\/a><\/figure>\n\n\n\n<p class=\"has-text-align-center\">*Used with permission from Imbr\u00ecaco et al. [18]<\/p>\n\n\n\n<div style=\"height:42px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"367\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-2.png\" alt=\"\" class=\"wp-image-36233\" style=\"width:535px;height:291px\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-2.png 675w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/image-2-480x261.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 675px, 100vw\" \/><\/a><\/figure>\n\n\n\n<p class=\"has-text-align-center\">*Used with permission from Imbr\u00ecaco et al. [18]<\/p>\n\n\n\n<div style=\"height:65px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Come ridurre al minimo il rischio di sposizionamento<\/h2>\n\n\n\n<p>Ultimo punto da non sottovalutare una volta posizionato il catetere \u00e8 il rischio di rimozione accidentale e dislocamento. Basti pensare che de<strong>l 20,4% dei cateteri rimossi accidentalmente il 65,3% ha richiesto il riposizionamento per poter continuare la terapia o monitoraggio<\/strong> [12]. <\/p>\n\n\n\n<p>La principale causa \u00e8 imputabile ad inadeguata <strong>medicazione e stabilizzazione<\/strong> per la quale da sempre vengono utilizzati i pi\u00f9 svariati metodi, da punti di sutura a cerotto (sterili e non), da sutureless devices a medicazioni in film di poliuretano. <\/p>\n\n\n\n<p>Mentre le suture non sono pi\u00f9 considerate un appropriato metodo di fissaggio ed il loro approccio \u00e8 considerato ormai una pratica obsoleta in quanto associate a sanguinamento, rischio di puntura da parte dell\u2019operatore, ripetuti cambi di medicazione, crescita di biofilm ed aumentato rischio di infezione del sangue associata a catetere [9-13], una recente revisione non ha trovato prove a sufficienza per suggerire un fissaggio rispetto ad un altro, se non l\u2019utilizzo di una medicazione trasparente semipermeabile in poliuretano che permetta la visualizzazione del punto di inserzione [14]. <\/p>\n\n\n\n<p><strong>Da valutare invece l\u2019utilizzo di colla cianoacrilato per i suoi vari benefici (riduce il sanguinamento, stabilizza il catetere, riduce il rischio di infezione)<\/strong> [15-16-17].<\/p>\n\n\n\n<p>La funzionalit\u00e0 e l\u2019affidabilit\u00e0 del dispositivo arterioso sono essenziali per garantire l\u2019accuratezza del monitoraggio emodinamico continuo, consentire frequenti prelievi ematici, evitare disagi e dolore al paziente, ottimizzare il carico di lavoro degli operatori sanitari.<\/p>\n\n\n\n<div style=\"height:56px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-background\" style=\"background-color:#7ba180\">Ad oggi la guida ecografica risulta essere lo standard che assieme alle strategie cliniche sopra elencate fornisce all\u2019operatore elementi diretti e di facile applicazione definiti dall\u2019acronimo RADIALS [18], protocollo descritto nello studio Imbr\u00ecaco et al., che estendono l\u2019effettiva durata del presidio riducendo al contempo le complicanze prevenibili.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"562\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/02\/protocollo-radials-1.png\" alt=\"\" class=\"wp-image-36726\" style=\"width:695px;height:auto\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/02\/protocollo-radials-1.png 740w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/02\/protocollo-radials-1-480x365.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 740px, 100vw\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\">*Used with permission from Imbr\u00ecaco et al. [18]<\/p>\n\n\n\n<div style=\"height:107px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-divi-layout\">[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.21.0&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.21.0&#8243; background_color=&#8221;gcid-2d45c7f1-05fc-4f3c-8b35-fe69709a6a62&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;55px||55px||true|&#8221; link_option_url=&#8221;https:\/\/www.vygon.it\/catalogo\/applicazioni\/terapia-intensiva\/&#8221; link_option_url_new_window=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;79px&#8221; box_shadow_spread=&#8221;-28px&#8221; global_colors_info=&#8221;{%22gcid-2d45c7f1-05fc-4f3c-8b35-fe69709a6a62%22:%91%22background_color%22%93}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;PRODOTTI CORRELATI&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\uf47d||fa||900&#8243; image_icon_width=&#8221;55px&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/div>\n\n\n\n<div style=\"height:136px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">BIBLIOGRAFIA<\/h2>\n\n\n\n<ol class=\"wp-block-list\" style=\"list-style-type:1\">\n<li>Chong MA, Wang Y, Berbenetz NM, McConachie I. Does goal-directed haemodynamic and fluid therapy improve peri-operative outcomes?: A systematic review and meta-analysis. Eur J Anaesthesiol. 2018 Jul;35(7):469-483. doi: 10.1097\/EJA.0000000000000778. PMID: 29369117.<\/li>\n\n\n\n<li>De Rosa, Rosanna. (2022). LINEE GUIDA Gestione emodinamica perioperatoria del paziente adulto in chirurgia non cardiaca LINEA GUIDA 2022.<\/li>\n\n\n\n<li>Wang A, Hendin A, Millington SJ, Koenig S, Eisen LA, Shiloh AL. Better With Ultrasound: Arterial Line Placement. Chest. 2020 Mar;157(3):574-579. doi: 10.1016\/j.chest.2019.08.2209. Epub 2019 Oct 18. PMID: 31634448.<\/li>\n\n\n\n<li>Bardin-Spencer AJ, Spencer TR. Arterial insertion method: A new method for systematic evaluation of ultrasound-guided radial arterial catheterization. J Vasc Access. 2021 Sep;22(5):733-738. doi: 10.1177\/1129729820944104. Epub 2020 Sep 28. PMID: 32985342.<\/li>\n\n\n\n<li>Gravante F, Lombardi A, Gagliardi AM, Pucci A, Latina R. Dressings and Securement Devices of Peripheral Arterial Catheters in Intensive Care Units and Operating Theaters: A Systematic Review. Dimens Crit Care Nurs. 2020 Sep\/Oct;39(5):242-250. doi: 10.1097\/DCC.0000000000000433. PMID: 32740194.<\/li>\n\n\n\n<li>Kiang SC, Nasiri AJ, Strilaeff RR, Prasad VS, Bharadwaj AS, Miller PA, Abou-Zamzam AM Jr, Tomihama RT. Analysis of Subjective and Objective Screening Techniques as Predictors of Safety for Radial Artery Intervention. Ann Vasc Surg. 2020 May;65:33-39. doi: 10.1016\/j.avsg.2019.11.011. Epub 2019 Nov 11. PMID: 31726202.<\/li>\n\n\n\n<li>Romagnoli S, Ricci Z, Quattrone D, Tofani L, Tujjar O, Villa G, Romano SM, De Gaudio AR. Accuracy of invasive arterial pressure monitoring in cardiovascular patients: an observational study. Crit Care. 2014 Nov 30;18(6):644. doi: 10.1186\/s13054-014-0644-4. PMID: 25433536; PMCID: PMC4279904.<\/li>\n\n\n\n<li>Pandurangadu AV, Tucker J, Brackney AR, Bahl A. Ultrasound-guided intravenous catheter survival impacted by amount of catheter residing in the vein. Emerg Med J. 2018 Sep;35(9):550-555. doi: 10.1136\/emermed-2017-206803. Epub 2018 Jul 18. PMID: 30021833.<\/li>\n\n\n\n<li>Gorski LA, Hadaway L, Hagle ME, Broadhurst D, Clare S, Kleidon T, Meyer BM, Nickel B, Rowley S, Sharpe E, Alexander M. Infusion Therapy Standards of Practice, 8th Edition. J Infus Nurs. 2021 Jan-Feb 01;44(1S Suppl 1):S1-S224. doi: 10.1097\/NAN.0000000000000396. PMID: 33394637.<\/li>\n\n\n\n<li>Spencer TR, Mahoney KJ. Reducing catheter-related thrombosis using a risk reduction tool centered on catheter to vessel ratio. J Thromb Thrombolysis. 2017 Nov;44(4):427-434. doi: 10.1007\/s11239-017-1569-y. PMID: 29022210.<\/li>\n\n\n\n<li>Li X, Fang G, Yang D, Wang L, Zheng C, Ruan L, Wang L. Ultrasonic Technology Improves Radial Artery Puncture and Cannulation in Intensive Care Unit (ICU) Shock Patients. Med Sci Monit. 2016 Jul 11;22:2409-16. doi: 10.12659\/msm.896805. PMID: 27397118; PMCID: PMC4954160.<\/li>\n\n\n\n<li>Galazzi A, Adamini I, Consonni D, Roselli P, Rancati D, Ghilardi G, Greco G, Salinaro G, Laquintana D. Accidental removal of devices in intensive care unit: An eight-year observational study. Intensive Crit Care Nurs. 2019 Oct;54:34-38. doi: 10.1016\/j.iccn.2019.06.002. Epub 2019 Jun 22. PMID: 31235215.<\/li>\n\n\n\n<li>O&#8217;Grady NP, Alexander M, Burns LA, Dellinger EP, Garland J, Heard SO, Lipsett PA, Masur H, Mermel LA, Pearson ML, Raad II, Randolph AG, Rupp ME, Saint S; Healthcare Infection Control Practices Advisory Committee (HICPAC). Guidelines for the prevention of intravascular catheter-related infections. Clin Infect Dis. 2011 May;52(9):e162-93. doi: 10.1093\/cid\/cir257. Epub 2011 Apr 1. PMID: 21460264; PMCID: PMC3106269.<\/li>\n\n\n\n<li>Kim JU, Lee YJ, Lee J, Kim JY. Differences in the Properties of the Radial Artery between Cun, Guan, Chi, and Nearby Segments Using Ultrasonographic Imaging: A Pilot Study on Arterial Depth, Diameter, and Blood Flow. Evid Based Complement Alternat Med. 2015;2015:381634. doi: 10.1155\/2015\/381634. Epub 2015 Feb 11. PMID: 25763090; PMCID: PMC4339866.<\/li>\n\n\n\n<li>Prince D, Solanki Z, Varughese R, Mastej J, Prince D. Antibacterial effect and proposed mechanism of action of a topical surgical adhesive. Am J Infect Control. 2018 Jan;46(1):26-29. doi: 10.1016\/j.ajic.2017.07.008. Epub 2017 Aug 24. PMID: 28844382.<\/li>\n\n\n\n<li>Gilardi E, Piano A, Chellini P, Fiori B, Dolcetti L, Pittiruti M, Scoppettuolo G. Reduction of bacterial colonization at the exit site of peripherally inserted central catheters: A comparison between chlorhexidine-releasing sponge dressings and cyano-acrylate. J Vasc Access. 2021 Jul;22(4):597-601. doi: 10.1177\/1129729820954743. Epub 2020 Sep 4. PMID: 32883154.<\/li>\n\n\n\n<li>Nicholson J, Hill J. Cyanoacrylate tissue adhesive: a new tool for the vascular access toolbox. Br J Nurs. 2019 Oct 24;28(19):S22-S28. doi: 10.12968\/bjon.2019.28.19.S22. PMID: 31647725.<\/li>\n\n\n\n<li>Imbr\u00ecaco G, Monesi A, Spencer TR. Preventing radial arterial catheter failure in critical care &#8211; Factoring updated clinical strategies and techniques. Anaesthesia Critical Care &amp; Pain Medicine. 2022 Aug 1;41(4):101096. doi: 10.1016\/j.accpm.2022.101096. Epub 2022 Apr 28. PMID: 35490863.&nbsp;<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il posizionamento del catetere arterioso periferico \u00e8 ad oggi una delle procedure pi\u00f9 utilizzate nei reparti di terapia intensiva e sale operatorie. Solitamente posizionato in arteria radiale con tecnica blind, spesse volte diventa sia per l\u2019operatore che per il paziente pi\u00f9 un problema che una risorsa. Se ben posizionato e funzionante (accuratezza nella lettura della [&hellip;]<\/p>\n","protected":false},"author":120,"featured_media":36267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[646,643],"tags":[664,716],"class_list":["post-36228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acceso-vascolare","category-anestesia-e-terapia-intensiva","tag-acceso-vascolare","tag-terapia-intensiva"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Importanza dell\u2019accesso arterioso in terapia intensiva - Campus Vygon Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Importanza dell\u2019accesso arterioso in terapia intensiva - Campus Vygon Italia\" \/>\n<meta property=\"og:description\" content=\"Il posizionamento del catetere arterioso periferico \u00e8 ad oggi una delle procedure pi\u00f9 utilizzate nei reparti di terapia intensiva e sale operatorie. Solitamente posizionato in arteria radiale con tecnica blind, spesse volte diventa sia per l\u2019operatore che per il paziente pi\u00f9 un problema che una risorsa. Se ben posizionato e funzionante (accuratezza nella lettura della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vygon-Italia-102738545680399\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-07T14:17:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T13:10:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"634\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simone Pirri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone Pirri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/\"},\"author\":{\"name\":\"Simone Pirri\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#\\\/schema\\\/person\\\/b6b6d6f31ac86b6c1ee55c122dfc84d2\"},\"headline\":\"Importanza dell\u2019accesso arterioso in terapia intensiva\",\"datePublished\":\"2023-06-07T14:17:22+00:00\",\"dateModified\":\"2024-02-16T13:10:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/\"},\"wordCount\":1978,\"publisher\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg\",\"keywords\":[\"Accesso vascolare\",\"Terapia intensiva\"],\"articleSection\":[\"Accesso Vascolare\",\"Anestesia e Terapia Intensiva\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/\",\"name\":\"Importanza dell\u2019accesso arterioso in terapia intensiva - Campus Vygon Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg\",\"datePublished\":\"2023-06-07T14:17:22+00:00\",\"dateModified\":\"2024-02-16T13:10:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg\",\"width\":634,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/importanza-dellaccesso-arterioso-in-terapia-intensiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Importanza dell\u2019accesso arterioso in terapia intensiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/\",\"name\":\"Campus Vygon Italia\",\"description\":\"Uno spazio dove imparare le procedure e le tecniche sanitarie dalla mano dei migliori professionisti del settore. Creato da e per gli specialisti della sanit\u00e0.\",\"publisher\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#organization\",\"name\":\"Campus Vygon Italia\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvit.b-cdn.net\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/02\\\/VYGON-ITALIA.jpg\",\"contentUrl\":\"https:\\\/\\\/cvit.b-cdn.net\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/02\\\/VYGON-ITALIA.jpg\",\"width\":703,\"height\":703,\"caption\":\"Campus Vygon Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vygon-Italia-102738545680399\",\"https:\\\/\\\/www.instagram.com\\\/campusvygonitalia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vygon-italia-srl\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCg8IwloH03GkRqQs0mLskHA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#\\\/schema\\\/person\\\/b6b6d6f31ac86b6c1ee55c122dfc84d2\",\"name\":\"Simone Pirri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/amicucci_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/amicucci_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/06\\\/amicucci_avatar-96x96.jpg\",\"caption\":\"Simone Pirri\"},\"description\":\"Sono infermiere, laureato nel 2008 preso la Sapienza Universit\u00e0 di Roma; il percorso di studi \u00e8 proseguito con un master in management coordinamento delle professioni sanitarie e formazione specifica per posizionamento di PICC. Dopo tre anni di esperienza presso la terapia intensiva del centro cardiochirurgico Hesperia Hospital di Modena, dal 2012 lavoro in rianimazione e terapia intensiva dell\u2019Azienda Ospedaliero Universitaria Senese dove mi occupo anche delle docenze nel master di I livello in Infermieristica di area critica e dell\u2019emergenza.\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/author\\\/amicucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Importanza dell\u2019accesso arterioso in terapia intensiva - Campus Vygon Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/","og_locale":"it_IT","og_type":"article","og_title":"Importanza dell\u2019accesso arterioso in terapia intensiva - Campus Vygon Italia","og_description":"Il posizionamento del catetere arterioso periferico \u00e8 ad oggi una delle procedure pi\u00f9 utilizzate nei reparti di terapia intensiva e sale operatorie. Solitamente posizionato in arteria radiale con tecnica blind, spesse volte diventa sia per l\u2019operatore che per il paziente pi\u00f9 un problema che una risorsa. Se ben posizionato e funzionante (accuratezza nella lettura della [&hellip;]","og_url":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/","og_site_name":"Campus Vygon Italia","article_publisher":"https:\/\/www.facebook.com\/Vygon-Italia-102738545680399","article_published_time":"2023-06-07T14:17:22+00:00","article_modified_time":"2024-02-16T13:10:32+00:00","og_image":[{"width":634,"height":475,"url":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg","type":"image\/jpeg"}],"author":"Simone Pirri","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Simone Pirri","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/"},"author":{"name":"Simone Pirri","@id":"https:\/\/campusvygon.com\/it\/#\/schema\/person\/b6b6d6f31ac86b6c1ee55c122dfc84d2"},"headline":"Importanza dell\u2019accesso arterioso in terapia intensiva","datePublished":"2023-06-07T14:17:22+00:00","dateModified":"2024-02-16T13:10:32+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/"},"wordCount":1978,"publisher":{"@id":"https:\/\/campusvygon.com\/it\/#organization"},"image":{"@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg","keywords":["Accesso vascolare","Terapia intensiva"],"articleSection":["Accesso Vascolare","Anestesia e Terapia Intensiva"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/","url":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/","name":"Importanza dell\u2019accesso arterioso in terapia intensiva - Campus Vygon Italia","isPartOf":{"@id":"https:\/\/campusvygon.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg","datePublished":"2023-06-07T14:17:22+00:00","dateModified":"2024-02-16T13:10:32+00:00","breadcrumb":{"@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/#primaryimage","url":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg","contentUrl":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/Importanza-dellaccesso-arterioso-in-terapia-intensiva.jpg","width":634,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/it\/importanza-dellaccesso-arterioso-in-terapia-intensiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/it\/"},{"@type":"ListItem","position":2,"name":"Importanza dell\u2019accesso arterioso in terapia intensiva"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/it\/#website","url":"https:\/\/campusvygon.com\/it\/","name":"Campus Vygon Italia","description":"Uno spazio dove imparare le procedure e le tecniche sanitarie dalla mano dei migliori professionisti del settore. Creato da e per gli specialisti della sanit\u00e0.","publisher":{"@id":"https:\/\/campusvygon.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/campusvygon.com\/it\/#organization","name":"Campus Vygon Italia","url":"https:\/\/campusvygon.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/campusvygon.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cvit.b-cdn.net\/wp-content\/uploads\/sites\/3\/2022\/02\/VYGON-ITALIA.jpg","contentUrl":"https:\/\/cvit.b-cdn.net\/wp-content\/uploads\/sites\/3\/2022\/02\/VYGON-ITALIA.jpg","width":703,"height":703,"caption":"Campus Vygon Italia"},"image":{"@id":"https:\/\/campusvygon.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vygon-Italia-102738545680399","https:\/\/www.instagram.com\/campusvygonitalia\/","https:\/\/www.linkedin.com\/company\/vygon-italia-srl","https:\/\/www.youtube.com\/channel\/UCg8IwloH03GkRqQs0mLskHA"]},{"@type":"Person","@id":"https:\/\/campusvygon.com\/it\/#\/schema\/person\/b6b6d6f31ac86b6c1ee55c122dfc84d2","name":"Simone Pirri","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/amicucci_avatar-96x96.jpg","url":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/amicucci_avatar-96x96.jpg","contentUrl":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/06\/amicucci_avatar-96x96.jpg","caption":"Simone Pirri"},"description":"Sono infermiere, laureato nel 2008 preso la Sapienza Universit\u00e0 di Roma; il percorso di studi \u00e8 proseguito con un master in management coordinamento delle professioni sanitarie e formazione specifica per posizionamento di PICC. Dopo tre anni di esperienza presso la terapia intensiva del centro cardiochirurgico Hesperia Hospital di Modena, dal 2012 lavoro in rianimazione e terapia intensiva dell\u2019Azienda Ospedaliero Universitaria Senese dove mi occupo anche delle docenze nel master di I livello in Infermieristica di area critica e dell\u2019emergenza.","url":"https:\/\/campusvygon.com\/it\/author\/amicucci\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/posts\/36228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/users\/120"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/comments?post=36228"}],"version-history":[{"count":13,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/posts\/36228\/revisions"}],"predecessor-version":[{"id":36729,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/posts\/36228\/revisions\/36729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/media\/36267"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/media?parent=36228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/categories?post=36228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/tags?post=36228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}