{"id":36806,"date":"2024-04-11T11:55:41","date_gmt":"2024-04-11T09:55:41","guid":{"rendered":"https:\/\/campusvygon.com\/it\/?p=36806"},"modified":"2024-05-08T16:00:27","modified_gmt":"2024-05-08T14:00:27","slug":"case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce","status":"publish","type":"post","link":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/","title":{"rendered":"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE"},"content":{"rendered":"\n<p>Le <strong>Linee Guida SIAARTI<\/strong> sulla \u201c<em>Gestione emodinamica perioperatoria del paziente adulto in chirurgia non cardiaca<\/em>\u201d suggeriscono l\u2019utilizzo di dispositivi per il monitoraggio emodinamico in grado di stimare e monitorare lo Stroke Volume e la Gittata Cardiaca associati al calcolo del Delivery di Ossigeno DO<sub>2<\/sub>, insieme a parametri dinamici quali la Variazione della Pressione di Picco (PPV) e la Variazione dello Stroke Volume (SVV), in pazienti ad alto rischio sottoposti a chirurgia non cardiaca.<\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-background has-link-color wp-elements-4d9ac2d9d5c54482fe246998f36bbd9f\" style=\"background-color:#7ba180\"><em>Parametri statici quali le pressioni arteriose non sono infatti indicativi del debito d\u2019ossigeno in cui pu\u00f2 incorrere il paziente, perch\u00e9 alterati da meccanismi di compensazione dell\u2019organismo.<\/em><\/p>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>In passato queste informazioni erano di difficile accesso perch\u00e9 richiedevano misurazioni molto invasive, a cui era associata una certa probabilit\u00e0 di complicanze per il paziente. Ad oggi esistono invece dei sistemi di monitoraggio emodinamico molto meno invasivi e che si basano sull\u2019analisi della forma d\u2019onda di pressione arteriosa per calcolare lo Stroke Volume del paziente e, a cascata, tutti gli altri parametri emodinamici. Questi sistemi si chiamano <strong><em>Pulse Contour Method<\/em> PCM<\/strong> e <strong>legano le variazioni di pressione arteriosa alle variazioni della gittata sistolica.<\/strong><\/p>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2022\/09\/PRAM-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2022\/09\/PRAM-1024x1024.jpg\" alt=\"\" class=\"wp-image-34724\" style=\"width:596px;height:auto\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2022\/09\/PRAM-980x980.jpg 980w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2022\/09\/PRAM-480x480.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Storicamente questi sistemi sono sempre stati considerati meno affidabili delle metodiche pi\u00f9 invasive, ma la tecnologia su cui alcuni di loro si basano, come ad esempio i sistemi che implementano il brevettato algoritmo PRAM, ha permesso di ottenere risultati paragonabili a quelli dello Swan Ganz, della termodiluizione e dell\u2019ecocardiografia.<\/p>\n\n\n\n<p>Oltre a stroke volume, gittata cardiaca, resistenze e indici di riempimento, esistono altri parametri che possono dare informazioni rilevanti su ulteriori aspetti clinici del paziente. Data l\u2019affidabilit\u00e0 di questi parametri ottenuti con le tecnologie pi\u00f9 recenti, \u00e8 stato possibile indagare approfonditamente questi aspetti e ottenere importanti consapevolezze su come utilizzarli nella pratica clinica.<\/p>\n\n\n\n<p>Descriviamo in seguito un case report in cui si \u00e8 rivelato di cruciale importanza il cosiddetto <strong>CCE, l\u2019Indice di efficienza del ciclo cardiaco<\/strong> reso disponibile dall\u2019algoritmo PRAM.<\/p>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"475\" height=\"229\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/image.png\" alt=\"\" class=\"wp-image-36808\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/image.png 475w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/image-300x145.png 300w\" sizes=\"(max-width: 475px) 100vw, 475px\" \/><\/figure>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>L\u2019indice di efficienza del ciclo cardiaco<\/strong> descrive le prestazioni emodinamiche in termini di dispendio energetico, considera l\u2019energia richiesta al cuore per generare un determinato stroke volume, che dipende dall\u2019interazione tra la funzione della pompa e il sistema arterioso.<\/p>\n\n\n\n<p>Il CCE pu\u00f2 cambiare in base alle diverse condizioni cliniche (ad es. bradicardia, tachicardia, scarsa contrattilit\u00e0 miocardica, aumento o riduzione del ritorno venoso, cambiamenti della resistenza vascolare sistemica) e pu\u00f2 essere utile per valutare la risposta emodinamica ai farmaci cardioattivi e vasoattivi. Inoltre, il monitoraggio dell\u2019andamento del CCE pu\u00f2 essere utile nella prevenzione di alterazioni emodinamiche impreviste e pu\u00f2 aiutare nel processo decisionale clinico.<\/p>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>PRESENTAZIONE DEL CASO<\/strong><\/h2>\n\n\n\n<p>Il paziente era un ragazzo di 17 anni che necessitava di essere sottoposto ad un intervento chirurgico addominale a causa di una massa tumorale retroperitoneale (20\u00d730 cm) che dislocava fegato, duodeno, pancreas e rene destro. L&#8217;anamnesi e gli esami cardio-respiratori preoperatori erano normali e il paziente era un giocatore di calcio professionista. Il giorno prima dell&#8217;intervento \u00e8 stata eseguita un&#8217;embolizzazione angiografica del tumore allo scopo di ridurre il sanguinamento intraoperatorio.<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-f2733928bcbf17065ccd2b75801f2815\" style=\"color:#7ba180\"><strong>Durante l&#8217;intervento sono stati monitorati i seguenti parametri:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>pressione arteriosa<\/strong> ABP<\/li>\n\n\n\n<li><strong>frequenza cardiaca<\/strong> HR,<\/li>\n\n\n\n<li><strong>saturazione arteriosa di ossigeno<\/strong> SaO<sub>2<\/sub><\/li>\n\n\n\n<li><strong>pressione venosa centrale<\/strong> PVC<\/li>\n<\/ul>\n\n\n\n<p>Inoltre, prima dell&#8217;induzione dell&#8217;anestesia \u00e8 stato introdotto un catetere dell&#8217;arteria radiale, per valutare i parametri emodinamici del paziente tramite sistema di monitoraggio mininvasivo non calibrato che analizza il segnale di pressione arterioso attraverso algoritmo PRAM.<\/p>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-bc813faddb7292c7a6011e56933d9f1f\" style=\"color:#7ba180\"><strong>Le variabili emodinamiche fornite sono le seguenti:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>gittata cardiaca\/indice<\/strong> CO\/CI,<\/li>\n\n\n\n<li><strong>resistenze vascolari sistemiche<\/strong> SVR\/SVRI,<\/li>\n\n\n\n<li><strong>variazione dello stroke volume<\/strong> SVV e<strong> variazione della pressione del polso<\/strong> PPV,<\/li>\n\n\n\n<li><strong>indice di contrattilit\u00e0<\/strong> dP\/dt<sub>max<\/sub><\/li>\n\n\n\n<li><strong>efficienza del ciclo cardiaco<\/strong> CCE<\/li>\n<\/ul>\n\n\n\n<div style=\"height:35px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>DIAGNOSTICA DURANTE L\u2019INTERVENTO<\/strong><\/h2>\n\n\n\n<p>Durante i primi venti minuti dell&#8217;intervento, mentre i chirurghi iniziavano l&#8217;isolamento della massa tumorale dai principali vasi intra-addominali, i valori del paziente erano normali:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pressione arteriosa media: 104 mmHg<\/li>\n\n\n\n<li>Frequenza cardiaca media: 91 battiti\/min<\/li>\n<\/ul>\n\n\n\n<p>Allo stesso tempo, i valori emodinamici erano invece inaspettatamente alterati:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>CI: 1,5-1,8 l\/min\/m<sup>2<\/sup><\/li>\n\n\n\n<li>SVR 2000 dynes\u00d7sec\/cm<sup>5<\/sup><\/li>\n\n\n\n<li>dP\/dt<sub>max<\/sub> molto basso<\/li>\n\n\n\n<li>CCE: -0,8 e -0,9<\/li>\n<\/ul>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/DIAGNOSTICA-DURANTE-LINTERVENTO.png\"><img loading=\"lazy\" decoding=\"async\" width=\"531\" height=\"320\" src=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/DIAGNOSTICA-DURANTE-LINTERVENTO.png\" alt=\"\" class=\"wp-image-36809\" srcset=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/DIAGNOSTICA-DURANTE-LINTERVENTO.png 531w, https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/DIAGNOSTICA-DURANTE-LINTERVENTO-480x289.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 531px, 100vw\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:72px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Una condizione quindi di bassa CI associata a un aumento della SVR, ed un dispendio energetico dato dal CCE molto elevato per il mantenimento dell&#8217;attuale stato emodinamico.<\/p>\n\n\n\n<p>I livelli di lattato, inoltre, hanno mostrato un aumento rispetto ai valori basali ottenuti con un prelievo di sangue arterioso prima dell&#8217;induzione dell&#8217;anestesia (3,5 vs. 1,2 mEq\/l), suggerendo un sorprendente sbilanciamento dell&#8217;apporto di ossigeno rispetto alle esigenze dei tessuti.<\/p>\n\n\n\n<p>Con dei valori di PPV del 13%, di SVV del 14% e una PVC di 14 mmHg, e dopo aver escluso una causa chirurgica di alterato ritorno venoso (cio\u00e8 un&#8217;ostruzione meccanica del drenaggio venoso epatico), \u00e8 stato somministrato un carico di liquidi di 250 ml di soluzione di ringer lattato (3,3 ml\/Kg).<\/p>\n\n\n\n<p>La PVC \u00e8 aumentata rapidamente a 20 mmHg senza che si verificasse alcun miglioramento di CI, SVR o HR.<\/p>\n\n\n\n<p>Si \u00e8 quindi deciso di eseguire un ecocardiogramma transesofageo (TEE), al fine di escludere altre cause di compromissione emodinamica (ad es. tamponamento cardiaco).<\/p>\n\n\n\n<p><strong>L&#8217;esame ha mostrato una disfunzione sistolica di entrambi i ventricoli:<\/strong> la frazione di eiezione del ventricolo sinistro era del 35%; la variazione dell&#8217;area frazionale del ventricolo destro era stimata al 18% e l&#8217;escursione sistolica del piano anulare della tricuspide era di 10 mm.<\/p>\n\n\n\n<div style=\"height:52px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>GESTIONE TERAPEUTICA<\/strong><\/h2>\n\n\n\n<p>Non sono stati effettuati ulteriori aggiustamenti emodinamici, se non per evitare l&#8217;ipovolemia, tenendo conto che la concentrazione di lattato \u00e8 progressivamente diminuita. Non sono stati effettuati altri interventi (ad es. farmaci inotropi) perch\u00e9 era noto che gli adattamenti fisiologici, caratterizzati principalmente da tachicardia compensatoria e ridistribuzione del flusso sanguigno agli organi, erano in grado di compensare la disfunzione cardiaca temporanea. La concentrazione di lattato, la pressione arteriosa e la diuresi sono state utilizzate come marcatori della perfusione e dell&#8217;ossigenazione dei tessuti.<\/p>\n\n\n\n<p>Dopo l&#8217;isolamento dalla circolazione sistemica del tumore e dell&#8217;asportazione del surrene, il CI ha mostrato un brusco aumento e i valori di CCE sono progressivamente aumentati fino a raggiungere il valore zero in prossimit\u00e0 dell&#8217;estrazione del tumore. \u00c8 da notare che durante l&#8217;intera operazione la pressione arteriosa sistolica \u00e8 rimasta stabile, mentre la diastolica e l&#8217;HR hanno mostrato una leggera diminuzione.<\/p>\n\n\n\n<p>Un&#8217;ulteriore TEE, eseguita al termine dell&#8217;intervento, ha mostrato un miglioramento globale della funzione sistolica ventricolare sia sinistra che destra (frazione di eiezione ventricolare sinistra= 45%; variazione dell&#8217;area frazionale ventricolare destra= 25% ed escursione sistolica del piano anulare tricuspidale= 16 mm).<\/p>\n\n\n\n<p>Dopo l&#8217;intervento, il paziente \u00e8 stato trasferito nell&#8217;unit\u00e0 di terapia intensiva generale (ICU) per uno stretto monitoraggio emodinamico fino al completo recupero della funzione cardiaca nelle 24 ore successive. L&#8217;esame istologico ha identificato il tumore come un adenocarcinoma e prima della dimissione del paziente dall&#8217;ospedale l&#8217;esame cardiologico ha confermato il completo recupero della funzione cardiaca.<\/p>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>VANTAGGI DEL MONITORAGGIO EMODINAMICO AVANZATO E DELL&#8217;UTILIZZO DI NUOVE VARIABILI COME L\u2019EFFICIENZA DEL CICLO CARDIACO<\/strong><\/h2>\n\n\n\n<p>Nel caso in esame, un sistema di monitoraggio emodinamico pi\u00f9 invasivo sarebbe stato considerato inutile e inappropriato, poich\u00e9 il paziente non era considerato ad alto rischio.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-background has-link-color wp-elements-26767e0a63c139e9b327a80fd75b310b\" style=\"background-color:#7ba180\"><em>Un sistema di monitoraggio emodinamico mininvasivo ma affidabile basato sull\u2019analisi della pressione arteriosa ha fornito un allarme precoce che ha suggerito di approfondire la condizione clinica del paziente e scoprire un&#8217;inattesa disfunzione bi-ventricolare. Il monitoraggio standard basato su pressione arteriosa e HR si \u00e8 rivelato incapace di rilevare il problema.<\/em><\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Nonostante la bassa CO, non \u00e8 stato utilizzato alcun supporto inotropo perch\u00e9, sebbene gli agenti inotropi possano essere utili per ripristinare i parametri emodinamici e migliorare la perfusione degli organi periferici, possono anche aumentare la mortalit\u00e0 a breve e lungo termine. Il paziente sembrava compensare la disfunzione cardiaca poich\u00e9 la concentrazione di lattato \u00e8 progressivamente diminuita. \u00c8 interessante notare che un basso valore di CCE, anormale per un sistema cardiovascolare sano, suggerisce l&#8217;attivazione di meccanismi di compensazione dell&#8217;impedenza arteriosa dinamica.<\/p>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-background has-link-color wp-elements-8ab3cd7f6492d4480ec4ee8956f73d82\" style=\"background-color:#7ba180\"><em>Senza il monitoraggio emodinamico, un&#8217;insufficienza cardiaca acuta, come quella descritta nel caso in esame, avrebbe potuto essere sospettata solo dopo il fallimento dei meccanismi di compensazione. Inoltre, le potenziali conseguenze negative, tra cui il rischio di sovraccarico di liquidi o l&#8217;uso non corretto di amine vasoattive, avrebbero potuto peggiorare le condizioni del paziente.<\/em><\/p>\n\n\n\n<div style=\"height:97px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">BIBLIOGRAFIA<\/h2>\n\n\n\n<p>Chong MA, Wang Y, Berbenetz NM, McConachie I. Does goal-directed haemodynamic and fluid therapy improve peri-operative outcomes?: A systematic review and meta-analysis. Eur J Anaesthesiol. 2018 Jul;35(7):469-483. doi: 10.1097\/EJA.0000000000000778. PMID: 29369117.<\/p>\n\n\n\n<p>Greiwe G, Luehsen K, Hapfelmeier A, Rogge D, Kubik M, Schulte-Uentrop L, Saugel B. <em>Cardiac output estimation by pulse wave analysis using the pressure recording analytical method and intermittent pulmonary artery thermodilution: A method comparison<\/em> <em>study after off-pump coronary artery bypass surgery. <\/em>Eur J Anaesthesiol. 2020 Oct;37(10):920-925. doi: 10.1097\/EJA.0000000000001227. PMID: 32398582.<\/p>\n\n\n\n<p>Scolletta S, Franchi F, Romagnoli S, Carl\u00e0 R, Donati A, Fabbri LP, Forfori F, Alonso-I\u00f1igo JM, Laviola S, Mangani V, Maj G, Martinelli G, Mirabella L, Morelli A, Persona P, Payen D; <em>Pulse wave analysis Cardiac Output validation (PulseCOval) Group. Comparison Between<\/em> <em>Doppler-Echocardiography and Uncalibrated Pulse Contour Method for Cardiac Output Measurement: A Multicenter Observational Study.<\/em> Crit Care Med. 2016 Jul;44(7):1370-9. doi: 10.1097\/CCM.0000000000001663. PMID: 27097293.<\/p>\n\n\n\n<p>Pavoni V, Romagnoli S, Batignani G, Gianesello L, Horton A, Romano SM<em>. <\/em><em>Unsuspected Heart Failure: Usefulness of a Minimally Invasive Hemodynamic Monitoring System<\/em>. <em>J Anesth Clin Res<\/em> 2012; 3(8).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Linee Guida SIAARTI sulla \u201cGestione emodinamica perioperatoria del paziente adulto in chirurgia non cardiaca\u201d suggeriscono l\u2019utilizzo di dispositivi per il monitoraggio emodinamico in grado di stimare e monitorare lo Stroke Volume e la Gittata Cardiaca associati al calcolo del Delivery di Ossigeno DO2, insieme a parametri dinamici quali la Variazione della Pressione di Picco [&hellip;]<\/p>\n","protected":false},"author":131,"featured_media":36810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[643],"tags":[719],"class_list":["post-36806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anestesia-e-terapia-intensiva","tag-monitoraggio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE - Campus Vygon Italia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE - Campus Vygon Italia\" \/>\n<meta property=\"og:description\" content=\"Le Linee Guida SIAARTI sulla \u201cGestione emodinamica perioperatoria del paziente adulto in chirurgia non cardiaca\u201d suggeriscono l\u2019utilizzo di dispositivi per il monitoraggio emodinamico in grado di stimare e monitorare lo Stroke Volume e la Gittata Cardiaca associati al calcolo del Delivery di Ossigeno DO2, insieme a parametri dinamici quali la Variazione della Pressione di Picco [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Vygon Italia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vygon-Italia-102738545680399\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-11T09:55:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T14:00:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ida Maroni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ida Maroni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/\"},\"author\":{\"name\":\"Ida Maroni\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#\\\/schema\\\/person\\\/042980c2069c32f5c5fd878123310dc3\"},\"headline\":\"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE\",\"datePublished\":\"2024-04-11T09:55:41+00:00\",\"dateModified\":\"2024-05-08T14:00:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/\"},\"wordCount\":1528,\"publisher\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/04\\\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg\",\"keywords\":[\"Monitoraggio\"],\"articleSection\":[\"Anestesia e Terapia Intensiva\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/\",\"name\":\"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE - Campus Vygon Italia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/04\\\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg\",\"datePublished\":\"2024-04-11T09:55:41+00:00\",\"dateModified\":\"2024-05-08T14:00:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/04\\\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/04\\\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg\",\"width\":1024,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/\",\"name\":\"Campus Vygon Italia\",\"description\":\"Uno spazio dove imparare le procedure e le tecniche sanitarie dalla mano dei migliori professionisti del settore. Creato da e per gli specialisti della sanit\u00e0.\",\"publisher\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#organization\",\"name\":\"Campus Vygon Italia\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cvit.b-cdn.net\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/02\\\/VYGON-ITALIA.jpg\",\"contentUrl\":\"https:\\\/\\\/cvit.b-cdn.net\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/02\\\/VYGON-ITALIA.jpg\",\"width\":703,\"height\":703,\"caption\":\"Campus Vygon Italia\"},\"image\":{\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vygon-Italia-102738545680399\",\"https:\\\/\\\/www.instagram.com\\\/campusvygonitalia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vygon-italia-srl\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCg8IwloH03GkRqQs0mLskHA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/#\\\/schema\\\/person\\\/042980c2069c32f5c5fd878123310dc3\",\"name\":\"Ida Maroni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/idam_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/idam_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/idam_avatar-96x96.jpg\",\"caption\":\"Ida Maroni\"},\"description\":\"Sono Product Specialist e mi occupo delle Business Unit \u201cPain and Airway Management\u201d e \u201cCritical Care\u201d all\u2019interno di Vygon, per le quali seguo le regioni del Nord Est dell\u2019Italia. Ho conseguito la mia Laurea Magistrale in Ingegneria Biomedica al Politecnico di Milano e recentemente un Master in \u201cMarket Access - Valutazione delle Tecnologie Sanitarie\u201d dell\u2019Alta Scuola di Economia e Management dei Sistemi Sanitari presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Roma. Seguo il percorso dei nostri dispositivi medici dalle prima fasi del loro utilizzo, confrontandomi con i professionisti sanitari e fornendo loro il supporto necessario per svolgere al meglio il loro prezioso lavoro di assistenza al paziente in fasi cos\u00ec delicate del suo percorso.\",\"url\":\"https:\\\/\\\/campusvygon.com\\\/it\\\/author\\\/idam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE - Campus Vygon Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/","og_locale":"it_IT","og_type":"article","og_title":"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE - Campus Vygon Italia","og_description":"Le Linee Guida SIAARTI sulla \u201cGestione emodinamica perioperatoria del paziente adulto in chirurgia non cardiaca\u201d suggeriscono l\u2019utilizzo di dispositivi per il monitoraggio emodinamico in grado di stimare e monitorare lo Stroke Volume e la Gittata Cardiaca associati al calcolo del Delivery di Ossigeno DO2, insieme a parametri dinamici quali la Variazione della Pressione di Picco [&hellip;]","og_url":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/","og_site_name":"Campus Vygon Italia","article_publisher":"https:\/\/www.facebook.com\/Vygon-Italia-102738545680399","article_published_time":"2024-04-11T09:55:41+00:00","article_modified_time":"2024-05-08T14:00:27+00:00","og_image":[{"width":1024,"height":512,"url":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg","type":"image\/jpeg"}],"author":"Ida Maroni","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Ida Maroni","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/#article","isPartOf":{"@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/"},"author":{"name":"Ida Maroni","@id":"https:\/\/campusvygon.com\/it\/#\/schema\/person\/042980c2069c32f5c5fd878123310dc3"},"headline":"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE","datePublished":"2024-04-11T09:55:41+00:00","dateModified":"2024-05-08T14:00:27+00:00","mainEntityOfPage":{"@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/"},"wordCount":1528,"publisher":{"@id":"https:\/\/campusvygon.com\/it\/#organization"},"image":{"@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg","keywords":["Monitoraggio"],"articleSection":["Anestesia e Terapia Intensiva"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/","url":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/","name":"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE - Campus Vygon Italia","isPartOf":{"@id":"https:\/\/campusvygon.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/#primaryimage"},"image":{"@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/#primaryimage"},"thumbnailUrl":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg","datePublished":"2024-04-11T09:55:41+00:00","dateModified":"2024-05-08T14:00:27+00:00","breadcrumb":{"@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/#primaryimage","url":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg","contentUrl":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2024\/04\/MONITORAGGIO-EMODINAMICO-AVANZATO.jpg","width":1024,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/campusvygon.com\/it\/case-report-limportanza-del-monitoraggio-emodinamico-avanzato-e-dei-nuovi-parametri-come-lefficienza-del-ciclo-cardiaco-cce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/campusvygon.com\/it\/"},{"@type":"ListItem","position":2,"name":"CASE REPORT: L\u2019IMPORTANZA DEL MONITORAGGIO EMODINAMICO AVANZATO E DEI NUOVI PARAMETRI COME L\u2019EFFICIENZA DEL CICLO CARDIACO CCE"}]},{"@type":"WebSite","@id":"https:\/\/campusvygon.com\/it\/#website","url":"https:\/\/campusvygon.com\/it\/","name":"Campus Vygon Italia","description":"Uno spazio dove imparare le procedure e le tecniche sanitarie dalla mano dei migliori professionisti del settore. Creato da e per gli specialisti della sanit\u00e0.","publisher":{"@id":"https:\/\/campusvygon.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campusvygon.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/campusvygon.com\/it\/#organization","name":"Campus Vygon Italia","url":"https:\/\/campusvygon.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/campusvygon.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cvit.b-cdn.net\/wp-content\/uploads\/sites\/3\/2022\/02\/VYGON-ITALIA.jpg","contentUrl":"https:\/\/cvit.b-cdn.net\/wp-content\/uploads\/sites\/3\/2022\/02\/VYGON-ITALIA.jpg","width":703,"height":703,"caption":"Campus Vygon Italia"},"image":{"@id":"https:\/\/campusvygon.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vygon-Italia-102738545680399","https:\/\/www.instagram.com\/campusvygonitalia\/","https:\/\/www.linkedin.com\/company\/vygon-italia-srl","https:\/\/www.youtube.com\/channel\/UCg8IwloH03GkRqQs0mLskHA"]},{"@type":"Person","@id":"https:\/\/campusvygon.com\/it\/#\/schema\/person\/042980c2069c32f5c5fd878123310dc3","name":"Ida Maroni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/10\/idam_avatar-96x96.jpg","url":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/10\/idam_avatar-96x96.jpg","contentUrl":"https:\/\/campusvygon.com\/it\/wp-content\/uploads\/sites\/3\/2023\/10\/idam_avatar-96x96.jpg","caption":"Ida Maroni"},"description":"Sono Product Specialist e mi occupo delle Business Unit \u201cPain and Airway Management\u201d e \u201cCritical Care\u201d all\u2019interno di Vygon, per le quali seguo le regioni del Nord Est dell\u2019Italia. Ho conseguito la mia Laurea Magistrale in Ingegneria Biomedica al Politecnico di Milano e recentemente un Master in \u201cMarket Access - Valutazione delle Tecnologie Sanitarie\u201d dell\u2019Alta Scuola di Economia e Management dei Sistemi Sanitari presso l\u2019Universit\u00e0 Cattolica del Sacro Cuore di Roma. Seguo il percorso dei nostri dispositivi medici dalle prima fasi del loro utilizzo, confrontandomi con i professionisti sanitari e fornendo loro il supporto necessario per svolgere al meglio il loro prezioso lavoro di assistenza al paziente in fasi cos\u00ec delicate del suo percorso.","url":"https:\/\/campusvygon.com\/it\/author\/idam\/"}]}},"_links":{"self":[{"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/posts\/36806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/users\/131"}],"replies":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/comments?post=36806"}],"version-history":[{"count":2,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/posts\/36806\/revisions"}],"predecessor-version":[{"id":36812,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/posts\/36806\/revisions\/36812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/media\/36810"}],"wp:attachment":[{"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/media?parent=36806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/categories?post=36806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campusvygon.com\/it\/wp-json\/wp\/v2\/tags?post=36806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}